{"id":26636,"date":"2022-12-06T14:38:03","date_gmt":"2022-12-06T14:38:03","guid":{"rendered":"https:\/\/zoom.cambridgeschool.com\/cursos-empresas\/"},"modified":"2025-07-19T08:57:07","modified_gmt":"2025-07-19T06:57:07","slug":"cursos-empreses","status":"publish","type":"page","link":"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-empreses\/","title":{"rendered":"Cursos empreses"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_ef109d-6d{margin-bottom:0px;}.kb-row-layout-id26636_ef109d-6d > .kt-row-column-wrap{align-content:end;}:where(.kb-row-layout-id26636_ef109d-6d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:end;}.kb-row-layout-id26636_ef109d-6d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1200px;padding-top:25px;padding-right:30px;padding-bottom:25px;padding-left:30px;min-height:485px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_ef109d-6d{background-image:url('https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-81-1.png');background-size:cover;background-position:62% 40%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id26636_ef109d-6d > .kt-row-layout-overlay{opacity:1;background-color:rgba(255, 255, 255, 0.12);background-image:url('https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Logo-cambridge-school-classes-empresas-1-e1674508025870.png');background-size:auto;background-position:20% 10%;background-attachment:scroll;background-repeat:no-repeat;mix-blend-mode:normal;}@media all and (max-width: 1024px){.kb-row-layout-id26636_ef109d-6d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_ef109d-6d{margin-top:0px;background-image:url('https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-82.png');background-size:cover;background-position:90% 42%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id26636_ef109d-6d > .kt-row-column-wrap{padding-top:0px;min-height:400px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_ef109d-6d > .kt-row-layout-overlay{opacity:1;background-image:url('https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-baner-e1674251633333.png');background-size:auto;background-position:93% 21%;background-attachment:scroll;background-repeat:no-repeat;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_ef109d-6d alignfull kt-row-has-bg video-home wp-block-kadence-rowlayout\" id=\"informacio\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-bottom kb-theme-content-width\">\n<style>.kadence-column26636_b3d96b-6d > .kt-inside-inner-col{display:flex;}.kadence-column26636_b3d96b-6d > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);}.kadence-column26636_b3d96b-6d > .kt-inside-inner-col,.kadence-column26636_b3d96b-6d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_b3d96b-6d > .kt-inside-inner-col{row-gap:var(--global-kb-gap-none, 0rem );column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_b3d96b-6d > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_b3d96b-6d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_b3d96b-6d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_b3d96b-6d{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_b3d96b-6d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_b3d96b-6d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_b3d96b-6d kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_37c8a1-39{margin-bottom:0px;}.kb-row-layout-id26636_37c8a1-39 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id26636_37c8a1-39 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id26636_37c8a1-39 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );max-width:1200px;min-height:67px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id26636_37c8a1-39 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_37c8a1-39 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id26636_37c8a1-39 > .kt-row-column-wrap{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_37c8a1-39 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column26636_d4c51e-64 > .kt-inside-inner-col{display:flex;}.kadence-column26636_d4c51e-64 > .kt-inside-inner-col,.kadence-column26636_d4c51e-64 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_d4c51e-64 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_d4c51e-64 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column26636_d4c51e-64 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column26636_d4c51e-64{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_d4c51e-64{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_d4c51e-64 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column26636_d4c51e-64 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_d4c51e-64{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column26636_d4c51e-64{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_d4c51e-64{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_d4c51e-64 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column26636_d4c51e-64 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column26636_d4c51e-64{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_d4c51e-64{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_d4c51e-64 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column26636_d4c51e-64 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_d4c51e-64 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kadence-column26636_37cf26-cd > .kt-inside-inner-col{display:flex;}.kadence-column26636_37cf26-cd > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column26636_37cf26-cd > .kt-inside-inner-col,.kadence-column26636_37cf26-cd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_37cf26-cd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_37cf26-cd > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column26636_37cf26-cd > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column26636_37cf26-cd{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_37cf26-cd{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_37cf26-cd > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column26636_37cf26-cd > .kt-inside-inner-col{background-color:rgba(0, 60, 90, 0.73);}.kadence-column26636_37cf26-cd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_37cf26-cd{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column26636_37cf26-cd{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_37cf26-cd{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_37cf26-cd > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column26636_37cf26-cd > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column26636_37cf26-cd{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_37cf26-cd{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_37cf26-cd > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column26636_37cf26-cd > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column26636_37cf26-cd, .kt-inside-inner-col > .kadence-column26636_37cf26-cd:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_37cf26-cd kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_042201-72, .wp-block-kadence-advancedheading.kt-adv-heading26636_042201-72[data-kb-block=\"kb-adv-heading26636_042201-72\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;text-align:left;font-size:40px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_042201-72 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_042201-72[data-kb-block=\"kb-adv-heading26636_042201-72\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_042201-72 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_042201-72[data-kb-block=\"kb-adv-heading26636_042201-72\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_042201-72, .wp-block-kadence-advancedheading.kt-adv-heading26636_042201-72[data-kb-block=\"kb-adv-heading26636_042201-72\"]{font-size:26px;}}<\/style>\n<h1 class=\"kt-adv-heading26636_042201-72 wp-block-kadence-advancedheading has-central-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading26636_042201-72\">CURSOS D&#8217;ANGL\u00c8S ONLINE PER A EMPRESES<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_7c8632-84, .wp-block-kadence-advancedheading.kt-adv-heading26636_7c8632-84[data-kb-block=\"kb-adv-heading26636_7c8632-84\"]{margin-bottom:0px;text-align:left;font-size:var(--global-kb-font-size-lg, 2rem);font-weight:600;font-style:normal;font-family:'Open Sans';}.wp-block-kadence-advancedheading.kt-adv-heading26636_7c8632-84 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_7c8632-84[data-kb-block=\"kb-adv-heading26636_7c8632-84\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_7c8632-84 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_7c8632-84[data-kb-block=\"kb-adv-heading26636_7c8632-84\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_7c8632-84, .wp-block-kadence-advancedheading.kt-adv-heading26636_7c8632-84[data-kb-block=\"kb-adv-heading26636_7c8632-84\"]{font-size:var(--global-kb-font-size-md, 1.25rem);}}<\/style>\n<h3 class=\"kt-adv-heading26636_7c8632-84 wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_7c8632-84\">Amb bonificacions p\u00fabliques FUNDAE<\/h3>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column26636_e61df6-f7 > .kt-inside-inner-col{display:flex;}.kadence-column26636_e61df6-f7 > .kt-inside-inner-col,.kadence-column26636_e61df6-f7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_e61df6-f7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_e61df6-f7 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column26636_e61df6-f7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column26636_e61df6-f7{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_e61df6-f7{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_e61df6-f7 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column26636_e61df6-f7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_e61df6-f7{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column26636_e61df6-f7{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_e61df6-f7{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_e61df6-f7 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column26636_e61df6-f7 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column26636_e61df6-f7{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_e61df6-f7{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column26636_e61df6-f7 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column26636_e61df6-f7 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_e61df6-f7\"><div class=\"kt-inside-inner-col\"><style>.kadence-column26636_d25357-c1 > .kt-inside-inner-col{display:flex;}.kadence-column26636_d25357-c1 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column26636_d25357-c1 > .kt-inside-inner-col{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}.kadence-column26636_d25357-c1 > .kt-inside-inner-col,.kadence-column26636_d25357-c1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_d25357-c1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_d25357-c1 > .kt-inside-inner-col{flex-direction:column;align-items:center;}.kadence-column26636_d25357-c1 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column26636_d25357-c1 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column26636_d25357-c1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_d25357-c1 > .kt-inside-inner-col{background-color:rgba(0, 60, 90, 0.72);}.kadence-column26636_d25357-c1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_d25357-c1{text-align:left;}.kadence-column26636_d25357-c1{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_d25357-c1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kadence-column26636_d25357-c1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_d25357-c1 kvs-sm-false\" data-aos=\"fade-up\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_f29895-be, .wp-block-kadence-advancedheading.kt-adv-heading26636_f29895-be[data-kb-block=\"kb-adv-heading26636_f29895-be\"]{font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_f29895-be mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_f29895-be[data-kb-block=\"kb-adv-heading26636_f29895-be\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_f29895-be img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_f29895-be[data-kb-block=\"kb-adv-heading26636_f29895-be\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading26636_f29895-be wp-block-kadence-advancedheading has-central-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading26636_f29895-be\">Sol\u00b7licita m\u00e9s informaci\u00f3<\/div>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f28457-o1\" lang=\"ca\" dir=\"ltr\" data-wpcf7-id=\"28457\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ca\/wp-json\/wp\/v2\/pages\/26636#wpcf7-f28457-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulari de contacte\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"28457\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"ca\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f28457-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:28457,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;repeater_remove_button&quot;:&quot;bottom&quot;,&quot;notice_dismissed_rollback-cf7-5.8.5&quot;:true,&quot;notice_dismissed_rollback-cf7-5.8.6&quot;:true,&quot;notice_dismissed_rollback-cf7-5.8.7&quot;:true}}\" \/>\n<\/fieldset>\n<div class=\"formulari header\">\n\t<div class=\"\">\n\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_source\" \/>\n\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_medium\" \/>\n\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_campaign\" \/>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Nom\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nom i cognoms\" value=\"\" type=\"text\" name=\"Nom\" \/><\/span>\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correu electr\u00f2nic\" value=\"\" type=\"email\" name=\"Email\" \/><\/span>\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e8fon\" value=\"\" type=\"tel\" name=\"Telefon\" \/><\/span>\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Curs\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"Curs\"><option value=\"\">-- Tria una opci\u00f3 --<\/option><option value=\"Adults\">Adults<\/option><option value=\"Joves\">Joves<\/option><option value=\"Empreses\">Empreses<\/option><option value=\"Certificats\">Certificats<\/option><\/select><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Accepta-privacitat\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"Accepta-privacitat\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Accepto la <a class=\"sg-popup-id-24535\" style=\"text-decoration:underline;\">Pol\u00edtica de Privacitat<\/a> de Cambridge School<\/span><\/label><\/span><\/span><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Accepta-comunicacions\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"Accepta-comunicacions\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Accepto rebre comunicacions de Cambridge School<\/span><\/label><\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"sense-marge\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner enviar\" type=\"submit\" value=\"ENVIAR\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_2\" name=\"_wpcf7_ak_js\" value=\"165\"\/><script>\ndocument.getElementById( \"ak_js_2\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_39aa64-4d{margin-bottom:0px;margin-top:-60px;margin-bottom:40px;}.kb-row-layout-id26636_39aa64-4d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_39aa64-4d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_39aa64-4d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_39aa64-4d > .kt-row-layout-overlay{opacity:0.30;}@media all and (min-width: 1025px){.kb-row-layout-id26636_39aa64-4d{display:none !important;}}@media all and (max-width: 1024px){.kb-row-layout-id26636_39aa64-4d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (min-width: 768px) and (max-width: 1024px){.kb-row-layout-id26636_39aa64-4d{display:none !important;}}@media all and (max-width: 767px){.kb-row-layout-id26636_39aa64-4d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_39aa64-4d alignnone kb-v-lg-hidden kb-v-md-hidden wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_12117f-2e > .kt-inside-inner-col{display:flex;}.kadence-column26636_12117f-2e > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column26636_12117f-2e > .kt-inside-inner-col{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}.kadence-column26636_12117f-2e > .kt-inside-inner-col,.kadence-column26636_12117f-2e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_12117f-2e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_12117f-2e > .kt-inside-inner-col{flex-direction:column;align-items:center;}.kadence-column26636_12117f-2e > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column26636_12117f-2e > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column26636_12117f-2e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_12117f-2e > .kt-inside-inner-col{background-color:#003c5a;}.kadence-column26636_12117f-2e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_12117f-2e{text-align:left;}.kadence-column26636_12117f-2e{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_12117f-2e > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kadence-column26636_12117f-2e > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_12117f-2e kvs-lg-false kvs-md-false\" data-aos=\"fade-up\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_0a75fd-12, .wp-block-kadence-advancedheading.kt-adv-heading26636_0a75fd-12[data-kb-block=\"kb-adv-heading26636_0a75fd-12\"]{text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_0a75fd-12 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_0a75fd-12[data-kb-block=\"kb-adv-heading26636_0a75fd-12\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_0a75fd-12 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_0a75fd-12[data-kb-block=\"kb-adv-heading26636_0a75fd-12\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_0a75fd-12, .wp-block-kadence-advancedheading.kt-adv-heading26636_0a75fd-12[data-kb-block=\"kb-adv-heading26636_0a75fd-12\"]{padding-bottom:var(--global-kb-spacing-xs, 1rem);font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<div class=\"kt-adv-heading26636_0a75fd-12 wp-block-kadence-advancedheading has-central-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading26636_0a75fd-12\">Sol\u00b7licita m\u00e9s informaci\u00f3<\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns26636_9fb75a-69{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns26636_9fb75a-69 .kt-button{font-weight:normal;font-style:normal;}.kt-btns26636_9fb75a-69 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns26636_9fb75a-69 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns26636_9fb75a-69 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns26636_9fb75a-69 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns26636_9fb75a-69 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns26636_9fb75a-69 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns26636_9fb75a-69 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns26636_9fb75a-69\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn26636_fa11ba-29.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn26636_fa11ba-29.kb-button{background:#4BAE50;}<\/style><span class=\"kb-button kt-button button kb-btn26636_fa11ba-29 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  joinchat_open wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">WhatsApp<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_019cde-3e{margin-bottom:0px;}.kb-row-layout-id26636_019cde-3e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_019cde-3e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_019cde-3e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:900px;margin-left:auto;margin-right:auto;padding-top:30px;padding-bottom:40px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_019cde-3e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_019cde-3e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_019cde-3e > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_019cde-3e alignnone wp-block-kadence-rowlayout\" id=\"cursos-empreses-1\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_4b421a-9e > .kt-inside-inner-col,.kadence-column26636_4b421a-9e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_4b421a-9e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_4b421a-9e > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_4b421a-9e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_4b421a-9e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_4b421a-9e{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_4b421a-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_4b421a-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_4b421a-9e inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_5a17e2-11, .wp-block-kadence-advancedheading.kt-adv-heading26636_5a17e2-11[data-kb-block=\"kb-adv-heading26636_5a17e2-11\"]{margin-bottom:0px;text-align:center;font-size:42px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_5a17e2-11 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_5a17e2-11[data-kb-block=\"kb-adv-heading26636_5a17e2-11\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_5a17e2-11 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_5a17e2-11[data-kb-block=\"kb-adv-heading26636_5a17e2-11\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_5a17e2-11, .wp-block-kadence-advancedheading.kt-adv-heading26636_5a17e2-11[data-kb-block=\"kb-adv-heading26636_5a17e2-11\"]{font-size:30px;}}<\/style>\n<h2 class=\"kt-adv-heading26636_5a17e2-11 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_5a17e2-11\">Plans d&#8217;angl\u00e8s per videoconfer\u00e8ncia<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_1fd8a6-8b, .wp-block-kadence-advancedheading.kt-adv-heading26636_1fd8a6-8b[data-kb-block=\"kb-adv-heading26636_1fd8a6-8b\"]{margin-bottom:20px;text-align:center;font-size:40px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_1fd8a6-8b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_1fd8a6-8b[data-kb-block=\"kb-adv-heading26636_1fd8a6-8b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_1fd8a6-8b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_1fd8a6-8b[data-kb-block=\"kb-adv-heading26636_1fd8a6-8b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_1fd8a6-8b, .wp-block-kadence-advancedheading.kt-adv-heading26636_1fd8a6-8b[data-kb-block=\"kb-adv-heading26636_1fd8a6-8b\"]{font-size:30px;}}<\/style>\n<h3 class=\"kt-adv-heading26636_1fd8a6-8b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_1fd8a6-8b\">a mida de la teva empresa<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_2fd151-fd, .wp-block-kadence-advancedheading.kt-adv-heading26636_2fd151-fd[data-kb-block=\"kb-adv-heading26636_2fd151-fd\"]{margin-bottom:5px;text-align:center;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_2fd151-fd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_2fd151-fd[data-kb-block=\"kb-adv-heading26636_2fd151-fd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_2fd151-fd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_2fd151-fd[data-kb-block=\"kb-adv-heading26636_2fd151-fd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_2fd151-fd, .wp-block-kadence-advancedheading.kt-adv-heading26636_2fd151-fd[data-kb-block=\"kb-adv-heading26636_2fd151-fd\"]{font-size:24px;}}<\/style>\n<h4 class=\"kt-adv-heading26636_2fd151-fd wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_2fd151-fd\"><strong>Via ZOOM o TEAMS, des de casa o des de l&#8217;oficina.<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_592cd2-2d, .wp-block-kadence-advancedheading.kt-adv-heading26636_592cd2-2d[data-kb-block=\"kb-adv-heading26636_592cd2-2d\"]{text-align:center;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_592cd2-2d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_592cd2-2d[data-kb-block=\"kb-adv-heading26636_592cd2-2d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_592cd2-2d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_592cd2-2d[data-kb-block=\"kb-adv-heading26636_592cd2-2d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_592cd2-2d, .wp-block-kadence-advancedheading.kt-adv-heading26636_592cd2-2d[data-kb-block=\"kb-adv-heading26636_592cd2-2d\"]{font-size:20px;}}<\/style>\n<h4 class=\"kt-adv-heading26636_592cd2-2d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_592cd2-2d\">Planifica la <strong>formaci\u00f3 d&#8217;idiomes online<\/strong> de la teva empresa amb<strong> Cambridge&nbsp;School<\/strong>&nbsp;<strong>In-company<\/strong>. Per a <strong>tota la plantilla<\/strong> o per a <strong>perfils concrets<\/strong>, amb plans adaptats <strong>a tots els nivells<\/strong> i un<strong> pla de seguiment<\/strong> dels progressos que facilita un <strong>alt retorn<\/strong> de la inversi\u00f3.<\/h4>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-26636_62cc6f-d6 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-26636_62cc6f-d6 .kt-divider{border-top-width:1px;height:1px;border-top-color:#212327;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-26636_62cc6f-d6\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_ae47c6-28, .wp-block-kadence-advancedheading.kt-adv-heading26636_ae47c6-28[data-kb-block=\"kb-adv-heading26636_ae47c6-28\"]{margin-bottom:0px;text-align:center;font-size:24px;font-weight:bold;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_ae47c6-28 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_ae47c6-28[data-kb-block=\"kb-adv-heading26636_ae47c6-28\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_ae47c6-28 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_ae47c6-28[data-kb-block=\"kb-adv-heading26636_ae47c6-28\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_ae47c6-28 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_ae47c6-28\">AMB LA PROFESSIONALITAT QUE DESITGES<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_2a7d73-64, .wp-block-kadence-advancedheading.kt-adv-heading26636_2a7d73-64[data-kb-block=\"kb-adv-heading26636_2a7d73-64\"]{margin-bottom:20px;text-align:center;font-size:24px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_2a7d73-64 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_2a7d73-64[data-kb-block=\"kb-adv-heading26636_2a7d73-64\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_2a7d73-64 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_2a7d73-64[data-kb-block=\"kb-adv-heading26636_2a7d73-64\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_2a7d73-64 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_2a7d73-64\">PER ALS TEUS NEGOCIS:<\/h3>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_d361fb-ed{margin-bottom:0px;margin-bottom:30px;}.kb-row-layout-id26636_d361fb-ed > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_d361fb-ed > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_d361fb-ed > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:30px;padding-bottom:25px;}.kb-row-layout-id26636_d361fb-ed > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id26636_d361fb-ed > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id26636_d361fb-ed > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_d361fb-ed > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id26636_d361fb-ed > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (min-width: 768px) and (max-width: 1024px){.kb-row-layout-id26636_d361fb-ed{display:none !important;}}@media all and (max-width: 767px){.kb-row-layout-id26636_d361fb-ed > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id26636_d361fb-ed > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_d361fb-ed{display:none !important;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_d361fb-ed alignfull kb-v-md-hidden kb-v-sm-hidden has-central-palette-6-background-color kt-row-has-bg editorskit-no-mobile wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_cc32b9-67 > .kt-inside-inner-col,.kadence-column26636_cc32b9-67 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_cc32b9-67 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_cc32b9-67 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_cc32b9-67 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_cc32b9-67 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_cc32b9-67{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_cc32b9-67 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_cc32b9-67 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_cc32b9-67 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box26636_14827c-5c .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box26636_14827c-5c .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:30px;}.kt-info-box26636_14827c-5c .kt-blocks-info-box-link-wrap:hover{background:#F2F2F2;}.kt-info-box26636_14827c-5c.wp-block-kadence-infobox{max-width:100%;}.kt-info-box26636_14827c-5c .kadence-info-box-image-inner-intrisic-container{max-width:130px;}.kt-info-box26636_14827c-5c .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:60.4651%;width:172px;height:0px;max-width:100%;}.kt-info-box26636_14827c-5c .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box26636_14827c-5c .kt-info-svg-icon-flip, .kt-info-box26636_14827c-5c .kt-blocks-info-box-number{font-size:50px;}.kt-info-box26636_14827c-5c .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box26636_14827c-5c .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box26636_14827c-5c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box26636_14827c-5c .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:22px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:20px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box26636_14827c-5c .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box26636_14827c-5c .kt-blocks-info-box-text{font-size:15px;}.kt-info-box26636_14827c-5c .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box26636_14827c-5c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box26636_14827c-5c .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box26636_14827c-5c .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box26636_14827c-5c .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box26636_14827c-5c\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-8-2.png\" alt=\"web-zoom-cursos-empresas-8\" width=\"172\" height=\"104\" class=\"kt-info-box-image wp-image-26221\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Professors nadius i internacionals<\/h4><p class=\"kt-blocks-info-box-text\">Titulats i amb doc\u00e8ncia contrastada. Som centre acreditat per la <strong>Universitat de Barcelona<\/strong> i autoritzat per<strong> Cambridge&nbsp;English<\/strong>, amb cursos que segueixen el<strong> MCER<\/strong>.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column26636_24d16f-e4 > .kt-inside-inner-col,.kadence-column26636_24d16f-e4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_24d16f-e4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_24d16f-e4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_24d16f-e4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_24d16f-e4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_24d16f-e4{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_24d16f-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_24d16f-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_24d16f-e4 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box26636_b7bb48-c2 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box26636_b7bb48-c2 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:20px;}.kt-info-box26636_b7bb48-c2 .kt-blocks-info-box-link-wrap:hover{background:#f2f2f2;}.kt-info-box26636_b7bb48-c2.wp-block-kadence-infobox{max-width:100%;}.kt-info-box26636_b7bb48-c2 .kadence-info-box-image-inner-intrisic-container{max-width:105px;}.kt-info-box26636_b7bb48-c2 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:136px;height:0px;max-width:100%;}.kt-info-box26636_b7bb48-c2 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box26636_b7bb48-c2 .kt-info-svg-icon-flip, .kt-info-box26636_b7bb48-c2 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box26636_b7bb48-c2 .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:0px;}.kt-info-box26636_b7bb48-c2 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box26636_b7bb48-c2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box26636_b7bb48-c2 .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:22px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:20px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box26636_b7bb48-c2 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box26636_b7bb48-c2 .kt-blocks-info-box-text{font-size:15px;}.kt-info-box26636_b7bb48-c2 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box26636_b7bb48-c2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box26636_b7bb48-c2 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box26636_b7bb48-c2 .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box26636_b7bb48-c2 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box26636_b7bb48-c2\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-9.png\" alt=\"web-zoom-cursos-empresas-9\" width=\"136\" height=\"136\" class=\"kt-info-box-image wp-image-26218\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">\u00c0mplia experi\u00e8ncia amb empreses<\/h4><p class=\"kt-blocks-info-box-text\"><strong>40 anys formant<\/strong> a empleats i professionals amb cursos d&#8217;angl\u00e8s presencials. I des de 2010 <strong>tamb\u00e9 en cursos online<\/strong> din\u00e0mics i pr\u00e0ctics, amb enfocament en <strong>Business Skills<\/strong>.<br><\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column26636_6c3cbe-c7 > .kt-inside-inner-col,.kadence-column26636_6c3cbe-c7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_6c3cbe-c7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_6c3cbe-c7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_6c3cbe-c7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_6c3cbe-c7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_6c3cbe-c7{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_6c3cbe-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_6c3cbe-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_6c3cbe-c7 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box26636_1ee5a8-e2 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box26636_1ee5a8-e2 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:30px;}.kt-info-box26636_1ee5a8-e2 .kt-blocks-info-box-link-wrap:hover{background:#f2f2f2;}.kt-info-box26636_1ee5a8-e2.wp-block-kadence-infobox{max-width:100%;}.kt-info-box26636_1ee5a8-e2 .kadence-info-box-image-inner-intrisic-container{max-width:105px;}.kt-info-box26636_1ee5a8-e2 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:400px;height:0px;max-width:100%;}.kt-info-box26636_1ee5a8-e2 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box26636_1ee5a8-e2 .kt-info-svg-icon-flip, .kt-info-box26636_1ee5a8-e2 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box26636_1ee5a8-e2 .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:0px;}.kt-info-box26636_1ee5a8-e2 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box26636_1ee5a8-e2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box26636_1ee5a8-e2 .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:22px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:20px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box26636_1ee5a8-e2 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box26636_1ee5a8-e2 .kt-blocks-info-box-text{font-size:15px;}.kt-info-box26636_1ee5a8-e2 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box26636_1ee5a8-e2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box26636_1ee5a8-e2 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box26636_1ee5a8-e2 .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box26636_1ee5a8-e2 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box26636_1ee5a8-e2\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12.png\" alt=\"Cursos-ingles-online- Cambridge-school-icona12\" width=\"400\" height=\"400\" class=\"kt-info-box-image wp-image-43\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12-300x300.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12-150x150.png 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Pla de seguiment dels alumnes<\/h4><p class=\"kt-blocks-info-box-text\">Amb <strong>informes trimestrals<\/strong>, q\u00fcestionaris de satisfacci\u00f3, observaci\u00f3 de classes, control d&#8217;assist\u00e8ncia\u2026 Per arribar als teus objectius d&#8217;angl\u00e8s<strong> en el temps \u00f2ptim<\/strong>.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_110729-60{margin-bottom:0px;margin-bottom:0px;}.kb-row-layout-id26636_110729-60 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_110729-60 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_110729-60 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1200px;margin-left:auto;margin-right:auto;padding-top:50px;padding-bottom:50px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_110729-60 > .kt-row-layout-overlay{opacity:0.30;}@media all and (min-width: 1025px){.kb-row-layout-id26636_110729-60{display:none !important;}}@media all and (max-width: 1024px){.kb-row-layout-id26636_110729-60 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_110729-60{margin-bottom:0px;}.kb-row-layout-id26636_110729-60 > .kt-row-column-wrap{padding-right:15px;padding-left:15px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_110729-60 alignnone kb-v-lg-hidden has-central-palette-6-background-color kt-row-has-bg editorskit-no-desktop editorskit-no-tablet wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_f80d1e-26 > .kt-inside-inner-col,.kadence-column26636_f80d1e-26 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_f80d1e-26 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_f80d1e-26 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_f80d1e-26 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_f80d1e-26 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_f80d1e-26{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_f80d1e-26 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_f80d1e-26 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_f80d1e-26 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box26636_8ad9f0-98 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box26636_8ad9f0-98 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:30px;}.kt-info-box26636_8ad9f0-98 .kt-blocks-info-box-link-wrap:hover{background:#F2F2F2;}.kt-info-box26636_8ad9f0-98.wp-block-kadence-infobox{max-width:100%;}.kt-info-box26636_8ad9f0-98 .kadence-info-box-image-inner-intrisic-container{max-width:70px;}.kt-info-box26636_8ad9f0-98 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:400px;height:0px;max-width:100%;}.kt-info-box26636_8ad9f0-98 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box26636_8ad9f0-98 .kt-info-svg-icon-flip, .kt-info-box26636_8ad9f0-98 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box26636_8ad9f0-98 .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box26636_8ad9f0-98 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box26636_8ad9f0-98 .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:23px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box26636_8ad9f0-98 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box26636_8ad9f0-98 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box26636_8ad9f0-98 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box26636_8ad9f0-98 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box26636_8ad9f0-98 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box26636_8ad9f0-98 .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box26636_8ad9f0-98 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box26636_8ad9f0-98\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet.png\" alt=\"vimet\" width=\"400\" height=\"400\" class=\"kt-info-box-image wp-image-139\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-300x300.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-150x150.png 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Professors nadius i internacionals<\/h4><p class=\"kt-blocks-info-box-text\">Titulats i amb doc\u00e8ncia contrastada. Som centre acreditat per la<strong> Universitat de Barcelona<\/strong> i autoritzat per <strong>Cambridge&nbsp;English<\/strong>, amb cursos que segueixen el <strong>MCER<\/strong>.<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box26636_a46c93-ca .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box26636_a46c93-ca .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:30px;}.kt-info-box26636_a46c93-ca .kt-blocks-info-box-link-wrap:hover{background:#f2f2f2;}.kt-info-box26636_a46c93-ca.wp-block-kadence-infobox{max-width:100%;}.kt-info-box26636_a46c93-ca .kadence-info-box-image-inner-intrisic-container{max-width:70px;}.kt-info-box26636_a46c93-ca .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:136px;height:0px;max-width:100%;}.kt-info-box26636_a46c93-ca .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box26636_a46c93-ca .kt-info-svg-icon-flip, .kt-info-box26636_a46c93-ca .kt-blocks-info-box-number{font-size:50px;}.kt-info-box26636_a46c93-ca .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box26636_a46c93-ca .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box26636_a46c93-ca .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:23px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box26636_a46c93-ca .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box26636_a46c93-ca .kt-blocks-info-box-text{font-size:16px;}.kt-info-box26636_a46c93-ca .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box26636_a46c93-ca .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box26636_a46c93-ca .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box26636_a46c93-ca .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box26636_a46c93-ca .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box26636_a46c93-ca\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-9.png\" alt=\"web-zoom-cursos-empresas-9\" width=\"136\" height=\"136\" class=\"kt-info-box-image wp-image-26218\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">\u00c0mplia experi\u00e8ncia amb empreses<\/h4><p class=\"kt-blocks-info-box-text\"><strong>40 anys formant<\/strong> a empleats i professionals amb cursos d&#8217;angl\u00e8s presencials. I des de 2010 <strong>tamb\u00e9 en cursos online<\/strong> din\u00e0mics i pr\u00e0ctics, amb enfocament en <strong>Business Skills<\/strong>.<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box26636_39e8bf-46 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box26636_39e8bf-46 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:30px;}.kt-info-box26636_39e8bf-46 .kt-blocks-info-box-link-wrap:hover{background:#f2f2f2;}.kt-info-box26636_39e8bf-46.wp-block-kadence-infobox{max-width:100%;}.kt-info-box26636_39e8bf-46 .kadence-info-box-image-inner-intrisic-container{max-width:70px;}.kt-info-box26636_39e8bf-46 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:400px;height:0px;max-width:100%;}.kt-info-box26636_39e8bf-46 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box26636_39e8bf-46 .kt-info-svg-icon-flip, .kt-info-box26636_39e8bf-46 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box26636_39e8bf-46 .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box26636_39e8bf-46 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box26636_39e8bf-46 .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:23px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box26636_39e8bf-46 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box26636_39e8bf-46 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box26636_39e8bf-46 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box26636_39e8bf-46 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box26636_39e8bf-46 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box26636_39e8bf-46 .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box26636_39e8bf-46 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box26636_39e8bf-46\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12.png\" alt=\"Cursos-ingles-online- Cambridge-school-icona12\" width=\"400\" height=\"400\" class=\"kt-info-box-image wp-image-43\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12-300x300.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12-150x150.png 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Pla de seguiment dels alumnes<\/h4><p class=\"kt-blocks-info-box-text\">Amb<strong> informes trimestrals<\/strong>, q\u00fcestionaris de satisfacci\u00f3, observaci\u00f3 de classes, control d&#8217;assist\u00e8ncia\u2026 Per arribar als teus objectius d&#8217;angl\u00e8s <strong>en el temps \u00f2ptim<\/strong>.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_d4ade3-4a{margin-bottom:0px;margin-top:20px;margin-bottom:0px;}.kb-row-layout-id26636_d4ade3-4a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_d4ade3-4a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_d4ade3-4a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_d4ade3-4a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_d4ade3-4a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_d4ade3-4a > .kt-row-column-wrap{padding-right:15px;padding-left:15px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_d4ade3-4a alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_9fa517-dc > .kt-inside-inner-col,.kadence-column26636_9fa517-dc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_9fa517-dc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_9fa517-dc > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_9fa517-dc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_9fa517-dc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_9fa517-dc{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_9fa517-dc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_9fa517-dc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_9fa517-dc inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_40600d-3e, .wp-block-kadence-advancedheading.kt-adv-heading26636_40600d-3e[data-kb-block=\"kb-adv-heading26636_40600d-3e\"]{padding-bottom:0px;margin-bottom:0px;text-align:center;font-style:normal;letter-spacing:-0.5px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_40600d-3e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_40600d-3e[data-kb-block=\"kb-adv-heading26636_40600d-3e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_40600d-3e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_40600d-3e[data-kb-block=\"kb-adv-heading26636_40600d-3e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_40600d-3e, .wp-block-kadence-advancedheading.kt-adv-heading26636_40600d-3e[data-kb-block=\"kb-adv-heading26636_40600d-3e\"]{font-size:24px;}}<\/style>\n<h3 class=\"kt-adv-heading26636_40600d-3e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_40600d-3e\"><strong>Per a empreses i professionals<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_5296e1-94, .wp-block-kadence-advancedheading.kt-adv-heading26636_5296e1-94[data-kb-block=\"kb-adv-heading26636_5296e1-94\"]{text-align:center;font-weight:400;font-style:normal;letter-spacing:-0.4px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_5296e1-94 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_5296e1-94[data-kb-block=\"kb-adv-heading26636_5296e1-94\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_5296e1-94 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_5296e1-94[data-kb-block=\"kb-adv-heading26636_5296e1-94\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_5296e1-94, .wp-block-kadence-advancedheading.kt-adv-heading26636_5296e1-94[data-kb-block=\"kb-adv-heading26636_5296e1-94\"]{font-size:24px;}}<\/style>\n<h3 class=\"kt-adv-heading26636_5296e1-94 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_5296e1-94\">de tota Espanya i en tots els sectors<\/h3>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_99a3dc-99{margin-bottom:0px;margin-top:70px;margin-bottom:70px;}.kb-row-layout-id26636_99a3dc-99 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id26636_99a3dc-99 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id26636_99a3dc-99 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1300px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(55% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(45% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id26636_99a3dc-99 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id26636_99a3dc-99 .kt-row-layout-bottom-sep{height:98px;}.kb-row-layout-id26636_99a3dc-99 .kt-row-layout-bottom-sep svg{width:128%;}.kb-row-layout-id26636_99a3dc-99 .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}.kb-row-layout-id26636_99a3dc-99 .kt-row-layout-top-sep{height:202px;}.kb-row-layout-id26636_99a3dc-99 .kt-row-layout-top-sep svg{width:100%;}.kb-row-layout-id26636_99a3dc-99 .kt-row-layout-top-sep svg{fill:#FFFFFF!important;}@media all and (max-width: 1024px){.kb-row-layout-id26636_99a3dc-99 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id26636_99a3dc-99 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id26636_99a3dc-99 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id26636_99a3dc-99 > .kt-row-column-wrap{padding-top:30px;padding-right:20px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_99a3dc-99 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id26636_99a3dc-99 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_99a3dc-99 alignnone has-central-palette-2-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column26636_1c4804-69 > .kt-inside-inner-col,.kadence-column26636_1c4804-69 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_1c4804-69 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_1c4804-69 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_1c4804-69 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_1c4804-69 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_1c4804-69{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_1c4804-69 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_1c4804-69 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_1c4804-69 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image26636_f960cf-d9:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:-50px;margin-bottom:-50px;}.kb-image26636_f960cf-d9 .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 767px){.wp-block-kadence-image.kb-image26636_f960cf-d9:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:0px;margin-bottom:0px;}}<\/style>\n<figure class=\"wp-block-kadence-image kb-image26636_f960cf-d9 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"718\" height=\"466\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-12.png\" alt=\"web-zoom-cursos-empresas-12\" class=\"kb-img wp-image-26227\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-12.png 718w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-12-300x195.png 300w\" sizes=\"auto, (max-width: 718px) 100vw, 718px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column26636_95cb53-c2 > .kt-inside-inner-col,.kadence-column26636_95cb53-c2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_95cb53-c2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_95cb53-c2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_95cb53-c2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_95cb53-c2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_95cb53-c2{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_95cb53-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_95cb53-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_95cb53-c2 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_60d83d-bb, .wp-block-kadence-advancedheading.kt-adv-heading26636_60d83d-bb[data-kb-block=\"kb-adv-heading26636_60d83d-bb\"]{margin-bottom:0px;font-size:22px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_60d83d-bb mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_60d83d-bb[data-kb-block=\"kb-adv-heading26636_60d83d-bb\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_60d83d-bb img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_60d83d-bb[data-kb-block=\"kb-adv-heading26636_60d83d-bb\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_60d83d-bb wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_60d83d-bb\"><strong>ANGL\u00c8S PER A EMPRESES<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_94f8db-68, .wp-block-kadence-advancedheading.kt-adv-heading26636_94f8db-68[data-kb-block=\"kb-adv-heading26636_94f8db-68\"]{font-size:24px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_94f8db-68 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_94f8db-68[data-kb-block=\"kb-adv-heading26636_94f8db-68\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_94f8db-68 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_94f8db-68[data-kb-block=\"kb-adv-heading26636_94f8db-68\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_94f8db-68 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_94f8db-68\">I PROFESSIONALS DE:<\/h3>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_76fad6-89:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_76fad6-89 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_76fad6-89 ul.kt-svg-icon-list{grid-row-gap:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_76fad6-89 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items26636_76fad6-89 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items26636_76fad6-89 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:#FFFFFF;font-size:17px;color:#FFFFFF;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items26636_76fad6-89 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-26636_f1ea26-88 .kt-svg-icon-list-single{font-size:20px !important;color:#F0504B !important;}.kt-svg-icon-list-item-26636_f1ea26-88 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_f1ea26-88 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Arts gr\u00e0fiques i audiovisuals<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_045ef8-5d .kt-svg-icon-list-single{font-size:20px !important;color:#F0504B !important;}.kt-svg-icon-list-item-26636_045ef8-5d .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_045ef8-5d kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Educaci\u00f3 prim\u00e0ria i secund\u00e0ria<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_9e9724-c9 .kt-svg-icon-list-single{font-size:20px !important;color:#F0504B !important;}.kt-svg-icon-list-item-26636_9e9724-c9 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_9e9724-c9 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">M\u00e0rqueting i comunicaci\u00f3<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_e80366-50 .kt-svg-icon-list-single{font-size:20px !important;color:#F0504B !important;}.kt-svg-icon-list-item-26636_e80366-50 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_e80366-50 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Restauraci\u00f3 i hostaleria<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_a08afc-55 .kt-svg-icon-list-single{font-size:20px !important;color:#F0504B !important;}.kt-svg-icon-list-item-26636_a08afc-55 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_a08afc-55 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Hospitals i medicina<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_c1729c-ca .kt-svg-icon-list-single{font-size:20px !important;color:#F0504B !important;}.kt-svg-icon-list-item-26636_c1729c-ca .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_c1729c-ca kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Farmac\u00e8utiques<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_930f61-3b .kt-svg-icon-list-single{font-size:20px !important;color:#F0504B !important;}.kt-svg-icon-list-item-26636_930f61-3b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_930f61-3b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Qu\u00edmiques<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_b0b06b-87 .kt-svg-icon-list-single{font-size:20px !important;color:#F0504B !important;}.kt-svg-icon-list-item-26636_b0b06b-87 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_b0b06b-87 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Exportaci\u00f3 i importaci\u00f3<br>Ind\u00fastria<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_556c53-2e .kt-svg-icon-list-single{font-size:20px !important;color:#F0504B !important;}.kt-svg-icon-list-item-26636_556c53-2e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_556c53-2e kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Comer\u00e7os i negocis retail\u2026i molts sectors m\u00e9s<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_2b92f0-ba{margin-bottom:0px;margin-top:20px;margin-bottom:0px;}.kb-row-layout-id26636_2b92f0-ba > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_2b92f0-ba > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_2b92f0-ba > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:15px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_2b92f0-ba > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_2b92f0-ba > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_2b92f0-ba{margin-top:0px;}.kb-row-layout-id26636_2b92f0-ba > .kt-row-column-wrap{padding-top:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_2b92f0-ba alignnone wp-block-kadence-rowlayout\" id=\"cursos-empreses-2\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_15bfd9-2d > .kt-inside-inner-col,.kadence-column26636_15bfd9-2d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_15bfd9-2d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_15bfd9-2d > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_15bfd9-2d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_15bfd9-2d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_15bfd9-2d{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_15bfd9-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_15bfd9-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_15bfd9-2d inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_68bcf4-73, .wp-block-kadence-advancedheading.kt-adv-heading26636_68bcf4-73[data-kb-block=\"kb-adv-heading26636_68bcf4-73\"]{padding-bottom:0px;margin-bottom:0px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_68bcf4-73 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_68bcf4-73[data-kb-block=\"kb-adv-heading26636_68bcf4-73\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_68bcf4-73 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_68bcf4-73[data-kb-block=\"kb-adv-heading26636_68bcf4-73\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_68bcf4-73 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_68bcf4-73\"><strong>Quin curs t&#8217;interessa?<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_6e9e89-52, .wp-block-kadence-advancedheading.kt-adv-heading26636_6e9e89-52[data-kb-block=\"kb-adv-heading26636_6e9e89-52\"]{text-align:center;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_6e9e89-52 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_6e9e89-52[data-kb-block=\"kb-adv-heading26636_6e9e89-52\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_6e9e89-52 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_6e9e89-52[data-kb-block=\"kb-adv-heading26636_6e9e89-52\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_6e9e89-52 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_6e9e89-52\">\u00c0mplia varietat de nivells i formats:<\/h3>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_b098cd-e8{margin-bottom:0px;margin-top:0px;}.kb-row-layout-id26636_b098cd-e8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_b098cd-e8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_b098cd-e8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:26px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_b098cd-e8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_b098cd-e8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_b098cd-e8 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_b098cd-e8 alignnone wp-block-kadence-rowlayout\" id=\"jovenes-anual\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_24c097-b6 > .kt-inside-inner-col,.kadence-column26636_24c097-b6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_24c097-b6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_24c097-b6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_24c097-b6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_24c097-b6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_24c097-b6{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_24c097-b6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_24c097-b6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_24c097-b6 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box26636_0f14bc-92 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box26636_0f14bc-92 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#003C5A;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}.kt-info-box26636_0f14bc-92 .kt-blocks-info-box-link-wrap:hover{background:#003C5A;}.kt-info-box26636_0f14bc-92.wp-block-kadence-infobox{max-width:100%;}.kt-info-box26636_0f14bc-92 .kadence-info-box-image-inner-intrisic-container{max-width:75px;}.kt-info-box26636_0f14bc-92 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:68%;width:400px;height:0px;max-width:100%;}.kt-info-box26636_0f14bc-92 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box26636_0f14bc-92 .kt-info-svg-icon-flip, .kt-info-box26636_0f14bc-92 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box26636_0f14bc-92 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box26636_0f14bc-92 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box26636_0f14bc-92 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:#FFFFFF;font-size:32px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box26636_0f14bc-92 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:#FFFFFF;}.kt-info-box26636_0f14bc-92 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box26636_0f14bc-92 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box26636_0f14bc-92 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box26636_0f14bc-92 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box26636_0f14bc-92 .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:20px;}.kt-info-box26636_0f14bc-92 .kt-blocks-info-box-link-wrap{display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box26636_0f14bc-92 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box26636_0f14bc-92\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png\" alt=\"vimet-blanc\" width=\"400\" height=\"272\" class=\"kt-info-box-image wp-image-85\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc-300x204.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">Cursos en grups IN-COMPANY<\/h2><\/div><\/span><\/div>\n\n\n<style>.kt-accordion-id26636_c7820b-a5 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:1px;}.kt-accordion-id26636_c7820b-a5 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#F2F2F2;padding-top:0px;padding-right:30px;padding-bottom:30px;padding-left:50px;}.kt-accordion-id26636_c7820b-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;font-size:18px;line-height:24px;color:#212327;padding-top:30px;padding-right:30px;padding-bottom:50px;padding-left:70px;}.kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#212327;}.kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#212327;}.kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id26636_c7820b-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id26636_c7820b-a5 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id26636_c7820b-a5 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id26636_c7820b-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#212327;background:#F2F2F2;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#212327;}.kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#212327;}.kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_c7820b-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#F2F2F2;}@media all and (max-width: 1024px){.kt-accordion-id26636_c7820b-a5 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id26636_c7820b-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id26636_c7820b-a5 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id26636_c7820b-a5 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id26636_c7820b-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id26636_c7820b-a5 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id26636_c7820b-a5 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:1px;}.kt-accordion-id26636_c7820b-a5 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id26636_c7820b-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{padding-right:10px;padding-left:15px;}.kt-accordion-id26636_c7820b-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id26636_c7820b-a5 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id26636_c7820b-a5 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id26636_c7820b-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone acordio\"><div class=\"kt-accordion-wrap kt-accordion-id26636_c7820b-a5 kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrowcircle kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane26636_106712-23 obrir\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-2-color\">Impartits EN EXCLUSIVA PER A LA TEVA EMPRESA.<br><\/mark><\/strong>En l&#8217;<strong>horari<\/strong>, <strong>dates<\/strong> i<strong> plataforma (Teams&nbsp;o Zoom)<\/strong> que especifiqueu vosaltres.<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-spacer.kt-block-spacer-26636_e6a2fb-ab .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-26636_e6a2fb-ab .kt-divider{border-top-width:1px;height:1px;border-top-color:#212327;width:100%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-26636_e6a2fb-ab\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_ac3e72-56{margin-bottom:0px;}.kb-row-layout-id26636_ac3e72-56 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_ac3e72-56 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_ac3e72-56 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}.kb-row-layout-id26636_ac3e72-56 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_ac3e72-56 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_ac3e72-56 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_ac3e72-56 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_497db9-7d > .kt-inside-inner-col,.kadence-column26636_497db9-7d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_497db9-7d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_497db9-7d > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_497db9-7d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_497db9-7d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_497db9-7d{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_497db9-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_497db9-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_497db9-7d inner-column-1\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"209\" height=\"229\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-8-3.png\" alt=\"\" class=\"wp-image-26258\"\/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column26636_030635-43 > .kt-inside-inner-col,.kadence-column26636_030635-43 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_030635-43 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_030635-43 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_030635-43 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_030635-43 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_030635-43{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_030635-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_030635-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_030635-43 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_2db68a-d5, .wp-block-kadence-advancedheading.kt-adv-heading26636_2db68a-d5[data-kb-block=\"kb-adv-heading26636_2db68a-d5\"]{margin-bottom:0px;font-size:20px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_2db68a-d5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_2db68a-d5[data-kb-block=\"kb-adv-heading26636_2db68a-d5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_2db68a-d5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_2db68a-d5[data-kb-block=\"kb-adv-heading26636_2db68a-d5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_2db68a-d5 wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_2db68a-d5\"><strong>INDICAT PER A:<\/strong><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_ba467c-0f, .wp-block-kadence-advancedheading.kt-adv-heading26636_ba467c-0f[data-kb-block=\"kb-adv-heading26636_ba467c-0f\"]{font-size:17px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_ba467c-0f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_ba467c-0f[data-kb-block=\"kb-adv-heading26636_ba467c-0f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_ba467c-0f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_ba467c-0f[data-kb-block=\"kb-adv-heading26636_ba467c-0f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_ba467c-0f wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_ba467c-0f\"><strong>Grups d&#8217;empresa amb un nivell homogeni<\/strong> de coneixements.<br>L&#8217;empresa tria el temps, l&#8217;horari (laboral o no-laboral) i el nombre d&#8217;alumnes, i nosaltres adaptem el temari a les necessitats espec\u00edfiques d&#8217;aquest grup\/s. Aix\u00f2 permet <strong>gran flexibilitat<\/strong>, ja que els cursos s&#8217;adapten en exclusiva a la teva plantilla<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_8a5133-e8, .wp-block-kadence-advancedheading.kt-adv-heading26636_8a5133-e8[data-kb-block=\"kb-adv-heading26636_8a5133-e8\"]{margin-bottom:0px;font-size:20px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_8a5133-e8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_8a5133-e8[data-kb-block=\"kb-adv-heading26636_8a5133-e8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_8a5133-e8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_8a5133-e8[data-kb-block=\"kb-adv-heading26636_8a5133-e8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_8a5133-e8 wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_8a5133-e8\"><strong>CURSOS OFERTS:<\/strong><\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_af0f2d-63:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_af0f2d-63 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_af0f2d-63 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_af0f2d-63 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items26636_af0f2d-63 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items26636_af0f2d-63 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:17px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items26636_af0f2d-63 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-26636_2a2e12-a3 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-26636_2a2e12-a3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_2a2e12-a3 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_minus kt-svg-icon-list-single\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>De BUSINESS ENGLISH<\/strong> (A1, A2, B1, B2, C1 i C2), amb la possibilitat de centrar part del curs a refor\u00e7ar el contingut rellevant per al sector de la teva empresa.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_ce700c-2a .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-26636_ce700c-2a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_ce700c-2a kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_minus kt-svg-icon-list-single\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>De PREPARACI\u00d3 d&#8217;Ex\u00e0mens Oficials<\/strong> per a tots els nivells. Per a poder presentar-se als ex\u00e0mens Cambridge English.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_3c5137-07 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-26636_3c5137-07 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_3c5137-07 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_minus kt-svg-icon-list-single\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>De CONVERSA<\/strong> per a tots els nivells, enfocant-nos en els temes que desitgis.<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_424244-c5, .wp-block-kadence-advancedheading.kt-adv-heading26636_424244-c5[data-kb-block=\"kb-adv-heading26636_424244-c5\"]{margin-bottom:0px;font-size:20px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_424244-c5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_424244-c5[data-kb-block=\"kb-adv-heading26636_424244-c5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_424244-c5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_424244-c5[data-kb-block=\"kb-adv-heading26636_424244-c5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_424244-c5 wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_424244-c5\"><strong>FORMAT\/PLATAFORMA:<\/strong><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_8d5648-1e, .wp-block-kadence-advancedheading.kt-adv-heading26636_8d5648-1e[data-kb-block=\"kb-adv-heading26636_8d5648-1e\"]{font-size:17px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_8d5648-1e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_8d5648-1e[data-kb-block=\"kb-adv-heading26636_8d5648-1e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_8d5648-1e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_8d5648-1e[data-kb-block=\"kb-adv-heading26636_8d5648-1e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_8d5648-1e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_8d5648-1e\">Per videoconfer\u00e8ncia, via<strong> Zoom<\/strong> i <strong>Microsoft Teams<\/strong> (a triar per l&#8217;empresa).<\/p>\n\n\n\n<p style=\"font-size:17px\"><span style=\"text-decoration: underline;\" class=\"ek-underline\"><a href=\"#informacio-empreses\" class=\"ek-link\">M\u00e9s informaci\u00f3?<\/a><\/span><\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_a0277d-32{margin-bottom:0px;margin-top:0px;}.kb-row-layout-id26636_a0277d-32 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_a0277d-32 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_a0277d-32 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_a0277d-32 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_a0277d-32 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_a0277d-32 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_a0277d-32 alignnone wp-block-kadence-rowlayout\" id=\"jovenes-anual\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_ace7a8-55 > .kt-inside-inner-col,.kadence-column26636_ace7a8-55 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_ace7a8-55 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_ace7a8-55 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_ace7a8-55 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_ace7a8-55 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_ace7a8-55{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_ace7a8-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_ace7a8-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_ace7a8-55 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box26636_557890-0b .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box26636_557890-0b .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#003C5A;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}.kt-info-box26636_557890-0b .kt-blocks-info-box-link-wrap:hover{background:#003C5A;}.kt-info-box26636_557890-0b.wp-block-kadence-infobox{max-width:100%;}.kt-info-box26636_557890-0b .kadence-info-box-image-inner-intrisic-container{max-width:75px;}.kt-info-box26636_557890-0b .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:68%;width:400px;height:0px;max-width:100%;}.kt-info-box26636_557890-0b .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box26636_557890-0b .kt-info-svg-icon-flip, .kt-info-box26636_557890-0b .kt-blocks-info-box-number{font-size:50px;}.kt-info-box26636_557890-0b .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box26636_557890-0b .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box26636_557890-0b .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:#FFFFFF;font-size:32px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box26636_557890-0b .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:#FFFFFF;}.kt-info-box26636_557890-0b .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box26636_557890-0b .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box26636_557890-0b .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box26636_557890-0b .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box26636_557890-0b .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:20px;}.kt-info-box26636_557890-0b .kt-blocks-info-box-link-wrap{display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box26636_557890-0b .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box26636_557890-0b\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png\" alt=\"vimet-blanc\" width=\"400\" height=\"272\" class=\"kt-info-box-image wp-image-85\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc-300x204.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">Cursos en grups CAMBRIDGE SCHOOL<\/h2><\/div><\/span><\/div>\n\n\n<style>.kt-accordion-id26636_d99755-62 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:1px;}.kt-accordion-id26636_d99755-62 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#F2F2F2;padding-top:0px;padding-right:30px;padding-bottom:30px;padding-left:50px;}.kt-accordion-id26636_d99755-62 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;font-size:18px;line-height:24px;color:#555555;padding-top:30px;padding-right:30px;padding-bottom:50px;padding-left:70px;}.kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id26636_d99755-62 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id26636_d99755-62 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id26636_d99755-62 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id26636_d99755-62 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#212327;background:#F2F2F2;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#212327;}.kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#212327;}.kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_d99755-62:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#F2F2F2;}@media all and (max-width: 1024px){.kt-accordion-id26636_d99755-62 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id26636_d99755-62 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id26636_d99755-62 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id26636_d99755-62 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id26636_d99755-62 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id26636_d99755-62 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id26636_d99755-62 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id26636_d99755-62 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:1px;}.kt-accordion-id26636_d99755-62 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id26636_d99755-62 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;padding-right:10px;padding-left:15px;}.kt-accordion-id26636_d99755-62 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id26636_d99755-62 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id26636_d99755-62 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id26636_d99755-62 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone acordio\"><div class=\"kt-accordion-wrap kt-accordion-id26636_d99755-62 kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrowcircle kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane26636_b3aaea-d1 obrir\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><span style=\"color: #00B8D6;\" class=\"ugb-highlight\"><strong>Els teus empleats estudien al costat d&#8217;altres alumnes Cambridge School.<\/strong><\/span><br><strong>Des de casa o des de l&#8217;oficina<\/strong>, en grups del seu <strong>mateix nivell<\/strong>.<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-spacer.kt-block-spacer-26636_5e111d-c5 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-26636_5e111d-c5 .kt-divider{border-top-width:1px;height:1px;border-top-color:#212327;width:100%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-26636_5e111d-c5\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_83b361-5c{margin-bottom:0px;}.kb-row-layout-id26636_83b361-5c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_83b361-5c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_83b361-5c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}.kb-row-layout-id26636_83b361-5c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_83b361-5c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_83b361-5c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_83b361-5c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_08a050-4d > .kt-inside-inner-col,.kadence-column26636_08a050-4d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_08a050-4d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_08a050-4d > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_08a050-4d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_08a050-4d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_08a050-4d{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_08a050-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_08a050-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_08a050-4d inner-column-1\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"216\" height=\"229\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-12-1.png\" alt=\"web-zoom-cursos-empresas-12\" class=\"wp-image-26277\"\/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column26636_552e60-6e > .kt-inside-inner-col,.kadence-column26636_552e60-6e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_552e60-6e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_552e60-6e > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_552e60-6e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_552e60-6e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_552e60-6e{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_552e60-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_552e60-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_552e60-6e inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_fc9374-62, .wp-block-kadence-advancedheading.kt-adv-heading26636_fc9374-62[data-kb-block=\"kb-adv-heading26636_fc9374-62\"]{margin-bottom:0px;font-size:20px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_fc9374-62 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_fc9374-62[data-kb-block=\"kb-adv-heading26636_fc9374-62\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_fc9374-62 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_fc9374-62[data-kb-block=\"kb-adv-heading26636_fc9374-62\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_fc9374-62 wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_fc9374-62\"><strong>INDICAT PER A:<\/strong><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_efb26f-d7, .wp-block-kadence-advancedheading.kt-adv-heading26636_efb26f-d7[data-kb-block=\"kb-adv-heading26636_efb26f-d7\"]{font-size:17px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_efb26f-d7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_efb26f-d7[data-kb-block=\"kb-adv-heading26636_efb26f-d7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_efb26f-d7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_efb26f-d7[data-kb-block=\"kb-adv-heading26636_efb26f-d7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_efb26f-d7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_efb26f-d7\"><strong>Empreses amb grups d&#8217;empleats de nivells diversos<\/strong>.<br>Aquests cursos s\u00f3n impartits per videoconfer\u00e8ncia <strong>via Zoom<\/strong>, i els empleats de la teva empresa treballen les lli\u00e7ons i comparteixen classe <strong>amb alumnes Cambridge&nbsp;School&nbsp;del seu mateix nivell<\/strong>.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_7d23c7-9c, .wp-block-kadence-advancedheading.kt-adv-heading26636_7d23c7-9c[data-kb-block=\"kb-adv-heading26636_7d23c7-9c\"]{font-size:17px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_7d23c7-9c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_7d23c7-9c[data-kb-block=\"kb-adv-heading26636_7d23c7-9c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_7d23c7-9c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_7d23c7-9c[data-kb-block=\"kb-adv-heading26636_7d23c7-9c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_7d23c7-9c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_7d23c7-9c\">Aquesta \u00e9s una <strong>opci\u00f3 \u00f2ptima<\/strong> per a oferir formaci\u00f3 a trav\u00e9s de l&#8217;empresa fins i tot <strong>quan els grups d&#8217;empleats s\u00f3n molt redu\u00efts<\/strong> i tenen <strong>nivells d&#8217;angl\u00e8s molt diferents<\/strong>.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_fc2294-2d, .wp-block-kadence-advancedheading.kt-adv-heading26636_fc2294-2d[data-kb-block=\"kb-adv-heading26636_fc2294-2d\"]{margin-bottom:0px;font-size:20px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_fc2294-2d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_fc2294-2d[data-kb-block=\"kb-adv-heading26636_fc2294-2d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_fc2294-2d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_fc2294-2d[data-kb-block=\"kb-adv-heading26636_fc2294-2d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_fc2294-2d wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_fc2294-2d\"><strong>CURSOS OFERTS:<\/strong><\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_e76aa0-42:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_e76aa0-42 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_e76aa0-42 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_e76aa0-42 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items26636_e76aa0-42 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items26636_e76aa0-42 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:17px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items26636_e76aa0-42 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-26636_9fb492-59 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-26636_9fb492-59 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_9fb492-59 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_minus kt-svg-icon-list-single\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>D&#8217;UN NIVELL<\/strong> (A1, A2, B1, B2, C1 i C2) \u2013 De setembre a juny (3 hores a la setmana) o intensius al juliol. Horaris a consultar.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_7c274d-39 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-26636_7c274d-39 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_7c274d-39 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_minus kt-svg-icon-list-single\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>DE T\u00c8CNIQUES D&#8217;EXAMEN <\/strong>per a tots els nivells. Per a poder presentar-se als ex\u00e0mens Cambridge English. Disponibles de setembre a juny i intensius al juliol.<br>Horaris a consultar.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_531d8e-d8 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-26636_531d8e-d8 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_531d8e-d8 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_minus kt-svg-icon-list-single\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>De CONVERSA<\/strong> per a tots els nivells. De setembre a juny. Horaris a consultar.<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_7dcbb1-4c, .wp-block-kadence-advancedheading.kt-adv-heading26636_7dcbb1-4c[data-kb-block=\"kb-adv-heading26636_7dcbb1-4c\"]{margin-bottom:0px;font-size:20px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_7dcbb1-4c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_7dcbb1-4c[data-kb-block=\"kb-adv-heading26636_7dcbb1-4c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_7dcbb1-4c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_7dcbb1-4c[data-kb-block=\"kb-adv-heading26636_7dcbb1-4c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_7dcbb1-4c wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_7dcbb1-4c\"><strong>FORMAT\/PLATAFORMA:<\/strong><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_590292-68, .wp-block-kadence-advancedheading.kt-adv-heading26636_590292-68[data-kb-block=\"kb-adv-heading26636_590292-68\"]{font-size:17px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_590292-68 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_590292-68[data-kb-block=\"kb-adv-heading26636_590292-68\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_590292-68 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_590292-68[data-kb-block=\"kb-adv-heading26636_590292-68\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_590292-68 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_590292-68\">Per videoconfer\u00e8ncia, via <strong>Zoom<\/strong>.<\/p>\n\n\n\n<p style=\"font-size:17px\"><span style=\"text-decoration: underline;\" class=\"ek-underline\"><a href=\"#informacio-empreses\" class=\"ek-link\">M\u00e9s informaci\u00f3?<\/a><\/span><\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_318c76-30{margin-bottom:0px;margin-top:0px;}.kb-row-layout-id26636_318c76-30 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_318c76-30 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_318c76-30 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_318c76-30 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_318c76-30 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_318c76-30 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_318c76-30 alignnone wp-block-kadence-rowlayout\" id=\"jovenes-anual\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_bf4383-d9 > .kt-inside-inner-col,.kadence-column26636_bf4383-d9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_bf4383-d9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_bf4383-d9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_bf4383-d9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_bf4383-d9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_bf4383-d9{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_bf4383-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_bf4383-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_bf4383-d9 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box26636_51b2b9-f6 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box26636_51b2b9-f6 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#003C5A;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}.kt-info-box26636_51b2b9-f6 .kt-blocks-info-box-link-wrap:hover{background:#003C5A;}.kt-info-box26636_51b2b9-f6.wp-block-kadence-infobox{max-width:100%;}.kt-info-box26636_51b2b9-f6 .kadence-info-box-image-inner-intrisic-container{max-width:75px;}.kt-info-box26636_51b2b9-f6 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:68%;width:400px;height:0px;max-width:100%;}.kt-info-box26636_51b2b9-f6 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box26636_51b2b9-f6 .kt-info-svg-icon-flip, .kt-info-box26636_51b2b9-f6 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box26636_51b2b9-f6 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box26636_51b2b9-f6 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box26636_51b2b9-f6 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:#FFFFFF;font-size:32px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box26636_51b2b9-f6 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:#FFFFFF;}.kt-info-box26636_51b2b9-f6 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box26636_51b2b9-f6 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box26636_51b2b9-f6 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box26636_51b2b9-f6 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box26636_51b2b9-f6 .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:20px;}.kt-info-box26636_51b2b9-f6 .kt-blocks-info-box-link-wrap{display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box26636_51b2b9-f6 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box26636_51b2b9-f6\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png\" alt=\"vimet-blanc\" width=\"400\" height=\"272\" class=\"kt-info-box-image wp-image-85\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc-300x204.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">Classes PARTICULARS<\/h2><\/div><\/span><\/div>\n\n\n<style>.kt-accordion-id26636_988131-44 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:1px;}.kt-accordion-id26636_988131-44 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#F2F2F2;padding-top:0px;padding-right:30px;padding-bottom:30px;padding-left:50px;}.kt-accordion-id26636_988131-44 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;font-size:18px;line-height:24px;color:#555555;padding-top:30px;padding-right:30px;padding-bottom:50px;padding-left:70px;}.kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id26636_988131-44 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id26636_988131-44 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id26636_988131-44 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id26636_988131-44 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#212327;background:#F2F2F2;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#212327;}.kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#212327;}.kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id26636_988131-44:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#F2F2F2;}@media all and (max-width: 1024px){.kt-accordion-id26636_988131-44 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id26636_988131-44 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id26636_988131-44 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id26636_988131-44 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id26636_988131-44 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id26636_988131-44 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id26636_988131-44 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id26636_988131-44 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:1px;}.kt-accordion-id26636_988131-44 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id26636_988131-44 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;padding-right:10px;padding-left:15px;}.kt-accordion-id26636_988131-44 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id26636_988131-44 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id26636_988131-44 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id26636_988131-44 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone acordio\"><div class=\"kt-accordion-wrap kt-accordion-id26636_988131-44 kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrowcircle kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane26636_8b325d-db obrir\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-2-color\">Per videoconfer\u00e8ncia&nbsp;one-to-one&nbsp;&#8211; 100% adaptades al perfil sol\u00b7licitat.<br><\/mark><\/strong>Ideal per a <strong>professionals especialistes i alts c\u00e0rrecs<\/strong> que requereixen molta flexibilitat.<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-spacer.kt-block-spacer-26636_8d123f-78 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-26636_8d123f-78 .kt-divider{border-top-width:1px;height:1px;border-top-color:#212327;width:100%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-26636_8d123f-78\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_412756-ac{margin-bottom:0px;}.kb-row-layout-id26636_412756-ac > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_412756-ac > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_412756-ac > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}.kb-row-layout-id26636_412756-ac > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_412756-ac > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_412756-ac > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_412756-ac alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_3e58df-45 > .kt-inside-inner-col,.kadence-column26636_3e58df-45 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_3e58df-45 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_3e58df-45 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_3e58df-45 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_3e58df-45 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_3e58df-45{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_3e58df-45 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_3e58df-45 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_3e58df-45 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"216\" height=\"230\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-15.png\" alt=\"web-zoom-cursos-empresas-15\" class=\"wp-image-26286\"\/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column26636_3c98df-b6 > .kt-inside-inner-col,.kadence-column26636_3c98df-b6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_3c98df-b6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_3c98df-b6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_3c98df-b6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_3c98df-b6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_3c98df-b6{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_3c98df-b6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_3c98df-b6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_3c98df-b6 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_64baf6-1f, .wp-block-kadence-advancedheading.kt-adv-heading26636_64baf6-1f[data-kb-block=\"kb-adv-heading26636_64baf6-1f\"]{margin-bottom:0px;font-size:20px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_64baf6-1f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_64baf6-1f[data-kb-block=\"kb-adv-heading26636_64baf6-1f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_64baf6-1f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_64baf6-1f[data-kb-block=\"kb-adv-heading26636_64baf6-1f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_64baf6-1f wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_64baf6-1f\"><strong>INDICAT PER A:<\/strong><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_95d127-4a, .wp-block-kadence-advancedheading.kt-adv-heading26636_95d127-4a[data-kb-block=\"kb-adv-heading26636_95d127-4a\"]{font-size:17px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_95d127-4a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_95d127-4a[data-kb-block=\"kb-adv-heading26636_95d127-4a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_95d127-4a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_95d127-4a[data-kb-block=\"kb-adv-heading26636_95d127-4a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_95d127-4a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_95d127-4a\"><strong>Empleats espec\u00edfics i executius<\/strong> que tenen una <strong>necessitat immediata i urgent de millorar una llengua<\/strong>, o requereixen un curs <strong>molt personalitzat<\/strong> i adaptat al seu nivell i a la seva <strong>disponibilitat<\/strong>.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_da19ea-14, .wp-block-kadence-advancedheading.kt-adv-heading26636_da19ea-14[data-kb-block=\"kb-adv-heading26636_da19ea-14\"]{font-size:17px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_da19ea-14 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_da19ea-14[data-kb-block=\"kb-adv-heading26636_da19ea-14\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_da19ea-14 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_da19ea-14[data-kb-block=\"kb-adv-heading26636_da19ea-14\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_da19ea-14 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_da19ea-14\">Per la seva <strong>alta flexibilitat<\/strong>, estan especialment recomanats per a<strong> professionals que viatgen molt o que volen desenvolupar el seu angl\u00e8s en un camp concret<\/strong>. Les classes es poden seguir a dist\u00e0ncia <strong>per&nbsp;Teams&nbsp;o per Zoom<\/strong> des d&#8217;on es trobi i preparar-se segons les seves necessitats concretes.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_220299-1e, .wp-block-kadence-advancedheading.kt-adv-heading26636_220299-1e[data-kb-block=\"kb-adv-heading26636_220299-1e\"]{margin-bottom:0px;font-size:20px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_220299-1e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_220299-1e[data-kb-block=\"kb-adv-heading26636_220299-1e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_220299-1e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_220299-1e[data-kb-block=\"kb-adv-heading26636_220299-1e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_220299-1e wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_220299-1e\"><strong>CURSOS OFERTS:<\/strong><\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_b2e380-ac:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_b2e380-ac ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_b2e380-ac ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_b2e380-ac ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items26636_b2e380-ac ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items26636_b2e380-ac ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:17px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items26636_b2e380-ac kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-26636_f9d649-42 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-26636_f9d649-42 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_f9d649-42 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_minus kt-svg-icon-list-single\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>De&nbsp;BUSINESS&nbsp;ENGLISH<\/strong>&nbsp;(A1, A2, B1, B2, C1 i C2), amb la possibilitat de centrar part del contingut en temes relacionats amb la teva empresa..<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_ea70a5-89 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-26636_ea70a5-89 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_ea70a5-89 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_minus kt-svg-icon-list-single\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>De PREPARACI\u00d3 d&#8217;Ex\u00e0mens Oficials <\/strong>per a tots els nivells. Per a poder presentar-se als ex\u00e0mens Cambridge&nbsp;English.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_c48cd4-43 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-26636_c48cd4-43 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_c48cd4-43 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_minus kt-svg-icon-list-single\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>De CONVERSA<\/strong> per a tots els nivells, enfocant-nos en els temes que desitgis.<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_24e624-95, .wp-block-kadence-advancedheading.kt-adv-heading26636_24e624-95[data-kb-block=\"kb-adv-heading26636_24e624-95\"]{margin-bottom:0px;font-size:20px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_24e624-95 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_24e624-95[data-kb-block=\"kb-adv-heading26636_24e624-95\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_24e624-95 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_24e624-95[data-kb-block=\"kb-adv-heading26636_24e624-95\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_24e624-95 wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_24e624-95\"><strong>FORMAT\/PLATAFORMA:<\/strong><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_a230df-02, .wp-block-kadence-advancedheading.kt-adv-heading26636_a230df-02[data-kb-block=\"kb-adv-heading26636_a230df-02\"]{font-size:17px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_a230df-02 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_a230df-02[data-kb-block=\"kb-adv-heading26636_a230df-02\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_a230df-02 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_a230df-02[data-kb-block=\"kb-adv-heading26636_a230df-02\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_a230df-02 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_a230df-02\">Per videoconfer\u00e8ncia, <strong>via Zoom<\/strong> i <strong>Microsoft&nbsp;Teams<\/strong><br>(a triar per l&#8217;empresa).<\/p>\n\n\n\n<p style=\"font-size:17px\"><span style=\"text-decoration: underline;\" class=\"ek-underline\"><a href=\"#informacio-empreses\" class=\"ek-link\">M\u00e9s informaci\u00f3?<\/a><\/span><\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_332175-ca{margin-bottom:0px;margin-top:10px;}.kb-row-layout-id26636_332175-ca > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_332175-ca > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_332175-ca > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1050px;margin-left:auto;margin-right:auto;padding-top:50px;padding-bottom:50px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_332175-ca > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_332175-ca > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_332175-ca > .kt-row-column-wrap{padding-right:20px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_332175-ca alignfull has-central-palette-2-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"cursos-empreses-3\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_5ecafc-3c > .kt-inside-inner-col,.kadence-column26636_5ecafc-3c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_5ecafc-3c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_5ecafc-3c > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_5ecafc-3c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_5ecafc-3c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_5ecafc-3c{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_5ecafc-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_5ecafc-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_5ecafc-3c inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_db4384-a2, .wp-block-kadence-advancedheading.kt-adv-heading26636_db4384-a2[data-kb-block=\"kb-adv-heading26636_db4384-a2\"]{margin-bottom:15px;text-align:center;font-size:40px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_db4384-a2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_db4384-a2[data-kb-block=\"kb-adv-heading26636_db4384-a2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_db4384-a2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_db4384-a2[data-kb-block=\"kb-adv-heading26636_db4384-a2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_db4384-a2, .wp-block-kadence-advancedheading.kt-adv-heading26636_db4384-a2[data-kb-block=\"kb-adv-heading26636_db4384-a2\"]{font-size:30px;}}<\/style>\n<h2 class=\"kt-adv-heading26636_db4384-a2 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading26636_db4384-a2\">Amb bonificacions Fundae<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_e131cc-12, .wp-block-kadence-advancedheading.kt-adv-heading26636_e131cc-12[data-kb-block=\"kb-adv-heading26636_e131cc-12\"]{text-align:center;font-size:28px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_e131cc-12 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_e131cc-12[data-kb-block=\"kb-adv-heading26636_e131cc-12\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_e131cc-12 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_e131cc-12[data-kb-block=\"kb-adv-heading26636_e131cc-12\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_e131cc-12, .wp-block-kadence-advancedheading.kt-adv-heading26636_e131cc-12[data-kb-block=\"kb-adv-heading26636_e131cc-12\"]{font-size:26px;}}<\/style>\n<h3 class=\"kt-adv-heading26636_e131cc-12 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_e131cc-12\">Tramitem <strong>ajudes p\u00fabliques per recuperar la inversi\u00f3<\/strong> tan aviat es realitza el curs.<\/h3>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_97cac8-fc{margin-bottom:0px;}.kb-row-layout-id26636_97cac8-fc > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_97cac8-fc > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_97cac8-fc > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(45% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(55% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id26636_97cac8-fc > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_97cac8-fc > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id26636_97cac8-fc > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_97cac8-fc alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_3388ad-9e > .kt-inside-inner-col,.kadence-column26636_3388ad-9e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_3388ad-9e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_3388ad-9e > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_3388ad-9e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_3388ad-9e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_3388ad-9e{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_3388ad-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_3388ad-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_3388ad-9e inner-column-1\"><div class=\"kt-inside-inner-col\"><div class=\"wp-block-image eplus-971rwa\">\n<figure class=\"alignright size-full\"><a href=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-16.png\"><img loading=\"lazy\" decoding=\"async\" width=\"493\" height=\"402\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-16.png\" alt=\"web-zoom-cursos-empresas-16\" class=\"wp-image-26300\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-16.png 493w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-16-300x245.png 300w\" sizes=\"auto, (max-width: 493px) 100vw, 493px\" \/><\/a><\/figure>\n<\/div><\/div><\/div>\n\n\n<style>.kadence-column26636_97cb8b-40 > .kt-inside-inner-col,.kadence-column26636_97cb8b-40 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_97cb8b-40 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_97cb8b-40 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_97cb8b-40 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_97cb8b-40 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_97cb8b-40{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_97cb8b-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_97cb8b-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_97cb8b-40 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_7a0d5f-35, .wp-block-kadence-advancedheading.kt-adv-heading26636_7a0d5f-35[data-kb-block=\"kb-adv-heading26636_7a0d5f-35\"]{font-size:30px;font-style:normal;letter-spacing:-0.8px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_7a0d5f-35 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_7a0d5f-35[data-kb-block=\"kb-adv-heading26636_7a0d5f-35\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_7a0d5f-35 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_7a0d5f-35[data-kb-block=\"kb-adv-heading26636_7a0d5f-35\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_7a0d5f-35, .wp-block-kadence-advancedheading.kt-adv-heading26636_7a0d5f-35[data-kb-block=\"kb-adv-heading26636_7a0d5f-35\"]{font-size:24px;}}<\/style>\n<h4 class=\"kt-adv-heading26636_7a0d5f-35 wp-block-kadence-advancedheading has-central-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading26636_7a0d5f-35\"><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">Som Entitat Organitzadora Fundae<\/span><\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_22ce0a-1d, .wp-block-kadence-advancedheading.kt-adv-heading26636_22ce0a-1d[data-kb-block=\"kb-adv-heading26636_22ce0a-1d\"]{font-size:17px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_22ce0a-1d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_22ce0a-1d[data-kb-block=\"kb-adv-heading26636_22ce0a-1d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_22ce0a-1d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_22ce0a-1d[data-kb-block=\"kb-adv-heading26636_22ce0a-1d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_22ce0a-1d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_22ce0a-1d\">Oferim la possibilitat de<strong> bonificar el curs<\/strong> amb les <strong>ajudes p\u00fabliques de la&nbsp;Fundae<\/strong>&nbsp;(Fundaci\u00f3n Estatal para la Formaci\u00f3n en el Empleo \u2013 antiga Fundaci\u00f3n Tripartita) per <strong>recuperar \u2013totalment o parcialment\u2013 el cost dels cursos<\/strong> dels alumnes que treballen en la teva empresa.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_7a4619-26, .wp-block-kadence-advancedheading.kt-adv-heading26636_7a4619-26[data-kb-block=\"kb-adv-heading26636_7a4619-26\"]{font-size:17px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_7a4619-26 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_7a4619-26[data-kb-block=\"kb-adv-heading26636_7a4619-26\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_7a4619-26 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_7a4619-26[data-kb-block=\"kb-adv-heading26636_7a4619-26\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_7a4619-26 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_7a4619-26\">Els cursos bonificats s\u00f3n una<strong> ajuda econ\u00f2mica a la formaci\u00f3<\/strong> per a <strong>alumnes empleats que treballen per compte d&#8217;altri<\/strong> que beneficia tant a l&#8217;empresa com a l&#8217;empleat.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_20fc7b-57, .wp-block-kadence-advancedheading.kt-adv-heading26636_20fc7b-57[data-kb-block=\"kb-adv-heading26636_20fc7b-57\"]{font-size:17px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_20fc7b-57 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_20fc7b-57[data-kb-block=\"kb-adv-heading26636_20fc7b-57\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_20fc7b-57 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_20fc7b-57[data-kb-block=\"kb-adv-heading26636_20fc7b-57\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading26636_20fc7b-57[data-kb-block=\"kb-adv-heading26636_20fc7b-57\"] a, .kt-adv-heading-link26636_20fc7b-57, .kt-adv-heading-link26636_20fc7b-57 .kt-adv-heading26636_20fc7b-57[data-kb-block=\"kb-adv-heading26636_20fc7b-57\"]{color:#FFFFFF;}.wp-block-kadence-advancedheading.kt-adv-heading26636_20fc7b-57[data-kb-block=\"kb-adv-heading26636_20fc7b-57\"] a:hover, .kt-adv-heading-link26636_20fc7b-57:hover, .kt-adv-heading-link26636_20fc7b-57:hover .kt-adv-heading26636_20fc7b-57[data-kb-block=\"kb-adv-heading26636_20fc7b-57\"]{color:#FFFFFF;}<\/style>\n<p class=\"kt-adv-heading26636_20fc7b-57 wp-block-kadence-advancedheading has-central-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading26636_20fc7b-57\"><strong><a href=\"#informacio-empreses\" class=\"ek-link\">&gt;&gt; INFORMA-TE&#8217;N ARA<\/a><\/strong><\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_6e1fc9-20{margin-bottom:0px;margin-top:50px;}.kb-row-layout-id26636_6e1fc9-20 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_6e1fc9-20 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_6e1fc9-20 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_6e1fc9-20 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_6e1fc9-20 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_6e1fc9-20 > .kt-row-column-wrap{padding-right:15px;padding-left:15px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_6e1fc9-20 alignnone wp-block-kadence-rowlayout\" id=\"pla-seguiment\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_9b3908-2f > .kt-inside-inner-col,.kadence-column26636_9b3908-2f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_9b3908-2f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_9b3908-2f > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_9b3908-2f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_9b3908-2f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_9b3908-2f{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_9b3908-2f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_9b3908-2f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_9b3908-2f inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_e49d98-d1, .wp-block-kadence-advancedheading.kt-adv-heading26636_e49d98-d1[data-kb-block=\"kb-adv-heading26636_e49d98-d1\"]{padding-bottom:0px;margin-bottom:0px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_e49d98-d1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_e49d98-d1[data-kb-block=\"kb-adv-heading26636_e49d98-d1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_e49d98-d1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_e49d98-d1[data-kb-block=\"kb-adv-heading26636_e49d98-d1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_e49d98-d1 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_e49d98-d1\"><strong>Amb pla de seguiment<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_5ea090-e3, .wp-block-kadence-advancedheading.kt-adv-heading26636_5ea090-e3[data-kb-block=\"kb-adv-heading26636_5ea090-e3\"]{text-align:center;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_5ea090-e3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_5ea090-e3[data-kb-block=\"kb-adv-heading26636_5ea090-e3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_5ea090-e3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_5ea090-e3[data-kb-block=\"kb-adv-heading26636_5ea090-e3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_5ea090-e3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_5ea090-e3\">per assolir l\u2019objectiu de la formaci\u00f3.<\/h3>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_20f863-39{margin-bottom:0px;}.kb-row-layout-id26636_20f863-39 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id26636_20f863-39 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id26636_20f863-39 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(35% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(65% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id26636_20f863-39 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_20f863-39 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (min-width: 768px) and (max-width: 1024px){.kb-row-layout-id26636_20f863-39{display:none !important;}}@media all and (max-width: 767px){.kb-row-layout-id26636_20f863-39 > .kt-row-column-wrap{padding-right:15px;padding-left:15px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_20f863-39{display:none !important;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_20f863-39 alignnone kb-v-md-hidden kb-v-sm-hidden wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column26636_da19b7-c6 > .kt-inside-inner-col,.kadence-column26636_da19b7-c6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_da19b7-c6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_da19b7-c6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_da19b7-c6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_da19b7-c6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_da19b7-c6{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_da19b7-c6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_da19b7-c6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_da19b7-c6 inner-column-1\"><div class=\"kt-inside-inner-col\"><div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"248\" height=\"685\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-17.png\" alt=\"\" class=\"wp-image-26306\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-17.png 248w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-17-109x300.png 109w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n<style>.kadence-column26636_7bc144-ca > .kt-inside-inner-col,.kadence-column26636_7bc144-ca > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_7bc144-ca > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_7bc144-ca > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_7bc144-ca > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_7bc144-ca > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_7bc144-ca{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_7bc144-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_7bc144-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_7bc144-ca inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_6024f0-6d, .wp-block-kadence-advancedheading.kt-adv-heading26636_6024f0-6d[data-kb-block=\"kb-adv-heading26636_6024f0-6d\"]{margin-bottom:10px;font-size:24px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_6024f0-6d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_6024f0-6d[data-kb-block=\"kb-adv-heading26636_6024f0-6d\"] mark.kt-highlight{font-style:normal;color:#00B8D6;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_6024f0-6d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_6024f0-6d[data-kb-block=\"kb-adv-heading26636_6024f0-6d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_6024f0-6d wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading26636_6024f0-6d\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-2-color\">PAS 1:<\/mark> Auditoria ling\u00fc\u00edstica de l&#8217;alumnat<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_42147a-ab, .wp-block-kadence-advancedheading.kt-adv-heading26636_42147a-ab[data-kb-block=\"kb-adv-heading26636_42147a-ab\"]{margin-bottom:0px;font-size:16px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_42147a-ab mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_42147a-ab[data-kb-block=\"kb-adv-heading26636_42147a-ab\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_42147a-ab img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_42147a-ab[data-kb-block=\"kb-adv-heading26636_42147a-ab\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading26636_42147a-ab wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_42147a-ab\">Es realitza una <strong>prova de nivell <\/strong>que consta d&#8217;una part gramatical i vocabulari i d&#8217;una entrevista oral. Mitjan\u00e7ant aquesta prova, <strong>obtenim el nivell d&#8217;angl\u00e8s de cada alumne<\/strong> dins del MCER (Marc Com\u00fa Europeu de Refer\u00e8ncia per a les lleng\u00fces).<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_d04cf1-36, .wp-block-kadence-advancedheading.kt-adv-heading26636_d04cf1-36[data-kb-block=\"kb-adv-heading26636_d04cf1-36\"]{margin-top:40px;margin-bottom:10px;font-size:24px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_d04cf1-36 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_d04cf1-36[data-kb-block=\"kb-adv-heading26636_d04cf1-36\"] mark.kt-highlight{font-style:normal;color:#00B8D6;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_d04cf1-36 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_d04cf1-36[data-kb-block=\"kb-adv-heading26636_d04cf1-36\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_d04cf1-36 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading26636_d04cf1-36\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-2-color\">PAS 2:<\/mark> Definici\u00f3 del pla i objectius de formaci\u00f3<\/strong><\/h3>\n\n\n\n<p>A partir dels resultats de l&#8217;auditoria, <strong>definim conjuntament els objectius<\/strong> i elaborem una proposta a mida. Com que partim d&#8217;una base real i tenim clara la meta de cada alumne, el pla de formaci\u00f3 permet <strong>assolir els objectius ling\u00fc\u00edstics en el temps \u00f2ptim<\/strong>.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_426b2d-4e, .wp-block-kadence-advancedheading.kt-adv-heading26636_426b2d-4e[data-kb-block=\"kb-adv-heading26636_426b2d-4e\"]{margin-top:40px;margin-bottom:10px;font-size:24px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_426b2d-4e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_426b2d-4e[data-kb-block=\"kb-adv-heading26636_426b2d-4e\"] mark.kt-highlight{font-style:normal;color:#00B8D6;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_426b2d-4e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_426b2d-4e[data-kb-block=\"kb-adv-heading26636_426b2d-4e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_426b2d-4e wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading26636_426b2d-4e\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-2-color\">PAS 3:<\/mark> Tests, ex\u00e0mens i mesurament del progr\u00e9s<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_c25daa-98, .wp-block-kadence-advancedheading.kt-adv-heading26636_c25daa-98[data-kb-block=\"kb-adv-heading26636_c25daa-98\"]{margin-bottom:0px;font-size:16px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_c25daa-98 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_c25daa-98[data-kb-block=\"kb-adv-heading26636_c25daa-98\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_c25daa-98 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_c25daa-98[data-kb-block=\"kb-adv-heading26636_c25daa-98\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_c25daa-98 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_c25daa-98\">Fem<strong> informes peri\u00f2dics de seguiment <\/strong>sobre:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_0a5737-e5:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_0a5737-e5 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_0a5737-e5 ul.kt-svg-icon-list{grid-row-gap:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_0a5737-e5 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items26636_0a5737-e5 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items26636_0a5737-e5 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:16px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items26636_0a5737-e5 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-26636_9351d1-53 .kt-svg-icon-list-single{font-size:14px !important;}.kt-svg-icon-list-item-26636_9351d1-53 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_9351d1-53 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_minus kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Assist\u00e8ncia de l&#8217;alumnat.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_9594e2-03 .kt-svg-icon-list-single{font-size:14px !important;}.kt-svg-icon-list-item-26636_9594e2-03 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_9594e2-03 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_minus kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Evoluci\u00f3 detallada del progr\u00e9s de cada alumne en les seves activitats individuals.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_991484-ff .kt-svg-icon-list-single{font-size:14px !important;}.kt-svg-icon-list-item-26636_991484-ff .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_991484-ff kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_minus kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Tasques escrites, corregides i avaluades.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_fedb95-e9 .kt-svg-icon-list-single{font-size:14px !important;}.kt-svg-icon-list-item-26636_fedb95-e9 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_fedb95-e9 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_minus kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Resultats dels controls peri\u00f2dics i ex\u00e0mens de nivell.<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_cdd011-bf, .wp-block-kadence-advancedheading.kt-adv-heading26636_cdd011-bf[data-kb-block=\"kb-adv-heading26636_cdd011-bf\"]{margin-top:40px;margin-bottom:10px;font-size:24px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_cdd011-bf mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_cdd011-bf[data-kb-block=\"kb-adv-heading26636_cdd011-bf\"] mark.kt-highlight{font-style:normal;color:#00B8D6;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_cdd011-bf img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_cdd011-bf[data-kb-block=\"kb-adv-heading26636_cdd011-bf\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_cdd011-bf wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading26636_cdd011-bf\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-2-color\">PAS 4:<\/mark> Feedback i planificaci\u00f3 del pr\u00f2xim curs<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_916d0a-f1, .wp-block-kadence-advancedheading.kt-adv-heading26636_916d0a-f1[data-kb-block=\"kb-adv-heading26636_916d0a-f1\"]{font-size:16px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_916d0a-f1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_916d0a-f1[data-kb-block=\"kb-adv-heading26636_916d0a-f1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_916d0a-f1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_916d0a-f1[data-kb-block=\"kb-adv-heading26636_916d0a-f1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading26636_916d0a-f1 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_916d0a-f1\">En acabar el curs, ja realitzats els ex\u00e0mens i les tutories amb els alumnes, <strong>comuniquem a l&#8217;empresa la nostra valoraci\u00f3<\/strong> i realitzem la planificaci\u00f3 necess\u00e0ria per al curs seg\u00fcent.<\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_a3b195-91{margin-bottom:0px;}.kb-row-layout-id26636_a3b195-91 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id26636_a3b195-91 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id26636_a3b195-91 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);padding-top:25px;padding-right:0px;padding-bottom:25px;padding-left:0px;grid-template-columns:minmax(0, calc(40% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(60% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id26636_a3b195-91 > .kt-row-layout-overlay{opacity:0.30;}@media all and (min-width: 1025px){.kb-row-layout-id26636_a3b195-91{display:none !important;}}@media all and (max-width: 1024px){.kb-row-layout-id26636_a3b195-91 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_a3b195-91 > .kt-row-column-wrap{padding-top:25px;padding-right:0px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_a3b195-91 alignnone kb-v-lg-hidden wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-middle\">\n<style>.kadence-column26636_d486cc-0d > .kt-inside-inner-col,.kadence-column26636_d486cc-0d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_d486cc-0d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_d486cc-0d > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_d486cc-0d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_d486cc-0d > .kt-inside-inner-col{background-image:url('https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-17.png');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column26636_d486cc-0d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_d486cc-0d{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_d486cc-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_d486cc-0d > .kt-inside-inner-col{min-height:600px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_d486cc-0d kb-section-dir-vertical kb-section-sm-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column26636_59d2e5-91 > .kt-inside-inner-col,.kadence-column26636_59d2e5-91 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_59d2e5-91 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_59d2e5-91 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_59d2e5-91 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_59d2e5-91 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_59d2e5-91{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_59d2e5-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_59d2e5-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_59d2e5-91 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_b7c5f0-48, .wp-block-kadence-advancedheading.kt-adv-heading26636_b7c5f0-48[data-kb-block=\"kb-adv-heading26636_b7c5f0-48\"]{margin-bottom:0px;font-size:20px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_b7c5f0-48 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_b7c5f0-48[data-kb-block=\"kb-adv-heading26636_b7c5f0-48\"] mark.kt-highlight{font-style:normal;color:#00B8D6;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_b7c5f0-48 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_b7c5f0-48[data-kb-block=\"kb-adv-heading26636_b7c5f0-48\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_b7c5f0-48, .wp-block-kadence-advancedheading.kt-adv-heading26636_b7c5f0-48[data-kb-block=\"kb-adv-heading26636_b7c5f0-48\"]{font-size:18px;}}<\/style>\n<h3 class=\"kt-adv-heading26636_b7c5f0-48 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading26636_b7c5f0-48\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-2-color\">PAS 1:<\/mark><\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_e9477f-7d, .wp-block-kadence-advancedheading.kt-adv-heading26636_e9477f-7d[data-kb-block=\"kb-adv-heading26636_e9477f-7d\"]{margin-bottom:10px;font-size:20px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_e9477f-7d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_e9477f-7d[data-kb-block=\"kb-adv-heading26636_e9477f-7d\"] mark.kt-highlight{font-style:normal;color:#00B8D6;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_e9477f-7d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_e9477f-7d[data-kb-block=\"kb-adv-heading26636_e9477f-7d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_e9477f-7d, .wp-block-kadence-advancedheading.kt-adv-heading26636_e9477f-7d[data-kb-block=\"kb-adv-heading26636_e9477f-7d\"]{padding-bottom:0px;margin-bottom:5px;font-size:18px;}}<\/style>\n<h3 class=\"kt-adv-heading26636_e9477f-7d wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading26636_e9477f-7d\"><strong>Auditoria ling\u00fc\u00edstica de l&#8217;alumnat<\/strong><\/h3>\n\n\n<style>#kt-modal26636_fa5545-4a .kt-blocks-modal-link{color:#00B8D6;background:transparent;border-radius:0px;font-size:16px;line-height:14px;font-weight:bold;border-width:0px 0px 0px 0px;padding:0px 0px 0px 0px;margin:0px 0px 0px 0px;}#kt-modal26636_fa5545-4a .kt-blocks-modal-link:hover, #kt-modal26636_fa5545-4a .kt-blocks-modal-link:focus{color:#003C5A;}#kt-modal26636_fa5545-4a .kt-modal-overlay, #kt-target-modal26636_fa5545-4a .kt-modal-overlay, .kb-modal-content26636_fa5545-4a .kt-modal-overlay{background:rgba(0, 184, 214, 0.66);}#kt-modal26636_fa5545-4a .kt-modal-overlay, #kt-target-modal26636_fa5545-4a .kt-modal-overlay, .kb-modal-content26636_fa5545-4a .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal26636_fa5545-4a .kt-modal-container, #kt-target-modal26636_fa5545-4a .kt-modal-container, .kb-modal-content26636_fa5545-4a .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal26636_fa5545-4a .kt-modal-container, #kt-target-modal26636_fa5545-4a .kt-modal-container, .kb-modal-content26636_fa5545-4a .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal26636_fa5545-4a .kt-modal-container, #kt-target-modal26636_fa5545-4a .kt-modal-container, .kb-modal-content26636_fa5545-4a .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal26636_fa5545-4a .kt-modal-close svg, #kt-target-modal26636_fa5545-4a .kt-modal-close svg, .kb-modal-content26636_fa5545-4a .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal26636_fa5545-4a .kt-modal-container, #kt-target-modal26636_fa5545-4a .kt-modal-container, .kb-modal-content26636_fa5545-4a .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal26636_fa5545-4a .kt-modal-close svg, #kt-target-modal26636_fa5545-4a .kt-modal-close svg, .kb-modal-content26636_fa5545-4a .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal26636_fa5545-4a .kt-modal-container, #kt-target-modal26636_fa5545-4a .kt-modal-container, .kb-modal-content26636_fa5545-4a .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal26636_fa5545-4a .kt-modal-close svg, #kt-target-modal26636_fa5545-4a .kt-modal-close svg, .kb-modal-content26636_fa5545-4a .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-left\" id=\"kt-modal26636_fa5545-4a\"><div id=\"kt-target-modal26636_fa5545-4a\" class=\"kb-modal-content26636_fa5545-4a kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal26636_fa5545-4a-content\" class=\"kt-modal-content\">\n<p>Es realitza una <strong>prova de nivell <\/strong>que consta d&#8217;una part gramatical i vocabulari i d&#8217;una entrevista oral. Mitjan\u00e7ant aquesta prova, <strong>obtenim el nivell d&#8217;angl\u00e8s de cada alumne<\/strong> dins del MCER (Marc Com\u00fa Europeu de Refer\u00e8ncia per a les lleng\u00fces).<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal26636_fa5545-4a\"><span class=\"kt-blocks-modal-link-inner\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">VE<\/span>URE M\u00c9S<\/span><\/button><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_a8e504-7f, .wp-block-kadence-advancedheading.kt-adv-heading26636_a8e504-7f[data-kb-block=\"kb-adv-heading26636_a8e504-7f\"]{margin-top:40px;margin-bottom:0px;font-size:20px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_a8e504-7f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_a8e504-7f[data-kb-block=\"kb-adv-heading26636_a8e504-7f\"] mark.kt-highlight{font-style:normal;color:#00B8D6;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_a8e504-7f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_a8e504-7f[data-kb-block=\"kb-adv-heading26636_a8e504-7f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_a8e504-7f, .wp-block-kadence-advancedheading.kt-adv-heading26636_a8e504-7f[data-kb-block=\"kb-adv-heading26636_a8e504-7f\"]{padding-top:0px;margin-top:24px;font-size:18px;}}<\/style>\n<h3 class=\"kt-adv-heading26636_a8e504-7f wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading26636_a8e504-7f\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-2-color\">PAS 2:<\/mark><\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_52ba4d-82, .wp-block-kadence-advancedheading.kt-adv-heading26636_52ba4d-82[data-kb-block=\"kb-adv-heading26636_52ba4d-82\"]{margin-top:0px;margin-bottom:10px;font-size:20px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_52ba4d-82 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_52ba4d-82[data-kb-block=\"kb-adv-heading26636_52ba4d-82\"] mark.kt-highlight{font-style:normal;color:#00B8D6;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_52ba4d-82 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_52ba4d-82[data-kb-block=\"kb-adv-heading26636_52ba4d-82\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_52ba4d-82, .wp-block-kadence-advancedheading.kt-adv-heading26636_52ba4d-82[data-kb-block=\"kb-adv-heading26636_52ba4d-82\"]{padding-bottom:0px;margin-bottom:5px;font-size:18px;}}<\/style>\n<h3 class=\"kt-adv-heading26636_52ba4d-82 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading26636_52ba4d-82\"><strong>Definici\u00f3 del pla i objectius de formaci\u00f3<\/strong><\/h3>\n\n\n<style>#kt-modal26636_6829c1-1c .kt-blocks-modal-link{color:#00B8D6;background:transparent;border-radius:0px;font-size:16px;line-height:14px;font-weight:bold;border-width:0px 0px 0px 0px;padding:0px 0px 0px 0px;margin:0px 0px 0px 0px;}#kt-modal26636_6829c1-1c .kt-blocks-modal-link:hover, #kt-modal26636_6829c1-1c .kt-blocks-modal-link:focus{color:#003C5A;}#kt-modal26636_6829c1-1c .kt-modal-overlay, #kt-target-modal26636_6829c1-1c .kt-modal-overlay, .kb-modal-content26636_6829c1-1c .kt-modal-overlay{background:rgba(0, 184, 214, 0.66);}#kt-modal26636_6829c1-1c .kt-modal-overlay, #kt-target-modal26636_6829c1-1c .kt-modal-overlay, .kb-modal-content26636_6829c1-1c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal26636_6829c1-1c .kt-modal-container, #kt-target-modal26636_6829c1-1c .kt-modal-container, .kb-modal-content26636_6829c1-1c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal26636_6829c1-1c .kt-modal-container, #kt-target-modal26636_6829c1-1c .kt-modal-container, .kb-modal-content26636_6829c1-1c .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal26636_6829c1-1c .kt-modal-container, #kt-target-modal26636_6829c1-1c .kt-modal-container, .kb-modal-content26636_6829c1-1c .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal26636_6829c1-1c .kt-modal-close svg, #kt-target-modal26636_6829c1-1c .kt-modal-close svg, .kb-modal-content26636_6829c1-1c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal26636_6829c1-1c .kt-modal-container, #kt-target-modal26636_6829c1-1c .kt-modal-container, .kb-modal-content26636_6829c1-1c .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal26636_6829c1-1c .kt-modal-close svg, #kt-target-modal26636_6829c1-1c .kt-modal-close svg, .kb-modal-content26636_6829c1-1c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal26636_6829c1-1c .kt-modal-container, #kt-target-modal26636_6829c1-1c .kt-modal-container, .kb-modal-content26636_6829c1-1c .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal26636_6829c1-1c .kt-modal-close svg, #kt-target-modal26636_6829c1-1c .kt-modal-close svg, .kb-modal-content26636_6829c1-1c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-left\" id=\"kt-modal26636_6829c1-1c\"><div id=\"kt-target-modal26636_6829c1-1c\" class=\"kb-modal-content26636_6829c1-1c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal26636_6829c1-1c-content\" class=\"kt-modal-content\">\n<p>A partir dels resultats de l&#8217;auditoria, <strong>definim conjuntament els objectius<\/strong> i elaborem una proposta a mida. Com que partim d&#8217;una base real i tenim clara la meta de cada alumne, el pla de formaci\u00f3 <strong>permet assolir els objectius ling\u00fc\u00edstics en el temps \u00f2ptim<\/strong>.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal26636_6829c1-1c\"><span class=\"kt-blocks-modal-link-inner\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">VEURE M\u00c9S<\/span><\/span><\/button><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_11cfef-97, .wp-block-kadence-advancedheading.kt-adv-heading26636_11cfef-97[data-kb-block=\"kb-adv-heading26636_11cfef-97\"]{margin-top:40px;margin-bottom:0px;font-size:20px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_11cfef-97 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_11cfef-97[data-kb-block=\"kb-adv-heading26636_11cfef-97\"] mark.kt-highlight{font-style:normal;color:#00B8D6;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_11cfef-97 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_11cfef-97[data-kb-block=\"kb-adv-heading26636_11cfef-97\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_11cfef-97, .wp-block-kadence-advancedheading.kt-adv-heading26636_11cfef-97[data-kb-block=\"kb-adv-heading26636_11cfef-97\"]{padding-top:0px;margin-top:24px;font-size:18px;}}<\/style>\n<h3 class=\"kt-adv-heading26636_11cfef-97 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading26636_11cfef-97\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-2-color\">PAS 3:<\/mark><\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_2d9b6d-21, .wp-block-kadence-advancedheading.kt-adv-heading26636_2d9b6d-21[data-kb-block=\"kb-adv-heading26636_2d9b6d-21\"]{margin-top:0px;margin-bottom:10px;font-size:20px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_2d9b6d-21 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_2d9b6d-21[data-kb-block=\"kb-adv-heading26636_2d9b6d-21\"] mark.kt-highlight{font-style:normal;color:#00B8D6;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_2d9b6d-21 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_2d9b6d-21[data-kb-block=\"kb-adv-heading26636_2d9b6d-21\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_2d9b6d-21, .wp-block-kadence-advancedheading.kt-adv-heading26636_2d9b6d-21[data-kb-block=\"kb-adv-heading26636_2d9b6d-21\"]{margin-bottom:5px;font-size:18px;}}<\/style>\n<h3 class=\"kt-adv-heading26636_2d9b6d-21 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading26636_2d9b6d-21\"><strong>Tests, ex\u00e0mens i mesurament del progr\u00e9s<\/strong><\/h3>\n\n\n<style>#kt-modal26636_bc4431-d0 .kt-blocks-modal-link{color:#00B8D6;background:transparent;border-radius:0px;font-size:16px;line-height:24px;font-weight:bold;border-width:0px 0px 0px 0px;padding:0px 0px 0px 0px;margin:0px 0px 0px 0px;}#kt-modal26636_bc4431-d0 .kt-blocks-modal-link:hover, #kt-modal26636_bc4431-d0 .kt-blocks-modal-link:focus{color:#003C5A;}#kt-modal26636_bc4431-d0 .kt-modal-overlay, #kt-target-modal26636_bc4431-d0 .kt-modal-overlay, .kb-modal-content26636_bc4431-d0 .kt-modal-overlay{background:rgba(0, 184, 214, 0.66);}#kt-modal26636_bc4431-d0 .kt-modal-overlay, #kt-target-modal26636_bc4431-d0 .kt-modal-overlay, .kb-modal-content26636_bc4431-d0 .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal26636_bc4431-d0 .kt-modal-container, #kt-target-modal26636_bc4431-d0 .kt-modal-container, .kb-modal-content26636_bc4431-d0 .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal26636_bc4431-d0 .kt-modal-container, #kt-target-modal26636_bc4431-d0 .kt-modal-container, .kb-modal-content26636_bc4431-d0 .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal26636_bc4431-d0 .kt-modal-container, #kt-target-modal26636_bc4431-d0 .kt-modal-container, .kb-modal-content26636_bc4431-d0 .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal26636_bc4431-d0 .kt-modal-close svg, #kt-target-modal26636_bc4431-d0 .kt-modal-close svg, .kb-modal-content26636_bc4431-d0 .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal26636_bc4431-d0 .kt-modal-container, #kt-target-modal26636_bc4431-d0 .kt-modal-container, .kb-modal-content26636_bc4431-d0 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal26636_bc4431-d0 .kt-modal-close svg, #kt-target-modal26636_bc4431-d0 .kt-modal-close svg, .kb-modal-content26636_bc4431-d0 .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal26636_bc4431-d0 .kt-modal-container, #kt-target-modal26636_bc4431-d0 .kt-modal-container, .kb-modal-content26636_bc4431-d0 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal26636_bc4431-d0 .kt-modal-close svg, #kt-target-modal26636_bc4431-d0 .kt-modal-close svg, .kb-modal-content26636_bc4431-d0 .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-left\" id=\"kt-modal26636_bc4431-d0\"><div id=\"kt-target-modal26636_bc4431-d0\" class=\"kb-modal-content26636_bc4431-d0 kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal26636_bc4431-d0-content\" class=\"kt-modal-content\">\n<p>Fem <strong>informes peri\u00f2dics<\/strong> de seguiment sobre:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Assist\u00e8ncia de l&#8217;alumnat.<\/li>\n\n\n\n<li>Evoluci\u00f3 detallada del progr\u00e9s de cada alumne en les seves activitats individuals.<\/li>\n\n\n\n<li>Tasques escrites, corregides i avaluades.<\/li>\n\n\n\n<li>Resultats dels controls peri\u00f2dics i ex\u00e0mens de nivell.<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal26636_bc4431-d0\"><span class=\"kt-blocks-modal-link-inner\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">VE<\/span>URE M\u00c9S<\/span><\/button><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_4add30-53, .wp-block-kadence-advancedheading.kt-adv-heading26636_4add30-53[data-kb-block=\"kb-adv-heading26636_4add30-53\"]{margin-top:40px;margin-bottom:0px;font-size:20px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_4add30-53 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_4add30-53[data-kb-block=\"kb-adv-heading26636_4add30-53\"] mark.kt-highlight{font-style:normal;color:#00B8D6;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_4add30-53 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_4add30-53[data-kb-block=\"kb-adv-heading26636_4add30-53\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_4add30-53, .wp-block-kadence-advancedheading.kt-adv-heading26636_4add30-53[data-kb-block=\"kb-adv-heading26636_4add30-53\"]{padding-top:0px;margin-top:24px;font-size:18px;}}<\/style>\n<h3 class=\"kt-adv-heading26636_4add30-53 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading26636_4add30-53\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-2-color\">PAS 4:<\/mark><\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_39c282-9a, .wp-block-kadence-advancedheading.kt-adv-heading26636_39c282-9a[data-kb-block=\"kb-adv-heading26636_39c282-9a\"]{margin-top:0px;margin-bottom:10px;font-size:20px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_39c282-9a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_39c282-9a[data-kb-block=\"kb-adv-heading26636_39c282-9a\"] mark.kt-highlight{font-style:normal;color:#00B8D6;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_39c282-9a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_39c282-9a[data-kb-block=\"kb-adv-heading26636_39c282-9a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_39c282-9a, .wp-block-kadence-advancedheading.kt-adv-heading26636_39c282-9a[data-kb-block=\"kb-adv-heading26636_39c282-9a\"]{padding-top:0px;padding-bottom:0px;margin-bottom:5px;font-size:18px;}}<\/style>\n<h3 class=\"kt-adv-heading26636_39c282-9a wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading26636_39c282-9a\"><strong>Feedback i planificaci\u00f3 del pr\u00f2xim curs<\/strong><\/h3>\n\n\n<style>#kt-modal26636_034246-5e .kt-blocks-modal-link{color:#00B8D6;background:transparent;border-radius:0px;font-size:16px;line-height:14px;font-weight:bold;border-width:0px 0px 0px 0px;padding:0px 0px 0px 0px;margin:0px 0px 0px 0px;}#kt-modal26636_034246-5e .kt-blocks-modal-link:hover, #kt-modal26636_034246-5e .kt-blocks-modal-link:focus{color:#003C5A;}#kt-modal26636_034246-5e .kt-modal-overlay, #kt-target-modal26636_034246-5e .kt-modal-overlay, .kb-modal-content26636_034246-5e .kt-modal-overlay{background:rgba(0, 184, 214, 0.66);}#kt-modal26636_034246-5e .kt-modal-overlay, #kt-target-modal26636_034246-5e .kt-modal-overlay, .kb-modal-content26636_034246-5e .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal26636_034246-5e .kt-modal-container, #kt-target-modal26636_034246-5e .kt-modal-container, .kb-modal-content26636_034246-5e .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal26636_034246-5e .kt-modal-container, #kt-target-modal26636_034246-5e .kt-modal-container, .kb-modal-content26636_034246-5e .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal26636_034246-5e .kt-modal-container, #kt-target-modal26636_034246-5e .kt-modal-container, .kb-modal-content26636_034246-5e .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal26636_034246-5e .kt-modal-close svg, #kt-target-modal26636_034246-5e .kt-modal-close svg, .kb-modal-content26636_034246-5e .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal26636_034246-5e .kt-modal-container, #kt-target-modal26636_034246-5e .kt-modal-container, .kb-modal-content26636_034246-5e .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal26636_034246-5e .kt-modal-close svg, #kt-target-modal26636_034246-5e .kt-modal-close svg, .kb-modal-content26636_034246-5e .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal26636_034246-5e .kt-modal-container, #kt-target-modal26636_034246-5e .kt-modal-container, .kb-modal-content26636_034246-5e .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal26636_034246-5e .kt-modal-close svg, #kt-target-modal26636_034246-5e .kt-modal-close svg, .kb-modal-content26636_034246-5e .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-left\" id=\"kt-modal26636_034246-5e\"><div id=\"kt-target-modal26636_034246-5e\" class=\"kb-modal-content26636_034246-5e kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal26636_034246-5e-content\" class=\"kt-modal-content\">\n<p>En acabar el curs, ja realitzats els ex\u00e0mens i les tutories amb els alumnes,<strong> comuniquem a l&#8217;empresa la nostra valoraci\u00f3<\/strong> i realitzem la planificaci\u00f3 necess\u00e0ria per al curs seg\u00fcent.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal26636_034246-5e\"><span class=\"kt-blocks-modal-link-inner\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">VEURE M\u00c9S<\/span><\/span><\/button><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_4eb542-cb, .wp-block-kadence-advancedheading.kt-adv-heading26636_4eb542-cb[data-kb-block=\"kb-adv-heading26636_4eb542-cb\"]{text-align:center;font-size:28px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_4eb542-cb mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_4eb542-cb[data-kb-block=\"kb-adv-heading26636_4eb542-cb\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_4eb542-cb img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_4eb542-cb[data-kb-block=\"kb-adv-heading26636_4eb542-cb\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_4eb542-cb wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_4eb542-cb\">Cada pas \u00e9s un pas en la direcci\u00f3 correcta.<\/h3>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_3ac4f9-c6{margin-bottom:0px;margin-top:50px;}.kb-row-layout-id26636_3ac4f9-c6 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_3ac4f9-c6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_3ac4f9-c6 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_3ac4f9-c6 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_3ac4f9-c6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_3ac4f9-c6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_3ac4f9-c6 alignnone wp-block-kadence-rowlayout\" id=\"cursos-empreses-4\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_e6f7f9-ba > .kt-inside-inner-col,.kadence-column26636_e6f7f9-ba > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_e6f7f9-ba > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_e6f7f9-ba > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_e6f7f9-ba > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_e6f7f9-ba > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_e6f7f9-ba{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_e6f7f9-ba > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_e6f7f9-ba > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_e6f7f9-ba inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_9f1eb3-42, .wp-block-kadence-advancedheading.kt-adv-heading26636_9f1eb3-42[data-kb-block=\"kb-adv-heading26636_9f1eb3-42\"]{padding-bottom:0px;margin-bottom:0px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_9f1eb3-42 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_9f1eb3-42[data-kb-block=\"kb-adv-heading26636_9f1eb3-42\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_9f1eb3-42 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_9f1eb3-42[data-kb-block=\"kb-adv-heading26636_9f1eb3-42\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_9f1eb3-42 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_9f1eb3-42\"><strong>Som centre autoritzat Cambridge&nbsp;English<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_14f493-da, .wp-block-kadence-advancedheading.kt-adv-heading26636_14f493-da[data-kb-block=\"kb-adv-heading26636_14f493-da\"]{text-align:center;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_14f493-da mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_14f493-da[data-kb-block=\"kb-adv-heading26636_14f493-da\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_14f493-da img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_14f493-da[data-kb-block=\"kb-adv-heading26636_14f493-da\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_14f493-da wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_14f493-da\">Preparador i examinador d&#8217;ex\u00e0mens oficials<\/h3>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_0b9a9c-b4{margin-bottom:0px;}.kb-row-layout-id26636_0b9a9c-b4 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_0b9a9c-b4 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_0b9a9c-b4 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_0b9a9c-b4 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_0b9a9c-b4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_0b9a9c-b4 > .kt-row-column-wrap{padding-top:25px;padding-right:20px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_0b9a9c-b4 alignnone has-central-palette-6-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_14e0b1-88 > .kt-inside-inner-col,.kadence-column26636_14e0b1-88 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_14e0b1-88 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_14e0b1-88 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_14e0b1-88 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_14e0b1-88 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_14e0b1-88{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_14e0b1-88 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_14e0b1-88 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_14e0b1-88 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_77dedf-cc{margin-bottom:0px;}.kb-row-layout-id26636_77dedf-cc > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id26636_77dedf-cc > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id26636_77dedf-cc > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:26px;padding-bottom:25px;grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id26636_77dedf-cc > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_77dedf-cc > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_77dedf-cc > .kt-row-column-wrap{padding-right:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_77dedf-cc alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column26636_752018-b7 > .kt-inside-inner-col,.kadence-column26636_752018-b7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_752018-b7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_752018-b7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_752018-b7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_752018-b7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_752018-b7{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_752018-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_752018-b7{text-align:left;}.kadence-column26636_752018-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_752018-b7 kb-section-dir-vertical kb-section-sm-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"629\" height=\"401\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-818.png\" alt=\"web-zoom-cursos-empresas-818\" class=\"wp-image-26341\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-818.png 629w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/web-zoom-cursos-empresas-818-300x191.png 300w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n<style>.kadence-column26636_2c73e0-af > .kt-inside-inner-col,.kadence-column26636_2c73e0-af > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_2c73e0-af > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_2c73e0-af > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_2c73e0-af > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_2c73e0-af > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_2c73e0-af{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_2c73e0-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_2c73e0-af > .kt-inside-inner-col{padding-right:20px;padding-left:20px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_2c73e0-af inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_a8241b-f6, .wp-block-kadence-advancedheading.kt-adv-heading26636_a8241b-f6[data-kb-block=\"kb-adv-heading26636_a8241b-f6\"]{font-size:25px;font-weight:bold;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_a8241b-f6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_a8241b-f6[data-kb-block=\"kb-adv-heading26636_a8241b-f6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_a8241b-f6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_a8241b-f6[data-kb-block=\"kb-adv-heading26636_a8241b-f6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_a8241b-f6 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_a8241b-f6\">Per obtenir el t\u00edtol oficial de Cambridge&nbsp;English<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_e070fd-d5, .wp-block-kadence-advancedheading.kt-adv-heading26636_e070fd-d5[data-kb-block=\"kb-adv-heading26636_e070fd-d5\"]{font-size:16px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_e070fd-d5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_e070fd-d5[data-kb-block=\"kb-adv-heading26636_e070fd-d5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_e070fd-d5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_e070fd-d5[data-kb-block=\"kb-adv-heading26636_e070fd-d5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_e070fd-d5 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_e070fd-d5\">Per motivar els alumnes a arribar a un nivell determinat, <strong>oferim l&#8217;opci\u00f3<\/strong> de fer tamb\u00e9 els <strong>ex\u00e0mens oficials Cambridge&nbsp;English<\/strong>, a fi d&#8217;obtenir un certificat oficial com a reconeixement del seu progr\u00e9s (<strong>A2 Key, B1&nbsp;Preliminary, B2&nbsp;First, C1&nbsp;Advanced, C2&nbsp;Proficiency<\/strong>\u2026).<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_398b96-46, .wp-block-kadence-advancedheading.kt-adv-heading26636_398b96-46[data-kb-block=\"kb-adv-heading26636_398b96-46\"]{font-size:16px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_398b96-46 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_398b96-46[data-kb-block=\"kb-adv-heading26636_398b96-46\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_398b96-46 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_398b96-46[data-kb-block=\"kb-adv-heading26636_398b96-46\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading26636_398b96-46 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_398b96-46\">Els ex\u00e0mens oficials s\u00f3n presencials, <strong>per\u00f2 tota la preparaci\u00f3 pot fer-se en online<\/strong>, i tenim una llarga traject\u00f2ria d&#8217;\u00e8xit en la preparaci\u00f3 per a ex\u00e0mens oficials<strong> en tots els nivells<\/strong>.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_170449-a8{margin-bottom:0px;}.kb-row-layout-id26636_170449-a8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_170449-a8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_170449-a8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:900px;margin-left:auto;margin-right:auto;padding-top:70px;padding-bottom:40px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_170449-a8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_170449-a8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_170449-a8 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_170449-a8 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_4da826-c7 > .kt-inside-inner-col,.kadence-column26636_4da826-c7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_4da826-c7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_4da826-c7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_4da826-c7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_4da826-c7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_4da826-c7{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_4da826-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_4da826-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_4da826-c7 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_fda679-26, .wp-block-kadence-advancedheading.kt-adv-heading26636_fda679-26[data-kb-block=\"kb-adv-heading26636_fda679-26\"]{margin-bottom:0px;text-align:center;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_fda679-26 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_fda679-26[data-kb-block=\"kb-adv-heading26636_fda679-26\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_fda679-26 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_fda679-26[data-kb-block=\"kb-adv-heading26636_fda679-26\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_fda679-26 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_fda679-26\"><strong>M\u00e9s de 250 empreses<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_1d84c2-cb, .wp-block-kadence-advancedheading.kt-adv-heading26636_1d84c2-cb[data-kb-block=\"kb-adv-heading26636_1d84c2-cb\"]{margin-bottom:20px;text-align:center;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_1d84c2-cb mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_1d84c2-cb[data-kb-block=\"kb-adv-heading26636_1d84c2-cb\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_1d84c2-cb img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_1d84c2-cb[data-kb-block=\"kb-adv-heading26636_1d84c2-cb\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading26636_1d84c2-cb wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_1d84c2-cb\">ja confien en nosaltres.<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_2ae983-69, .wp-block-kadence-advancedheading.kt-adv-heading26636_2ae983-69[data-kb-block=\"kb-adv-heading26636_2ae983-69\"]{margin-bottom:5px;text-align:center;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_2ae983-69 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_2ae983-69[data-kb-block=\"kb-adv-heading26636_2ae983-69\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_2ae983-69 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_2ae983-69[data-kb-block=\"kb-adv-heading26636_2ae983-69\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading26636_2ae983-69 wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_2ae983-69\"><strong>I aix\u00f2 \u00e9s el que diuen dels nostres cursos:<\/strong><\/h4>\n\n\n<style>.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-svg-testimonial-global-icon{font-size:30px;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-testimonial-rating-wrap .kb-svg-icon-wrap{color:#ffd700;font-size:16px;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-testimonial-grid-wrap{gap:30px;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-blocks-testimonials-inner-wrap .kt-blocks-carousel-init:not(.splide-initialized):not(.tns-slider) .kb-slide-item{display:none;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-blocks-testimonials-inner-wrap .kt-blocks-carousel-init:not(.splide-initialized):not(.tns-slider) .kb-slide-item:nth-child(-n+1){padding-left:30px;display:block;float:left;width:calc(100% \/ 1);}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-blocks-testimonials-inner-wrap .kt-blocks-carousel-init:not(.splide-initialized):not(.tns-slider){margin-left:-30px;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-testimonial-item-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-testimonial-content{color:#333333;font-size:20px;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-testimonial-name{color:#00B8D6;font-size:20px;font-weight:bold;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-testimonial-occupation{color:#00B8D6;font-size:20px;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-testimonial-item-wrap{max-width:600px;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-testimonial-media-inner-wrap{border-top:0px solid;border-right:0px solid;border-bottom:0px solid;border-left:0px solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-svg-testimonial-icon{justify-content:center;align-items:center;}@media all and (max-width: 1024px){.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-blocks-testimonials-inner-wrap .kt-blocks-carousel-init:not(.splide-initialized):not(.tns-slider) .kb-slide-item{display:none;}}@media all and (max-width: 1024px){.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-blocks-testimonials-inner-wrap .kt-blocks-carousel-init:not(.splide-initialized):not(.tns-slider) .kb-slide-item:nth-child(-n+1){padding-left:30px;display:block;float:left;width:calc(100% \/ 1);}}@media all and (max-width: 1024px){.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-blocks-testimonials-inner-wrap .kt-blocks-carousel-init:not(.splide-initialized):not(.tns-slider){margin-left:-30px;}}@media all and (max-width: 1024px){.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-testimonial-media-inner-wrap{border-top:0px solid;border-right:0px solid;border-bottom:0px solid;border-left:0px solid;}}@media all and (max-width: 767px){.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-blocks-carousel .kt-blocks-testimonial-carousel-item{padding-top:px;padding-bottom:px;margin-top:px;margin-bottom:px;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-blocks-testimonials-inner-wrap .kt-blocks-carousel-init:not(.splide-initialized):not(.tns-slider) .kb-slide-item{display:none;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-blocks-testimonials-inner-wrap .kt-blocks-carousel-init:not(.splide-initialized):not(.tns-slider) .kb-slide-item:nth-child(-n+1){display:block;float:left;width:calc(100% \/ 1);padding-left:30px;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-blocks-testimonials-inner-wrap .kt-blocks-carousel-init:not(.splide-initialized):not(.tns-slider){margin-left:-30px;}.kt-blocks-testimonials-wrap26636_fe88d8-97 .kt-testimonial-media-inner-wrap{border-top:0px solid;border-right:0px solid;border-bottom:0px solid;border-left:0px solid;}}<\/style><div class=\"kt-blocks-testimonials-wrap26636_fe88d8-97 kt-testimonial-halign-center kt-testimonial-style-card kt-testimonials-media-on kt-testimonials-icon-off kt-testimonial-columns-1 kt-t-xxl-col-1 kt-t-xl-col-1 kt-t-lg-col-1 kt-t-md-col-1 kt-t-sm-col-1 kt-t-xs-col-1 wp-block-kadence-testimonials\"><div class=\"kt-blocks-testimonials-inner-wrap kt-blocks-carousel kt-carousel-container-dotstyle-dark kt-carousel-container-arrowstyle-blackonlight\"><div class=\"kt-blocks-carousel-init splide kb-gallery-carousel kt-carousel-arrowstyle-blackonlight kt-carousel-dotstyle-dark\" data-columns-xxl=\"1\" data-columns-xl=\"1\" data-columns-md=\"1\" data-columns-sm=\"1\" data-columns-xs=\"1\" data-columns-ss=\"1\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-type=\"loop\" data-slider-arrows=\"true\" data-slider-dots=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"\" data-slider-speed=\"7000\" data-slider-gap=\"30px\" data-slider-gap-tablet=\"30px\" data-slider-gap-mobile=\"30px\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"splide__list\">\n<li class=\"kt-blocks-testimonial-carousel-item kb-slide-item splide__slide\"><div class=\"kt-testimonial-item-wrap kt-testimonial-item-26636_649538-c7 wp-block-kadence-testimonial\"><div class=\"kt-testimonial-text-wrap\"><div class=\"kt-testimonial-media-wrap\"><div class=\"kt-testimonial-media-inner-wrap\"><div class=\"kadence-testimonial-image-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1066\" height=\"359\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-Kohler.png\" class=\"kt-testimonial-image wp-image-26733 size-full\" alt=\"LOGOS TESTIMONIALES Empresas Kohler\" style=\"object-fit: Contain;\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-Kohler.png 1066w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-Kohler-300x101.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-Kohler-1024x345.png 1024w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-Kohler-768x259.png 768w\" sizes=\"auto, (max-width: 1066px) 100vw, 1066px\" \/><\/div><\/div><\/div><div class=\"kt-testimonial-content-wrap\"><blockquote class=\"kt-testimonial-content\">&#8220;<strong>El nivell \u00e9s desafiant i em motiva<\/strong> a estar tota la classe\u00a0concentrat. La professora t\u00e9 un <strong>nivell excel\u00b7lent<\/strong> i cada dia em proposa <strong>vocabulari nou<\/strong> que m&#8217;ajuda a millorar.&#8221;<\/blockquote><\/div><\/div><div class=\"kt-testimonial-meta-wrap\"><div class=\"kt-testimonial-meta-name-wrap\"><div class=\"kt-testimonial-name-wrap\"><div class=\"kt-testimonial-name\">Roberto Exp\u00f3sito<\/div><\/div><div class=\"kt-testimonial-occupation-wrap\"><div class=\"kt-testimonial-occupation\">Kohler<\/div><\/div><\/div><\/div><\/div><\/li>\n\n<li class=\"kt-blocks-testimonial-carousel-item kb-slide-item splide__slide\"><div class=\"kt-testimonial-item-wrap kt-testimonial-item-26636_486cbe-8d wp-block-kadence-testimonial\"><div class=\"kt-testimonial-text-wrap\"><div class=\"kt-testimonial-media-wrap\"><div class=\"kt-testimonial-media-inner-wrap\"><div class=\"kadence-testimonial-image-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1066\" height=\"359\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-NETLINK-Imaging.png\" class=\"kt-testimonial-image wp-image-26735 size-full\" alt=\"LOGOS TESTIMONIALES Empresas NETLINK Imaging\" style=\"object-fit: Contain;\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-NETLINK-Imaging.png 1066w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-NETLINK-Imaging-300x101.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-NETLINK-Imaging-1024x345.png 1024w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-NETLINK-Imaging-768x259.png 768w\" sizes=\"auto, (max-width: 1066px) 100vw, 1066px\" \/><\/div><\/div><\/div><div class=\"kt-testimonial-content-wrap\"><blockquote class=\"kt-testimonial-content\">&#8220;<strong>Classes molt ben preparades<\/strong>. El professor proposa<strong> temes diferents cada setmana <\/strong>que ens permeten adquirir constantment nous coneixements.&#8221;<\/blockquote><\/div><\/div><div class=\"kt-testimonial-meta-wrap\"><div class=\"kt-testimonial-meta-name-wrap\"><div class=\"kt-testimonial-name-wrap\"><div class=\"kt-testimonial-name\">Sonia Carrero Seijas<\/div><\/div><div class=\"kt-testimonial-occupation-wrap\"><div class=\"kt-testimonial-occupation\">Netlink Imaging<\/div><\/div><\/div><\/div><\/div><\/li>\n\n<li class=\"kt-blocks-testimonial-carousel-item kb-slide-item splide__slide\"><div class=\"kt-testimonial-item-wrap kt-testimonial-item-26636_2f0306-56 wp-block-kadence-testimonial\"><div class=\"kt-testimonial-text-wrap\"><div class=\"kt-testimonial-media-wrap\"><div class=\"kt-testimonial-media-inner-wrap\"><div class=\"kadence-testimonial-image-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1066\" height=\"359\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-Brenntag.png\" class=\"kt-testimonial-image wp-image-26729 size-full\" alt=\"LOGOS TESTIMONIALES Empresas Brenntag\" style=\"object-fit: Contain;\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-Brenntag.png 1066w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-Brenntag-300x101.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-Brenntag-1024x345.png 1024w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-Brenntag-768x259.png 768w\" sizes=\"auto, (max-width: 1066px) 100vw, 1066px\" \/><\/div><\/div><\/div><div class=\"kt-testimonial-content-wrap\"><blockquote class=\"kt-testimonial-content\">&#8220;<strong>Content tant amb el professor<\/strong> com <strong>amb la formaci\u00f3<\/strong> per videoconfer\u00e8ncia. M\u2019ofereix <strong>molta flexibilita<\/strong>t i puc encaixar-la <strong>en el meu dia a dia laboral<\/strong>.&#8221;<\/blockquote><\/div><\/div><div class=\"kt-testimonial-meta-wrap\"><div class=\"kt-testimonial-meta-name-wrap\"><div class=\"kt-testimonial-name-wrap\"><div class=\"kt-testimonial-name\">Juan Pablo Felipo Sanjuan<\/div><\/div><div class=\"kt-testimonial-occupation-wrap\"><div class=\"kt-testimonial-occupation\">Brenntag<\/div><\/div><\/div><\/div><\/div><\/li>\n\n<li class=\"kt-blocks-testimonial-carousel-item kb-slide-item splide__slide\"><div class=\"kt-testimonial-item-wrap kt-testimonial-item-26636_dee3bc-7f wp-block-kadence-testimonial\"><div class=\"kt-testimonial-text-wrap\"><div class=\"kt-testimonial-media-wrap\"><div class=\"kt-testimonial-media-inner-wrap\"><div class=\"kadence-testimonial-image-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1066\" height=\"359\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-GJM-Group.png\" class=\"kt-testimonial-image wp-image-26731 size-full\" alt=\"LOGOS TESTIMONIALES Empresas GJM Group\" style=\"object-fit: Contain;\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-GJM-Group.png 1066w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-GJM-Group-300x101.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-GJM-Group-1024x345.png 1024w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/LOGOS-TESTIMONIALES-Empresas-GJM-Group-768x259.png 768w\" sizes=\"auto, (max-width: 1066px) 100vw, 1066px\" \/><\/div><\/div><\/div><div class=\"kt-testimonial-content-wrap\"><blockquote class=\"kt-testimonial-content\">&#8220;<strong>Felicitacions a la meva professora<\/strong> per la seva labor! Agraeixo enormement la <strong>dedicaci\u00f3 i paci\u00e8ncia<\/strong> que mostra durant les classes d&#8217;angl\u00e8s.&#8221;<\/blockquote><\/div><\/div><div class=\"kt-testimonial-meta-wrap\"><div class=\"kt-testimonial-meta-name-wrap\"><div class=\"kt-testimonial-name-wrap\"><div class=\"kt-testimonial-name\">David Garc\u00eda Ord\u00f3\u00f1ez<\/div><\/div><div class=\"kt-testimonial-occupation-wrap\"><div class=\"kt-testimonial-occupation\">GJM Group<\/div><\/div><\/div><\/div><\/div><\/li>\n<\/ul><\/div><\/div><\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_7ca79d-c1{margin-bottom:0px;}.kb-row-layout-id26636_7ca79d-c1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_7ca79d-c1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_7ca79d-c1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:700px;margin-left:auto;margin-right:auto;padding-top:70px;padding-bottom:40px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_7ca79d-c1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_7ca79d-c1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_7ca79d-c1 > .kt-row-column-wrap{padding-right:15px;padding-left:15px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_7ca79d-c1 alignnone has-central-palette-2-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_81d7a0-27 > .kt-inside-inner-col,.kadence-column26636_81d7a0-27 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_81d7a0-27 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_81d7a0-27 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_81d7a0-27 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_81d7a0-27 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_81d7a0-27{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_81d7a0-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_81d7a0-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_81d7a0-27 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_154811-ca, .wp-block-kadence-advancedheading.kt-adv-heading26636_154811-ca[data-kb-block=\"kb-adv-heading26636_154811-ca\"]{margin-bottom:20px;text-align:center;font-size:42px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_154811-ca mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_154811-ca[data-kb-block=\"kb-adv-heading26636_154811-ca\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_154811-ca img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_154811-ca[data-kb-block=\"kb-adv-heading26636_154811-ca\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_154811-ca, .wp-block-kadence-advancedheading.kt-adv-heading26636_154811-ca[data-kb-block=\"kb-adv-heading26636_154811-ca\"]{font-size:40px;}}<\/style>\n<h2 class=\"kt-adv-heading26636_154811-ca wp-block-kadence-advancedheading has-central-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading26636_154811-ca\"><strong>Comencem?<\/strong><\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_878580-7c, .wp-block-kadence-advancedheading.kt-adv-heading26636_878580-7c[data-kb-block=\"kb-adv-heading26636_878580-7c\"]{margin-bottom:5px;text-align:center;font-size:24px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_878580-7c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_878580-7c[data-kb-block=\"kb-adv-heading26636_878580-7c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_878580-7c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_878580-7c[data-kb-block=\"kb-adv-heading26636_878580-7c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading26636_878580-7c[data-kb-block=\"kb-adv-heading26636_878580-7c\"] a, .kt-adv-heading-link26636_878580-7c, .kt-adv-heading-link26636_878580-7c .kt-adv-heading26636_878580-7c[data-kb-block=\"kb-adv-heading26636_878580-7c\"]{color:#003C5A;}.wp-block-kadence-advancedheading.kt-adv-heading26636_878580-7c[data-kb-block=\"kb-adv-heading26636_878580-7c\"] a:hover, .kt-adv-heading-link26636_878580-7c:hover, .kt-adv-heading-link26636_878580-7c:hover .kt-adv-heading26636_878580-7c[data-kb-block=\"kb-adv-heading26636_878580-7c\"]{color:#003C5A;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_878580-7c, .wp-block-kadence-advancedheading.kt-adv-heading26636_878580-7c[data-kb-block=\"kb-adv-heading26636_878580-7c\"]{font-size:20px;}}<\/style>\n<h4 class=\"kt-adv-heading26636_878580-7c wp-block-kadence-advancedheading has-central-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading26636_878580-7c\"><strong><span style=\"text-decoration: underline;\" class=\"ek-underline\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-empreses\/#informacio-empreses\" class=\"ek-link\">Sol\u00b7licita informaci\u00f3 ara<\/a><\/span> i el nostre equip<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_2e6286-79, .wp-block-kadence-advancedheading.kt-adv-heading26636_2e6286-79[data-kb-block=\"kb-adv-heading26636_2e6286-79\"]{margin-bottom:30px;text-align:center;font-size:24px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_2e6286-79 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_2e6286-79[data-kb-block=\"kb-adv-heading26636_2e6286-79\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_2e6286-79 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_2e6286-79[data-kb-block=\"kb-adv-heading26636_2e6286-79\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_2e6286-79, .wp-block-kadence-advancedheading.kt-adv-heading26636_2e6286-79[data-kb-block=\"kb-adv-heading26636_2e6286-79\"]{font-size:20px;}}<\/style>\n<h4 class=\"kt-adv-heading26636_2e6286-79 wp-block-kadence-advancedheading has-central-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading26636_2e6286-79\">contactar\u00e0 amb tu per oferir-te:<\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_b67457-a0:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_b67457-a0 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_b67457-a0 ul.kt-svg-icon-list{grid-row-gap:15px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items26636_b67457-a0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:15px;}.kt-svg-icon-list-items26636_b67457-a0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items26636_b67457-a0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:#FFFFFF;font-size:22px;font-weight:bold;color:#FFFFFF;}@media all and (max-width: 767px){.kt-svg-icon-list-items26636_b67457-a0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items26636_b67457-a0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:17px;}}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items26636_b67457-a0 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-26636_8a9cf7-c5 .kt-svg-icon-list-single{font-size:24px !important;color:#F0504B !important;}.kt-svg-icon-list-item-26636_8a9cf7-c5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_8a9cf7-c5 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Pressupost sense comprom\u00eds <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-1-color\">de contractaci\u00f3.<\/mark><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_96a122-de .kt-svg-icon-list-single{font-size:24px !important;color:#F0504B !important;}.kt-svg-icon-list-item-26636_96a122-de .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_96a122-de kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Valoraci\u00f3 conjunta de les bonificacions&nbsp;Fundae&nbsp;<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-1-color\">que poden aplicar-se a la teva empresa.<\/mark><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-26636_f405aa-a3 .kt-svg-icon-list-single{font-size:24px !important;color:#F0504B !important;}.kt-svg-icon-list-item-26636_f405aa-a3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-26636_f405aa-a3 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Estimaci\u00f3 de l&#8217;estalvi <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-1-color\">en la formaci\u00f3 de la teva empresa.<\/mark><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_395a28-5d{margin-bottom:0px;}.kb-row-layout-id26636_395a28-5d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_395a28-5d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_395a28-5d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1000px;margin-left:auto;margin-right:auto;padding-top:50px;padding-bottom:100px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_395a28-5d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_395a28-5d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_395a28-5d > .kt-row-column-wrap{padding-right:20px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_395a28-5d alignfull has-central-palette-1-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"informacio-empreses\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_5d3023-68 > .kt-inside-inner-col,.kadence-column26636_5d3023-68 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_5d3023-68 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_5d3023-68 > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_5d3023-68 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_5d3023-68 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_5d3023-68{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_5d3023-68 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_5d3023-68 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_5d3023-68 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_6696a7-c5, .wp-block-kadence-advancedheading.kt-adv-heading26636_6696a7-c5[data-kb-block=\"kb-adv-heading26636_6696a7-c5\"]{margin-bottom:10px;text-align:center;font-size:42px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_6696a7-c5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_6696a7-c5[data-kb-block=\"kb-adv-heading26636_6696a7-c5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_6696a7-c5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_6696a7-c5[data-kb-block=\"kb-adv-heading26636_6696a7-c5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 id=\"ancla\" class=\"kt-adv-heading26636_6696a7-c5 wp-block-kadence-advancedheading has-central-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading26636_6696a7-c5\">Sol\u00b7licita informaci\u00f3 per a la teva empresa<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_9a43fa-f5, .wp-block-kadence-advancedheading.kt-adv-heading26636_9a43fa-f5[data-kb-block=\"kb-adv-heading26636_9a43fa-f5\"]{margin-top:0px;margin-bottom:40px;text-align:center;font-size:24px;font-weight:bold;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_9a43fa-f5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_9a43fa-f5[data-kb-block=\"kb-adv-heading26636_9a43fa-f5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_9a43fa-f5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_9a43fa-f5[data-kb-block=\"kb-adv-heading26636_9a43fa-f5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h5 id=\"anclaj\" class=\"kt-adv-heading26636_9a43fa-f5 wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading26636_9a43fa-f5\">I PRESSUPOST SENSE COMPROM\u00cdS.<\/h5>\n\n\n<script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_2' ><form method='post' enctype='multipart\/form-data'  id='gform_2'  action='\/ca\/wp-json\/wp\/v2\/pages\/26636' data-formid='2' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_2' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_2_1\" class=\"gfield gfield--type-html blaue gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h4>Dades de contacte:<\/h4><\/div><div id=\"field_2_3\" class=\"gfield gfield--type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_2_3'>Nom empresa<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Obligatori)<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_2_3' type='text' value='' class='large'    placeholder='Nom empresa*' aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_2_4\" class=\"gfield gfield--type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_2_4'>Persona de contacte<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Obligatori)<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_4' id='input_2_4' type='text' value='' class='large'    placeholder='Persona de contacte*' aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_2_5\" class=\"gfield gfield--type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_2_5'>Web empresa<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Obligatori)<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_5' id='input_2_5' type='text' value='' class='large'    placeholder='Web empresa*' aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_2_9\" class=\"gfield gfield--type-email gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_2_9'>Email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Obligatori)<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_9' id='input_2_9' type='email' value='' class='large'   placeholder='Email*' aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_2_6\" class=\"gfield gfield--type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_2_6'>Tel\u00e8fon<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Obligatori)<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_6' id='input_2_6' type='text' value='' class='large'    placeholder='Tel\u00e8fon*' aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_2_7\" class=\"gfield gfield--type-html gfield--width-half camps gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  >*Camp obligatori.<\/div><div id=\"field_2_10\" class=\"gfield gfield--type-html gfield--width-full blaue gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h4>Cursos que t\u2019interessen::<\/h4><\/div><fieldset id=\"field_2_11\" class=\"gfield gfield--type-checkbox gfield--type-choice idiomas field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >IDIOMES:<\/legend><div class='ginput_container ginput_container_checkbox'><div class='gfield_checkbox ' id='input_2_11'><div class='gchoice gchoice_2_11_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_11.1' type='checkbox'  value='Angl\u00e8s'  id='choice_2_11_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_2_11_1' id='label_2_11_1' class='gform-field-label gform-field-label--type-inline'>Angl\u00e8s<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_2_11_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_11.2' type='checkbox'  value='Alemany'  id='choice_2_11_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_2_11_2' id='label_2_11_2' class='gform-field-label gform-field-label--type-inline'>Alemany<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_2_11_3'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_11.3' type='checkbox'  value='Espanyol'  id='choice_2_11_3'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_2_11_3' id='label_2_11_3' class='gform-field-label gform-field-label--type-inline'>Espanyol<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_2_11_4'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_11.4' type='checkbox'  value='Franc\u00e8s'  id='choice_2_11_4'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_2_11_4' id='label_2_11_4' class='gform-field-label gform-field-label--type-inline'>Franc\u00e8s<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_2_11_5'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_11.5' type='checkbox'  value='Itali\u00e0'  id='choice_2_11_5'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_2_11_5' id='label_2_11_5' class='gform-field-label gform-field-label--type-inline'>Itali\u00e0<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_2_11_6'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_11.6' type='checkbox'  value='Catal\u00e0'  id='choice_2_11_6'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_2_11_6' id='label_2_11_6' class='gform-field-label gform-field-label--type-inline'>Catal\u00e0<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_2_11_7'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_11.7' type='checkbox'  value='Xin\u00e8s'  id='choice_2_11_7'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_2_11_7' id='label_2_11_7' class='gform-field-label gform-field-label--type-inline'>Xin\u00e8s<\/label>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><\/fieldset><fieldset id=\"field_2_12\" class=\"gfield gfield--type-checkbox gfield--type-choice idiomas field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >FORMAT PREFERIT:<\/legend><div class='ginput_container ginput_container_checkbox'><div class='gfield_checkbox ' id='input_2_12'><div class='gchoice gchoice_2_12_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_12.1' type='checkbox'  value='Microsoft Teams'  id='choice_2_12_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_2_12_1' id='label_2_12_1' class='gform-field-label gform-field-label--type-inline'>Microsoft Teams<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_2_12_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_12.2' type='checkbox'  value='Zoom'  id='choice_2_12_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_2_12_2' id='label_2_12_2' class='gform-field-label gform-field-label--type-inline'>Zoom<\/label>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><\/fieldset><div id=\"field_2_20\" class=\"gfield gfield--type-html gfield--width-full espai gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  >&nbsp;<\/div><div id=\"field_2_14\" class=\"gfield gfield--type-text gfield--width-third field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_2_14'>Nombre de persones interessades<\/label><div class='ginput_container ginput_container_text'><input name='input_14' id='input_2_14' type='text' value='' class='large'    placeholder='Nombre de persones interessades'  aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_2_13\" class=\"gfield gfield--type-text gfield--width-third field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_2_13'>Hores setmanals<\/label><div class='ginput_container ginput_container_text'><input name='input_13' id='input_2_13' type='text' value='' class='large'    placeholder='Hores setmanals'  aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_2_27\" class=\"gfield gfield--type-date gfield--input-type-datepicker gfield--datepicker-no-icon gfield--width-third field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_2_27'>Data d&#039;inici<\/label><div class='ginput_container ginput_container_date'>\n                            <input name='input_27' id='input_2_27' type='text' value='' class='datepicker gform-datepicker mdy datepicker_no_icon gdatepicker-no-icon'   placeholder='Data d&#039;inici' aria-describedby=\"input_2_27_date_format\" aria-invalid=\"false\" \/>\n                            <span id='input_2_27_date_format' class='screen-reader-text'>MM slash DD slash YYYY<\/span>\n                        <\/div>\n                        <input type='hidden' id='gforms_calendar_icon_input_2_27' class='gform_hidden' value='https:\/\/zoom.cambridgeschool.com\/wp-content\/plugins\/gravityforms\/images\/datepicker\/datepicker.svg'\/><\/div><div id=\"field_2_16\" class=\"gfield gfield--type-html gfield--width-full blaue gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h4>Ajudes p\u00fabliques:<\/h4><\/div><fieldset id=\"field_2_17\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield--width-third deseo field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >informaci\u00f3 ajudes p\u00fabliques<\/legend><div class='ginput_container ginput_container_checkbox'><div class='gfield_checkbox ' id='input_2_17'><div class='gchoice gchoice_2_17_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_17.1' type='checkbox'  value='Desitjo rebre m\u00e9s informaci\u00f3 de les &lt;u&gt;&lt;span class=&quot;sg-popup-id-26719&quot;&gt;ajudes p\u00fabliques i el seu retorn&lt;\/span&gt;&lt;\/u&gt;'  id='choice_2_17_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_2_17_1' id='label_2_17_1' class='gform-field-label gform-field-label--type-inline'>Desitjo rebre m\u00e9s informaci\u00f3 de les <u><span class=\"sg-popup-id-26719\">ajudes p\u00fabliques i el seu retorn<\/span><\/u><\/label>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><\/fieldset><fieldset id=\"field_2_18\" class=\"gfield gfield--type-radio gfield--type-choice gfield--width-third soy field_sublabel_below gfield--no-description field_description_above field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label' >Soc<\/legend><div class='ginput_container ginput_container_radio'><div class='gfield_radio' id='input_2_18'>\n\t\t\t<div class='gchoice gchoice_2_18_0'>\n\t\t\t\t\t<input class='gfield-choice-input' name='input_18' type='radio' value='PIME'  id='choice_2_18_0' onchange='gformToggleRadioOther( this )'    \/>\n\t\t\t\t\t<label for='choice_2_18_0' id='label_2_18_0' class='gform-field-label gform-field-label--type-inline'>PIME<\/label>\n\t\t\t<\/div>\n\t\t\t<div class='gchoice gchoice_2_18_1'>\n\t\t\t\t\t<input class='gfield-choice-input' name='input_18' type='radio' value='Gran Empresa'  id='choice_2_18_1' onchange='gformToggleRadioOther( this )'    \/>\n\t\t\t\t\t<label for='choice_2_18_1' id='label_2_18_1' class='gform-field-label gform-field-label--type-inline'>Gran Empresa<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><div id=\"field_2_19\" class=\"gfield gfield--type-text gfield--width-third field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_2_19'>Nombre d\u2019empleats<\/label><div class='ginput_container ginput_container_text'><input name='input_19' id='input_2_19' type='text' value='' class='large'    placeholder='Nombre d\u2019empleats'  aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_2_24\" class=\"gfield gfield--type-html gfield--width-full espai gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  >&nbsp;<\/div><div id=\"field_2_22\" class=\"gfield gfield--type-textarea gfield--width-half field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_2_22'>Com ens vas con\u00e8ixer?<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_22' id='input_2_22' class='textarea small'    placeholder='Com ens vas con\u00e8ixer? (OPCIONAL)'  aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><div id=\"field_2_23\" class=\"gfield gfield--type-textarea gfield--width-half field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_2_23'>Comentaris<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_23' id='input_2_23' class='textarea small'    placeholder='Comentaris (OPCIONAL)'  aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><div id=\"field_2_25\" class=\"gfield gfield--type-html gfield--width-full politica gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h4>POL\u00cdTICA DE PRIVACITAT<\/h4>\n<p class=\"pop1\">Responsable: Cambridge Language School, S.L. (\u201cCambridge School\u201d). <a class=\"sg-popup-id-24535\">+ info <\/a><\/p>\n<p class=\"pop1\">Finalitat: Gesti\u00f3 de les sol\u00b7licituds d&#8217;informaci\u00f3 i de l&#8217;enviament de comunicacions comercials. <a class=\"sg-popup-id-24535\">+ info <\/a><\/p><br>\n<p class=\"pop1\"> Legitimaci\u00f3: Consentiment de l&#8217;interessat. <a class=\"sg-popup-id-24535\">+ info <\/a><\/p>\n<p class=\"pop1\">Destinataris: No se cediran dades a tercers, excepte per obligaci\u00f3 legal, i es compartiran amb British Summer Experiences SL en cas de sol\u00b7licitar informaci\u00f3 sobre col\u00f2nies o viatges a l&#8217;estranger. <a class=\"sg-popup-id-24535\">+ info <\/a><\/p>\n<p class=\"pop1\">Drets: Accedir, rectificar, cancel\u00b7lar o suprimir i oposar-se, aix\u00ed com altres drets, com s&#8217;explica en la informaci\u00f3 addicional. <a class=\"sg-popup-id-24535\">+ info <\/a><\/p>\n<p class=\"pop1\">Informaci\u00f3 addicional: Podeu consultar la informaci\u00f3 addicional i detallada sobre Protecci\u00f3 de Dades a la nostra p\u00e0gina web:  <a class=\"sg-popup-id-24535\">pol\u00edtica de privacitat<\/a><\/p><\/div><fieldset id=\"field_2_26\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield--width-two-thirds acepto gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Acceptaci\u00f3 pol\u00edtica<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Obligatori)<\/span><\/span><\/legend><div class='ginput_container ginput_container_checkbox'><div class='gfield_checkbox ' id='input_2_26'><div class='gchoice gchoice_2_26_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_26.1' type='checkbox'  value='Accepto el tractament de les meves dades personals de conformitat amb la Pol\u00edtica de Privacitat.'  id='choice_2_26_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_2_26_1' id='label_2_26_1' class='gform-field-label gform-field-label--type-inline'>Accepto el tractament de les meves dades personals de conformitat amb la Pol\u00edtica de Privacitat.<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_2_26_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_26.2' type='checkbox'  value='Accepto rebre peri\u00f2dicament ofertes i novetats dels productes i serveis en el meu e-mail.'  id='choice_2_26_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_2_26_2' id='label_2_26_2' class='gform-field-label gform-field-label--type-inline'>Accepto rebre peri\u00f2dicament ofertes i novetats dels productes i serveis en el meu e-mail.<\/label>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><\/fieldset><div id=\"field_submit\" class=\"gfield gfield--type-submit gfield--width-third field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  data-field-class=\"gform_editor_submit_container\" data-field-position=\"inline\" ><input type='submit' id='gform_submit_button_2' class='gform-button gform-button--white  button gform-button--width-full' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Enviar'  \/><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'>  \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_2' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_2' id='gform_theme_2' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_2' id='gform_style_settings_2' value='{&quot;inputPrimaryColor&quot;:&quot;#204ce5&quot;}' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_2' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='2' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='EUR' value='NZZwXqV\/ppTH\/8KHkGOx8xMtJ1RMrMOOQtmOdSpWotdYKTkpjLf4UAJ\/sOuQAIHDd6avYgiuoHdgkmoBeaOinBbWL44udWimRvRN\/LFzECEmNwI=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_2' value='WyJ7XCIxOFwiOltcImIzYTk3MmQxNTQyNTJmNmE0NjBlN2U5YzYxM2Q1MjcyXCIsXCI3OWUwN2RjZjE2ZjI3MzhiMTExZWQ4YzY4ZTBiNDM3N1wiXX0iLCI4NzUwZGViMzJiNWQwOWU5NDEzZTRjOTQ4NzA2NmU4OCJd' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_2' id='gform_target_page_number_2' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_2' id='gform_source_page_number_2' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"211\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><\/form>\n                        <\/div><script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 2, 'https:\/\/zoom.cambridgeschool.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_2').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_2');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_2').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_2').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_2').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_2').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_2').val();gformInitSpinner( 2, 'https:\/\/zoom.cambridgeschool.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [2, current_page]);window['gf_submitting_2'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_2').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [2]);window['gf_submitting_2'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_2').text());}else{jQuery('#gform_2').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"2\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_2\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_2\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_2\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 2, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_47290f-09{margin-bottom:0px;}.kb-row-layout-id26636_47290f-09 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_47290f-09 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_47290f-09 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1000px;margin-left:auto;margin-right:auto;padding-top:50px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_47290f-09 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_47290f-09 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_47290f-09 > .kt-row-column-wrap{padding-right:20px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_47290f-09 alignnone has-central-palette-2-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_6cfff0-de > .kt-inside-inner-col,.kadence-column26636_6cfff0-de > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_6cfff0-de > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_6cfff0-de > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_6cfff0-de > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_6cfff0-de > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_6cfff0-de{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_6cfff0-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_6cfff0-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_6cfff0-de inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading26636_99fc75-2d, .wp-block-kadence-advancedheading.kt-adv-heading26636_99fc75-2d[data-kb-block=\"kb-adv-heading26636_99fc75-2d\"]{margin-bottom:0px;text-align:center;font-size:36px;font-weight:600;font-style:normal;font-family:'Open Sans';letter-spacing:-0.3px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_99fc75-2d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_99fc75-2d[data-kb-block=\"kb-adv-heading26636_99fc75-2d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_99fc75-2d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_99fc75-2d[data-kb-block=\"kb-adv-heading26636_99fc75-2d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_99fc75-2d, .wp-block-kadence-advancedheading.kt-adv-heading26636_99fc75-2d[data-kb-block=\"kb-adv-heading26636_99fc75-2d\"]{font-size:18px;}}<\/style>\n<h4 class=\"kt-adv-heading26636_99fc75-2d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading26636_99fc75-2d\">O si ho prefereixes, truca\u2019ns al tel\u00e8fon<\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading26636_76af9f-b5, .wp-block-kadence-advancedheading.kt-adv-heading26636_76af9f-b5[data-kb-block=\"kb-adv-heading26636_76af9f-b5\"]{text-align:center;font-size:100px;font-weight:bold;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading26636_76af9f-b5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading26636_76af9f-b5[data-kb-block=\"kb-adv-heading26636_76af9f-b5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading26636_76af9f-b5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading26636_76af9f-b5[data-kb-block=\"kb-adv-heading26636_76af9f-b5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading26636_76af9f-b5, .wp-block-kadence-advancedheading.kt-adv-heading26636_76af9f-b5[data-kb-block=\"kb-adv-heading26636_76af9f-b5\"]{font-size:50px;}}<\/style>\n<h2 class=\"kt-adv-heading26636_76af9f-b5 color-blanc wp-block-kadence-advancedheading has-central-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading26636_76af9f-b5\"><span class=\"ugb-highlight\" style=\"color: #FFFFFF;\"><a class=\"ek-link\" href=\"tel:+34936550558\">93 870 20 01<\/a><\/span><\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id26636_17d4ca-eb{margin-bottom:0px;}.kb-row-layout-id26636_17d4ca-eb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id26636_17d4ca-eb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id26636_17d4ca-eb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);min-height:73px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id26636_17d4ca-eb{background-color:#f0504b;}.kb-row-layout-id26636_17d4ca-eb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id26636_17d4ca-eb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id26636_17d4ca-eb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id26636_17d4ca-eb alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column26636_cdd8f6-1a > .kt-inside-inner-col,.kadence-column26636_cdd8f6-1a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column26636_cdd8f6-1a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column26636_cdd8f6-1a > .kt-inside-inner-col{flex-direction:column;}.kadence-column26636_cdd8f6-1a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column26636_cdd8f6-1a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column26636_cdd8f6-1a{position:relative;}@media all and (max-width: 1024px){.kadence-column26636_cdd8f6-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column26636_cdd8f6-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column26636_cdd8f6-1a inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id25074_eed2e0-14{margin-bottom:0px;}.kb-row-layout-id25074_eed2e0-14 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id25074_eed2e0-14 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id25074_eed2e0-14 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-lg, 4rem);max-width:1200px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);}.kb-row-layout-id25074_eed2e0-14 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id25074_eed2e0-14 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id25074_eed2e0-14 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id25074_eed2e0-14 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id25074_eed2e0-14 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 767px){.kb-row-layout-id25074_eed2e0-14 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:40px;padding-right:20px;padding-bottom:10px;padding-left:20px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id25074_eed2e0-14 > .kt-row-column-wrap > *:nth-child(3n+1 of *:not(style)){grid-column:1 \/ -1;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id25074_eed2e0-14 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-first-row kt-row-valign-middle\">\n<style>.kadence-column25074_786f18-5e > .kt-inside-inner-col{display:flex;}.kadence-column25074_786f18-5e > .kt-inside-inner-col,.kadence-column25074_786f18-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25074_786f18-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25074_786f18-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column25074_786f18-5e > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column25074_786f18-5e > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column25074_786f18-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column25074_786f18-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_786f18-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_786f18-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column25074_786f18-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25074_786f18-5e{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column25074_786f18-5e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_786f18-5e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_786f18-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column25074_786f18-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column25074_786f18-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_786f18-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_786f18-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column25074_786f18-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25074_786f18-5e inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-image25074_7ddc74-a0.kb-image-is-ratio-size, .kb-image25074_7ddc74-a0 .kb-image-is-ratio-size{max-width:240px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image25074_7ddc74-a0.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image25074_7ddc74-a0 .kb-image-is-ratio-size{align-self:unset;}.kb-image25074_7ddc74-a0{max-width:240px;}.image-is-svg.kb-image25074_7ddc74-a0{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image25074_7ddc74-a0 img{width:100%;}.kb-image25074_7ddc74-a0 .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 767px){.kb-image25074_7ddc74-a0.kb-image-is-ratio-size, .kb-image25074_7ddc74-a0 .kb-image-is-ratio-size{max-width:370px;width:100%;}.kb-image25074_7ddc74-a0{max-width:370px;}}<\/style>\n<figure class=\"wp-block-kadence-image kb-image25074_7ddc74-a0 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"108\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Logos-cambridge-zoom-1.png\" alt=\"Cambridge School\" class=\"kb-img wp-image-23902\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Logos-cambridge-zoom-1.png 370w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Logos-cambridge-zoom-1-300x88.png 300w\" sizes=\"auto, (max-width: 370px) 100vw, 370px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column25074_a9a004-37 > .kt-inside-inner-col{display:flex;}.kadence-column25074_a9a004-37 > .kt-inside-inner-col,.kadence-column25074_a9a004-37 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25074_a9a004-37 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25074_a9a004-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column25074_a9a004-37 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column25074_a9a004-37 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column25074_a9a004-37 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column25074_a9a004-37{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_a9a004-37{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_a9a004-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column25074_a9a004-37 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25074_a9a004-37{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column25074_a9a004-37{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_a9a004-37{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_a9a004-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column25074_a9a004-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column25074_a9a004-37{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_a9a004-37{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_a9a004-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column25074_a9a004-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25074_a9a004-37 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-image25074_ec1266-e8.kb-image-is-ratio-size, .kb-image25074_ec1266-e8 .kb-image-is-ratio-size{max-width:200px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image25074_ec1266-e8.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image25074_ec1266-e8 .kb-image-is-ratio-size{align-self:unset;}.kb-image25074_ec1266-e8{max-width:200px;}.image-is-svg.kb-image25074_ec1266-e8{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image25074_ec1266-e8 img{width:100%;}.kb-image25074_ec1266-e8 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image25074_ec1266-e8\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"252\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cambridge_English_Authorised_Exam_Centre.jpg\" alt=\"Cambridge English Authorised Exam Centre\" class=\"kb-img wp-image-28771\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cambridge_English_Authorised_Exam_Centre.jpg 500w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cambridge_English_Authorised_Exam_Centre-300x151.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col{display:flex;}.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col,.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column25074_f76d6d-c8{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_f76d6d-c8{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25074_f76d6d-c8{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column25074_f76d6d-c8{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_f76d6d-c8{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column25074_f76d6d-c8{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_f76d6d-c8{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column25074_f76d6d-c8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25074_f76d6d-c8 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kb-image25074_3f94a5-a7.kb-image-is-ratio-size, .kb-image25074_3f94a5-a7 .kb-image-is-ratio-size{max-width:200px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image25074_3f94a5-a7.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image25074_3f94a5-a7 .kb-image-is-ratio-size{align-self:unset;}.kb-image25074_3f94a5-a7{max-width:200px;}.image-is-svg.kb-image25074_3f94a5-a7{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image25074_3f94a5-a7 img{width:100%;}.kb-image25074_3f94a5-a7 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image25074_3f94a5-a7\"><img loading=\"lazy\" decoding=\"async\" width=\"519\" height=\"288\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/CEQ_Prep_2025-26.png\" alt=\"Ceq Prep 2025 26\" class=\"kb-img wp-image-28512\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/CEQ_Prep_2025-26.png 519w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/CEQ_Prep_2025-26-300x166.png 300w\" sizes=\"auto, (max-width: 519px) 100vw, 519px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id25074_aaa89b-32{margin-bottom:0px;}.kb-row-layout-id25074_aaa89b-32 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id25074_aaa89b-32 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id25074_aaa89b-32 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1240px;margin-left:auto;margin-right:auto;padding-top:40px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id25074_aaa89b-32 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id25074_aaa89b-32 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id25074_aaa89b-32 > .kt-row-column-wrap{padding-right:20px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id25074_aaa89b-32 alignnone has-central-palette-5-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column25074_8e2e14-37 > .kt-inside-inner-col,.kadence-column25074_8e2e14-37 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25074_8e2e14-37 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25074_8e2e14-37 > .kt-inside-inner-col{flex-direction:column;}.kadence-column25074_8e2e14-37 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column25074_8e2e14-37 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25074_8e2e14-37{position:relative;}@media all and (max-width: 1024px){.kadence-column25074_8e2e14-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column25074_8e2e14-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25074_8e2e14-37 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id25074_1b9d16-e0{margin-bottom:0px;}.kb-row-layout-id25074_1b9d16-e0 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id25074_1b9d16-e0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id25074_1b9d16-e0 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(6, minmax(0, 1fr));}.kb-row-layout-id25074_1b9d16-e0 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id25074_1b9d16-e0 > .kt-row-column-wrap{grid-template-columns:repeat(6, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id25074_1b9d16-e0 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id25074_1b9d16-e0 alignnone peu wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-6-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column25074_dbb495-60 > .kt-inside-inner-col,.kadence-column25074_dbb495-60 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25074_dbb495-60 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25074_dbb495-60 > .kt-inside-inner-col{flex-direction:column;}.kadence-column25074_dbb495-60 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column25074_dbb495-60 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25074_dbb495-60{position:relative;}@media all and (max-width: 1024px){.kadence-column25074_dbb495-60 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column25074_dbb495-60 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25074_dbb495-60 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading25074_0c2055-06, .wp-block-kadence-advancedheading.kt-adv-heading25074_0c2055-06[data-kb-block=\"kb-adv-heading25074_0c2055-06\"]{margin-bottom:20px;font-size:14px;font-weight:bold;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading25074_0c2055-06 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading25074_0c2055-06[data-kb-block=\"kb-adv-heading25074_0c2055-06\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading25074_0c2055-06 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading25074_0c2055-06[data-kb-block=\"kb-adv-heading25074_0c2055-06\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading25074_0c2055-06 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading25074_0c2055-06\"><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">CURSOS ADULTS<\/span><\/h3>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_48dddb-ca:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_48dddb-ca ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_48dddb-ca ul.kt-svg-icon-list{grid-row-gap:6px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_48dddb-ca ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:3px;}.kt-svg-icon-list-items25074_48dddb-ca ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items25074_48dddb-ca ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:#FFFFFF;font-size:13px;color:#FFFFFF;}@media all and (max-width: 767px){.kt-svg-icon-list-items25074_48dddb-ca ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items25074_48dddb-ca ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:11px;}}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items25074_48dddb-ca kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-25074_3ce984-e3 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_3ce984-e3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_3ce984-e3 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-dangles-online-per-adults\/#adultos-anual\" class=\"ek-link\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">CURS ANUAL<\/span><\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_c8ea27-f6 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_c8ea27-f6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_c8ea27-f6 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-dangles-online-per-adults\/#adultos-conversa\" class=\"ek-link\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">CURS DE CONVERSA<\/span><\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_3c2b4b-37 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_3c2b4b-37 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_3c2b4b-37 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a class=\"ek-link\" href=\"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-dangles-online-per-adults\/#adultos-examenes\"><span class=\"ek-underline\" style=\"text-decoration: underline;\">CURSOS DE T\u00c8CNIQUES EXAMEN OFICIAL B2 I C1<\/span><\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_50aaff-e6 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_50aaff-e6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_50aaff-e6 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-dangles-online-per-adults\/#adultos-particulares\" class=\"ek-link\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">CLASSES PARTICULARS<\/span><\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_0e6154-55 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_0e6154-55 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_0e6154-55 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-dangles-online-per-adults\/#adultos-empresas\" class=\"ek-link\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">EMPRESES<\/span><\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_f0b8fe-68 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_f0b8fe-68 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_f0b8fe-68 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-dangles-online-per-adults\/#adultos-verano\" class=\"ek-link\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">CURSOS D&#8217;ESTIU<\/span><\/a><\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-25074_f74919-24 .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-25074_f74919-24 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-25074_f74919-24\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<p class=\"eplus-SbhHyt\"><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column25074_47954a-05 > .kt-inside-inner-col,.kadence-column25074_47954a-05 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25074_47954a-05 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25074_47954a-05 > .kt-inside-inner-col{flex-direction:column;}.kadence-column25074_47954a-05 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column25074_47954a-05 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25074_47954a-05{position:relative;}@media all and (max-width: 1024px){.kadence-column25074_47954a-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column25074_47954a-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25074_47954a-05 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading25074_177989-3b, .wp-block-kadence-advancedheading.kt-adv-heading25074_177989-3b[data-kb-block=\"kb-adv-heading25074_177989-3b\"]{margin-top:0px;margin-bottom:0px;font-size:14px;font-weight:bold;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading25074_177989-3b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading25074_177989-3b[data-kb-block=\"kb-adv-heading25074_177989-3b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading25074_177989-3b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading25074_177989-3b[data-kb-block=\"kb-adv-heading25074_177989-3b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading25074_177989-3b wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading25074_177989-3b\"><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">CURSOS JOVES<\/span><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading25074_b1cbce-df, .wp-block-kadence-advancedheading.kt-adv-heading25074_b1cbce-df[data-kb-block=\"kb-adv-heading25074_b1cbce-df\"]{margin-top:0px;font-size:14px;font-weight:bold;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading25074_b1cbce-df mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading25074_b1cbce-df[data-kb-block=\"kb-adv-heading25074_b1cbce-df\"] mark.kt-highlight{font-style:normal;color:#FFFFFF;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading25074_b1cbce-df img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading25074_b1cbce-df[data-kb-block=\"kb-adv-heading25074_b1cbce-df\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading25074_b1cbce-df wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading25074_b1cbce-df\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-central-palette-7-color\">(10-17 ANYS)<\/mark><\/h3>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_41f785-23:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_41f785-23 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_41f785-23 ul.kt-svg-icon-list{grid-row-gap:6px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_41f785-23 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:3px;}.kt-svg-icon-list-items25074_41f785-23 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items25074_41f785-23 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:#FFFFFF;font-size:13px;color:#FFFFFF;}@media all and (max-width: 767px){.kt-svg-icon-list-items25074_41f785-23 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items25074_41f785-23 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:11px;}}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items25074_41f785-23 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-25074_9a40ab-60 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_9a40ab-60 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_9a40ab-60 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/#jovenes-anual\" class=\"ek-link\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">CURS ANUAL<\/span><\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_8526da-28 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_8526da-28 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_8526da-28 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a class=\"ek-link\" href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/#jovenes-examenes\"><span class=\"ek-underline\" style=\"text-decoration: underline;\">CURSOS DE T\u00c8CNIQUES EXAMEN OFICIAL B2 I C1<\/span><\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_369b70-d6 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_369b70-d6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_369b70-d6 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/#jovenes-particulares\" class=\"ek-link\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">PARTICULARS<\/span><\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_6d5f99-0c .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_6d5f99-0c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_6d5f99-0c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/#jovenes-verano\" class=\"ek-link\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">CURSOS D&#8217;ESTIU<\/span><\/a><\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-25074_ddcb11-b9 .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-25074_ddcb11-b9 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-25074_ddcb11-b9\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<p class=\"eplus-32tr6g\"><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column25074_3c4a9d-76 > .kt-inside-inner-col,.kadence-column25074_3c4a9d-76 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25074_3c4a9d-76 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25074_3c4a9d-76 > .kt-inside-inner-col{flex-direction:column;}.kadence-column25074_3c4a9d-76 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column25074_3c4a9d-76 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25074_3c4a9d-76{position:relative;}@media all and (max-width: 1024px){.kadence-column25074_3c4a9d-76 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column25074_3c4a9d-76 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25074_3c4a9d-76\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading25074_7a22eb-64, .wp-block-kadence-advancedheading.kt-adv-heading25074_7a22eb-64[data-kb-block=\"kb-adv-heading25074_7a22eb-64\"]{margin-bottom:20px;font-size:14px;font-weight:bold;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading25074_7a22eb-64 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading25074_7a22eb-64[data-kb-block=\"kb-adv-heading25074_7a22eb-64\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading25074_7a22eb-64 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading25074_7a22eb-64[data-kb-block=\"kb-adv-heading25074_7a22eb-64\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading25074_7a22eb-64 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading25074_7a22eb-64\"><span class=\"ugb-highlight\" style=\"color: #FFFFFF;\">CURSOS EMPRESA<\/span><\/h3>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_7b8e68-26:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_7b8e68-26 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_7b8e68-26 ul.kt-svg-icon-list{grid-row-gap:6px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_7b8e68-26 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:3px;}.kt-svg-icon-list-items25074_7b8e68-26 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items25074_7b8e68-26 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:#FFFFFF;font-size:13px;color:#FFFFFF;}@media all and (max-width: 767px){.kt-svg-icon-list-items25074_7b8e68-26 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items25074_7b8e68-26 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:11px;}}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items25074_7b8e68-26 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-25074_870aa4-6a .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_870aa4-6a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_870aa4-6a kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><span style=\"text-decoration: underline;\" class=\"ek-underline\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-empreses\/#cursos-empreses-1\" class=\"ek-link\">PLANS ANGL\u00c8S PER A EMPRESES<\/a><\/span><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_0aa953-e4 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_0aa953-e4 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_0aa953-e4 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-empreses\/#cursos-empreses-2\" class=\"ek-link\">TIPUS DE CURSOS<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_68bfeb-c2 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_68bfeb-c2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_68bfeb-c2 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-empreses\/#cursos-empreses-3\" class=\"ek-link\">BONIFICACIONS FUNDAE<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_9249af-55 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_9249af-55 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_9249af-55 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-empreses\/#pla-seguiment\" class=\"ek-link\">PLA DE SEGUIMENT<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_081139-7b .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_081139-7b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_081139-7b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"http:\/\/href=&quot;https:\/\/zoom.cambridgeschool.com\/ca\/cursos-empreses\/#cursos-empreses-4\" class=\"ek-link\">EX\u00c0MENS OFICIALS CAMBRIDGE ENGLISH<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_2819a6-99 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_2819a6-99 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_2819a6-99 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-empreses\/#informacio-empreses\" class=\"ek-link\">SOL\u00b7LICITUD<\/a><\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-25074_f21f60-01 .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-25074_f21f60-01 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-25074_f21f60-01\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column25074_51cb2f-d2 > .kt-inside-inner-col,.kadence-column25074_51cb2f-d2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25074_51cb2f-d2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25074_51cb2f-d2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column25074_51cb2f-d2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column25074_51cb2f-d2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25074_51cb2f-d2{position:relative;}@media all and (max-width: 1024px){.kadence-column25074_51cb2f-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column25074_51cb2f-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25074_51cb2f-d2 inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading25074_c4a986-a9, .wp-block-kadence-advancedheading.kt-adv-heading25074_c4a986-a9[data-kb-block=\"kb-adv-heading25074_c4a986-a9\"]{margin-bottom:20px;font-size:14px;font-weight:bold;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading25074_c4a986-a9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading25074_c4a986-a9[data-kb-block=\"kb-adv-heading25074_c4a986-a9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading25074_c4a986-a9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading25074_c4a986-a9[data-kb-block=\"kb-adv-heading25074_c4a986-a9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading25074_c4a986-a9 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading25074_c4a986-a9\"><span class=\"ugb-highlight\" style=\"color: #FFFFFF;\">Certifica l&#8217;angl\u00e8s<\/span><\/h3>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_9694d9-3c:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_9694d9-3c ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_9694d9-3c ul.kt-svg-icon-list{grid-row-gap:6px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_9694d9-3c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:3px;}.kt-svg-icon-list-items25074_9694d9-3c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items25074_9694d9-3c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:#FFFFFF;font-size:13px;color:#FFFFFF;}@media all and (max-width: 767px){.kt-svg-icon-list-items25074_9694d9-3c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items25074_9694d9-3c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:11px;}}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items25074_9694d9-3c kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-25074_cdf908-5c .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_cdf908-5c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_cdf908-5c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/nivell-plans-i-examens\/#centre-autoritzat\" title=\"\">CENTRE EXAMINADOR AUTORITZAT CAMBRIDGE<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_2f1228-5b .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_2f1228-5b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_2f1228-5b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/nivell-plans-i-examens\/#examen-oficial\" title=\"\"><span class=\"ek-underline\" style=\"text-decoration: underline;\">FER L&#8217;EXAMEN OFICIAL A&nbsp;ESPANYA<\/span><\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_470b77-13 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_470b77-13 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_470b77-13 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/nivell-plans-i-examens\/#guia\" title=\"\">GUIA PAS A PAS<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_f5a630-14 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_f5a630-14 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_f5a630-14 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/nivell-plans-i-examens\/#cursos-preparacio\" title=\"\">CURSOS PREPARACI\u00d3 D&#8217;EXAMEN<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_d3295e-88 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_d3295e-88 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_d3295e-88 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/nivell-plans-i-examens\/#acrediten\" title=\"\">QU\u00c8 ACREDITEN ELS&nbsp;CERTIFICATS OFICIALS<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_108a31-79 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_108a31-79 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_108a31-79 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/nivell-plans-i-examens\/#plans\" title=\"\">PLANS I&nbsp;OBJECTIUS PERSONALS<\/a><\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-25074_395de3-aa .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-25074_395de3-aa .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-25074_395de3-aa\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column25074_fc7e44-af > .kt-inside-inner-col,.kadence-column25074_fc7e44-af > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25074_fc7e44-af > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25074_fc7e44-af > .kt-inside-inner-col{flex-direction:column;}.kadence-column25074_fc7e44-af > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column25074_fc7e44-af > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25074_fc7e44-af{position:relative;}@media all and (max-width: 1024px){.kadence-column25074_fc7e44-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column25074_fc7e44-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25074_fc7e44-af inner-column-5\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading25074_56cf6a-a9, .wp-block-kadence-advancedheading.kt-adv-heading25074_56cf6a-a9[data-kb-block=\"kb-adv-heading25074_56cf6a-a9\"]{font-size:14px;font-weight:bold;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading25074_56cf6a-a9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading25074_56cf6a-a9[data-kb-block=\"kb-adv-heading25074_56cf6a-a9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading25074_56cf6a-a9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading25074_56cf6a-a9[data-kb-block=\"kb-adv-heading25074_56cf6a-a9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading25074_56cf6a-a9 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading25074_56cf6a-a9\"><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">FAQS SOBRE CURSOS<\/span><\/h3>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_fd3a6d-f7:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_fd3a6d-f7 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_fd3a6d-f7 ul.kt-svg-icon-list{grid-row-gap:6px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_fd3a6d-f7 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:3px;}.kt-svg-icon-list-items25074_fd3a6d-f7 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items25074_fd3a6d-f7 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:#FFFFFF;font-size:13px;color:#FFFFFF;}@media all and (max-width: 767px){.kt-svg-icon-list-items25074_fd3a6d-f7 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items25074_fd3a6d-f7 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:11px;}}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items25074_fd3a6d-f7 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-25074_e0211c-b8 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_e0211c-b8 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_e0211c-b8 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/faqs\/#calendari\" class=\"ek-link\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">CALENDARI<\/span><\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_97e893-23 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_97e893-23 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_97e893-23 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/faqs\/#llibres\" class=\"ek-link\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">LLIBRES<\/span><\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_a36094-c3 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_a36094-c3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_a36094-c3 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/faqs\/#certificat\" class=\"ek-link\">CERTIFICATS DELS CURSOS&nbsp;<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_d82db8-59 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_d82db8-59 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_d82db8-59 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/faqs\/#conexio\" class=\"ek-link\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">CONNEXI\u00d3 I ACC\u00c9S A CLASSE<\/span><\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_c4c625-b3 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_c4c625-b3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_c4c625-b3 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/faqs\/#preguntes\" class=\"ek-link\">ALTRES<\/a><\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-25074_26899b-15 .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-25074_26899b-15 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-25074_26899b-15\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column25074_9f5dcf-83 > .kt-inside-inner-col,.kadence-column25074_9f5dcf-83 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25074_9f5dcf-83 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25074_9f5dcf-83 > .kt-inside-inner-col{flex-direction:column;}.kadence-column25074_9f5dcf-83 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column25074_9f5dcf-83 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25074_9f5dcf-83{position:relative;}@media all and (max-width: 1024px){.kadence-column25074_9f5dcf-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column25074_9f5dcf-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25074_9f5dcf-83 inner-column-6\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading25074_adb762-12, .wp-block-kadence-advancedheading.kt-adv-heading25074_adb762-12[data-kb-block=\"kb-adv-heading25074_adb762-12\"]{font-size:14px;font-weight:bold;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading25074_adb762-12 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading25074_adb762-12[data-kb-block=\"kb-adv-heading25074_adb762-12\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading25074_adb762-12 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading25074_adb762-12[data-kb-block=\"kb-adv-heading25074_adb762-12\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading25074_adb762-12 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading25074_adb762-12\"><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">SOBRE NOSALTRES<\/span><\/h3>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_b6436a-76:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_b6436a-76 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_b6436a-76 ul.kt-svg-icon-list{grid-row-gap:6px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items25074_b6436a-76 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:3px;}.kt-svg-icon-list-items25074_b6436a-76 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items25074_b6436a-76 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:#FFFFFF;font-size:13px;color:#FFFFFF;}@media all and (max-width: 767px){.kt-svg-icon-list-items25074_b6436a-76 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items25074_b6436a-76 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:11px;}}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items25074_b6436a-76 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-25074_0f1e09-7b .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_0f1e09-7b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_0f1e09-7b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/sobre-nosaltres\/\" class=\"ek-link\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">QUI SOM<\/span><\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-25074_a99322-18 .kt-svg-icon-list-single{font-size:12px !important;}.kt-svg-icon-list-item-25074_a99322-18 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-25074_a99322-18 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/sobre-nosaltres\/#professors\" class=\"ek-link\"><span style=\"text-decoration: underline;\" class=\"ek-underline\">PROFESSORS<\/span><\/a><\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-25074_b85fce-25 .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-25074_b85fce-25 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-25074_b85fce-25\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id25074_a65ad7-f8{margin-bottom:0px;}.kb-row-layout-id25074_a65ad7-f8 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id25074_a65ad7-f8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id25074_a65ad7-f8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:25px;padding-bottom:0px;grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id25074_a65ad7-f8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id25074_a65ad7-f8 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id25074_a65ad7-f8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id25074_a65ad7-f8 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column25074_6aa8f8-8f > .kt-inside-inner-col,.kadence-column25074_6aa8f8-8f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25074_6aa8f8-8f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25074_6aa8f8-8f > .kt-inside-inner-col{flex-direction:column;}.kadence-column25074_6aa8f8-8f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column25074_6aa8f8-8f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25074_6aa8f8-8f{position:relative;}@media all and (max-width: 1024px){.kadence-column25074_6aa8f8-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column25074_6aa8f8-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25074_6aa8f8-8f inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading25074_f0474b-8b, .wp-block-kadence-advancedheading.kt-adv-heading25074_f0474b-8b[data-kb-block=\"kb-adv-heading25074_f0474b-8b\"]{margin-bottom:5px;text-align:left;font-size:14px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading25074_f0474b-8b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading25074_f0474b-8b[data-kb-block=\"kb-adv-heading25074_f0474b-8b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading25074_f0474b-8b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading25074_f0474b-8b[data-kb-block=\"kb-adv-heading25074_f0474b-8b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading25074_f0474b-8b wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading25074_f0474b-8b\"><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">Seu de Cambridge School: Pla\u00e7a Porxada, 39 \u00b7 08401 \u00b7 Granollers \u00b7 Barcelona \u00b7 Espa\u00f1a<\/span><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading25074_473868-ae, .wp-block-kadence-advancedheading.kt-adv-heading25074_473868-ae[data-kb-block=\"kb-adv-heading25074_473868-ae\"]{margin-top:0px;font-size:14px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading25074_473868-ae mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading25074_473868-ae[data-kb-block=\"kb-adv-heading25074_473868-ae\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading25074_473868-ae img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading25074_473868-ae[data-kb-block=\"kb-adv-heading25074_473868-ae\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading25074_473868-ae wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading25074_473868-ae\"><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">Copyright \u00a9 2023. Cambridge School \u00b7 Tots els drets reservats.<br><\/span><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column25074_f2c623-f9 > .kt-inside-inner-col,.kadence-column25074_f2c623-f9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25074_f2c623-f9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25074_f2c623-f9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column25074_f2c623-f9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column25074_f2c623-f9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25074_f2c623-f9{position:relative;}@media all and (max-width: 1024px){.kadence-column25074_f2c623-f9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column25074_f2c623-f9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25074_f2c623-f9 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>#kt-modal25074_bd8a9a-ea .kt-blocks-modal-link{color:#FFFFFF;background:transparent;border-color:#212327;border-radius:0px;font-size:14px;line-height:20px;border-width:0px 0px 0px 0px;padding:4px 8px 4px 8px;margin:0px 0px 0px 0px;}#kt-modal25074_bd8a9a-ea .kt-blocks-modal-link:hover, #kt-modal25074_bd8a9a-ea .kt-blocks-modal-link:focus{border-color:#FFFFFF;}#kt-modal25074_bd8a9a-ea .kt-modal-overlay, #kt-target-modal25074_bd8a9a-ea .kt-modal-overlay, .kb-modal-content25074_bd8a9a-ea .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal25074_bd8a9a-ea .kt-modal-overlay, #kt-target-modal25074_bd8a9a-ea .kt-modal-overlay, .kb-modal-content25074_bd8a9a-ea .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal25074_bd8a9a-ea .kt-modal-container, #kt-target-modal25074_bd8a9a-ea .kt-modal-container, .kb-modal-content25074_bd8a9a-ea .kt-modal-container{width:80%;max-width:800px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal25074_bd8a9a-ea .kt-modal-container, #kt-target-modal25074_bd8a9a-ea .kt-modal-container, .kb-modal-content25074_bd8a9a-ea .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal25074_bd8a9a-ea .kt-modal-container, #kt-target-modal25074_bd8a9a-ea .kt-modal-container, .kb-modal-content25074_bd8a9a-ea .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal25074_bd8a9a-ea .kt-modal-close, #kt-target-modal25074_bd8a9a-ea .kt-modal-close, .kb-modal-content25074_bd8a9a-ea .kt-modal-close{color:#212327;}#kt-modal25074_bd8a9a-ea .kt-modal-close svg, #kt-target-modal25074_bd8a9a-ea .kt-modal-close svg, .kb-modal-content25074_bd8a9a-ea .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal25074_bd8a9a-ea .kt-modal-container, #kt-target-modal25074_bd8a9a-ea .kt-modal-container, .kb-modal-content25074_bd8a9a-ea .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal25074_bd8a9a-ea .kt-modal-close svg, #kt-target-modal25074_bd8a9a-ea .kt-modal-close svg, .kb-modal-content25074_bd8a9a-ea .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal25074_bd8a9a-ea .kt-modal-container, #kt-target-modal25074_bd8a9a-ea .kt-modal-container, .kb-modal-content25074_bd8a9a-ea .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal25074_bd8a9a-ea .kt-modal-close svg, #kt-target-modal25074_bd8a9a-ea .kt-modal-close svg, .kb-modal-content25074_bd8a9a-ea .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center peu-line\" id=\"kt-modal25074_bd8a9a-ea\"><div id=\"kt-target-modal25074_bd8a9a-ea\" class=\"kb-modal-content25074_bd8a9a-ea kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal25074_bd8a9a-ea-content\" class=\"kt-modal-content\">\n<h2 class=\"wp-block-heading eplus-GwyL65\">Av\u00eds legal<\/h2>\n\n\n\n<p class=\"eplus-8gcdpe\">CAMBRIDGE LANGUAGE SCHOOL, S.L. (en endavant CAMBRIDGE SCHOOL) \u00e9s una escola d\u2019idiomes amb domicili social a Pla\u00e7a Porxada, 39 de Granollers, amb CIF B61104576. CAMBRIDGE SCHOOL \u00e9s el titular del domini en Internet \u201ccambridgeschool\u201d, sota el que figura el portal web www.cambridgeschool.com i tots els subdominis i directoris inclosos sota el mateix.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-6uG7R3\">Informaci\u00f3 general<\/h4>\n\n\n\n<p class=\"eplus-yKmYCI\">L\u2019acc\u00e9s i \u00fas d\u2019aquest portal queden subjectes als termes d\u2019aquest Av\u00eds Legal, sense prejudici de que l\u2019acc\u00e9s a algun dels serveis pugui precisar l\u2019acceptaci\u00f3 d\u2019unes condicions particulars.<\/p>\n\n\n\n<p class=\"eplus-TA8qjW\">Qualsevol \u00fas que es faci del Portal o dels serveis en ell inclosos implicar\u00e0 l\u2019acceptaci\u00f3 dels termes legals d\u2019aquest Av\u00eds Legal.<\/p>\n\n\n\n<p class=\"eplus-RKGIY1\">L\u2019acc\u00e9s al Portal i l\u2019\u00fas correcte de la informaci\u00f3 continguda en el mateix s\u00f3n responsabilitat de qui realitza aquestes accions, no essent responsable CAMBRIDGE SCHOOL per l\u2019\u00fas incorrecte, il\u00b7l\u00edcit o negligent que del mateix pogu\u00e9s fer-ne&nbsp; l\u2019usuari.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-HjUNDF\">Contingut<\/h4>\n\n\n\n<p class=\"eplus-Omlwjp\">L\u2019objectiu del Portal \u00e9s promocionar les activitats i serveis que realitza i presta CAMBRIDGE SCHOOL, per la qual cosa la informaci\u00f3 continguda en ell no constitueix una oferta vinculant.<\/p>\n\n\n\n<p class=\"eplus-2yFnVy\">El Portal podr\u00e0 contenir articles sobre temes d\u2019educaci\u00f3, de cultura,&nbsp; d\u2019actualitat o d\u2019altres, el contingut dels quals reflectir\u00e0 l\u2019opini\u00f3 dels seus autors, per\u00f2 no necess\u00e0riament la de CAMBRIDGE SCHOOL.<\/p>\n\n\n\n<p class=\"eplus-YBdKnQ\">CAMBRIDGE SCHOOL no assumir\u00e0 cap responsabilitat sobre l\u2019\u00fas inadequat dels continguts del seu lloc web.<\/p>\n\n\n\n<p class=\"eplus-WXQLbG\">CAMBRIDGE SCHOOL es reserva el dret a realitzar canvis i modificacions dels continguts i\/o disseny del Portal sense previ av\u00eds en qualsevol moment. Els continguts del Portal s\u2019actualitzen peri\u00f2dicament. Degut a que l\u2019actualitzaci\u00f3 de la informaci\u00f3 no \u00e9s immediata, li suggerim que comprovi sempre la vig\u00e8ncia i exactitud de la mateixa continguda en el Portal.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-edsskN\">Propietat intel\u00b7lectual i industrial<\/h4>\n\n\n\n<p class=\"eplus-XdIkpv\">El disseny, contingut i codis Font del Portal, aix\u00ed com els logotip, marques i d\u2019altres signes distintius que apareixen en el mateix, pertanyen a CAMBRIDGE SCHOOL&nbsp; i estan protegits pels corresponents drets de propietat intel\u00b7lectual i industrial, per la qual cosa el seu \u00fas, reproducci\u00f3, distribuci\u00f3, comunicaci\u00f3 p\u00fablica, transformaci\u00f3 o qualsevol altra activitat similar o an\u00e0loga, queda totalment prohibida excepte que existeixi expressa autoritzaci\u00f3 per escrit de CAMBRIDGE SCHOOL.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-E64BbM\">Virus i errors tecnol\u00f2gics<\/h4>\n\n\n\n<p class=\"eplus-Nhjp1n\">CAMBRIDGE SCHOOL no controla ni garanteix l\u2019abs\u00e8ncia de virus ni d\u2019altres elements en els continguts que puguin produir alteracions en el sistema inform\u00e0ticde l\u2019usuari (software i hardware), documents o fitxers. Per aix\u00f2, CS no es fa responsable dels danys o perjudicis que pateixi l\u2019usuari per l\u2019exist\u00e8ncia de virus od\u2019altres elements en el Portal.<\/p>\n\n\n\n<p class=\"eplus-khoeZx\">CAMBRIDGE SCHOOL no pot garantir l\u2019abs\u00e8ncia de fallades tecnol\u00f2giques, ni la permanent disponibilitat del Portal i dels serveis continguts en el mateix i, en conseq\u00fc\u00e8ncia, no assumeix cap responsabilitat pels danys i perjudicis que puguin generar-se per la manca de disponibilitat i fallades en l\u2019acc\u00e9s.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-OLmL7Y\">Seguretat de la informaci\u00f3<\/h4>\n\n\n\n<p class=\"eplus-t91f4W\">CAMBRIDGE SCHOOL no pot garantir que les transmissions d\u2019informaci\u00f3 a trav\u00e9s d\u2019Internet siguin totalment segures, ja que intervenen m\u00faltiples factors fora del control de CAMBRIDGE SCHOOL. CAMBRIDGE SCHOOL no es fa responsable dels danys o perjudicis que pateixi l\u2019usuari per possibles conting\u00e8ncies en la transmissi\u00f3 d\u2019informaci\u00f3, tals com la p\u00e8rdua de dades o accessos no autoritzats de terceres persones.<\/p>\n\n\n\n<p class=\"eplus-L7MGYw\">Malgrat aix\u00f2, l\u2019informem que CAMBRIDGE SCHOOL mant\u00e9 una pol\u00edtica de seguretat de tractament de dades de car\u00e0cter personal d\u2019acord la llei Org\u00e0nica 15\/1999 de 13 de desembre de Protecci\u00f3 de dades de car\u00e0cter personal.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-a7uMqF\">Publicitat<\/h4>\n\n\n\n<p class=\"eplus-RTCrZA\">En cas que CAMBRIDGE SCHOOL inser\u00eds publicitat de terceres empreses anunciants que consider\u00e9s d\u2019inter\u00e8s de l\u2019usuari, l\u2019informem que CAMBRIDGE SCHOOL no facilita informaci\u00f3 de l\u2019usuari als anunciants, excepte dades estad\u00edstiques an\u00f2nimes sobre la utilitzaci\u00f3 del Portal, amb la finalitat que es pugui millorar el servei i oferir productes conforme a les expectatives dels usuaris.<\/p>\n\n\n\n<p class=\"eplus-IbzoYO\">Malgrat aix\u00f2, CAMBRIDGE SCHOOL l\u2019informa que els anunciants i prove\u00efdors, mitjan\u00e7ant les cookies, poden tenir la possibilitat d\u2019obtenir informaci\u00f3 sobre l\u2019usuari, els usos que fa dels serveis i els seus moviments a trav\u00e9s de la xarxa. Per no tenir vinculaci\u00f3 amb els usos que de l\u2019esmentada informaci\u00f3 pugui realitzar l\u2019empresa anunciant, CAMBRIDGE SCHOOL no es fa responsable de la recollida d\u2019informaci\u00f3 per part d\u2019aquestes empreses.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-HPAC78\">Links a altres p\u00e0gines web<\/h4>\n\n\n\n<p class=\"eplus-xnPAUS\">CAMBRIDGE SCHOOL pot facilitar en aquest web site, links a altres p\u00e0gines web que cregui d\u2019inter\u00e8s, per\u00f2&nbsp; no subscriu ni es responsabilitza obligat\u00f2riament dels continguts d\u2019aquestes p\u00e0gines. La finalitat de publicar accessos a aquestes p\u00e0gines es sempre informativa.<\/p>\n\n\n\n<p class=\"eplus-ToAdl9\">No es permetr\u00e0 l\u2019enlla\u00e7 de cap p\u00e0gina web o d\u2019una adre\u00e7a de correu electr\u00f2nic al Portal, excepte amb l\u2019autoritzaci\u00f3 expressa per escrit de CAMBRIDGE SCHOOL, que podr\u00e0 ser revocada en qualsevol moment. L\u2019establiment de l\u2019enlla\u00e7 no suposar\u00e0 cap tipus d\u2019acord, contracte, patrocini ni recomanaci\u00f3 per part de CAMBRIDGE SCHOOL.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-IMpsjU\">Cl\u00e0usula de confidencialitat<\/h4>\n\n\n\n<p class=\"eplus-6ItYmm\">En compliment del que estableix la llei Org\u00e0nica 15\/1999 de 13 de desembre de Protecci\u00f3 de dades de car\u00e0cter personal i del Reglament 679\/2016, CAMBRIDGE SCHOOL respectar\u00e0 la confidencialitat de les dades de car\u00e0cter personal aportades pels usuaris del Portal, mitjan\u00e7ant l\u2019observan\u00e7a de la mat\u00e8ria vigent sobre protecci\u00f3 de dades de car\u00e0cter personal.<\/p>\n\n\n\n<p class=\"eplus-YrQ5IA\">Al proporcionar-nos les seves dades de car\u00e0cter personal a trav\u00e9s dels formularis electr\u00f2nics del Portal, est\u00e0 consentint que CAMBRIDGE SCHOOL pugui tractar aquestes dades en els termes d\u2019aquesta cl\u00e0usula de confidencialitat.<\/p>\n\n\n\n<p class=\"eplus-aOEJUA\">L\u2019informem que CAMBRIDGE SCHOOL \u00e9s el responsable del fitxer en qu\u00e8 les seves dades personals recaptades seran tractades confidencialment amb la \u00fanica finalitat de gestionar la seva sol\u00b7licitud, facilitar-ne la informaci\u00f3 i\/o serveis que sol\u00b7liciti, aix\u00ed com aquells que creiem puguin ser del seu inter\u00e8s. Tanmateix, l\u2019informem que determinades preguntes de formularis, que vindran convenientment assenyalades, exigeixen que obligat\u00f2riament siguin contestades per tal de poder atendre la seva petici\u00f3.<\/p>\n\n\n\n<p class=\"eplus-AEi2HG\">CAMBRIDGE SCHOOL es compromet a no comunicar les seves dades personals a tercers aliens a CAMBRIDGE SCHOOL. S\u2019exceptuaran aquells sup\u00f2sits en qu\u00e8, amb acord a la finalitat perqu\u00e8 es van obtenir les dades, es faci necessari cedir-los a persones que actu\u00efn en nom o representaci\u00f3 de CAMBRIDGE SCHOOL o en relaci\u00f3 amb el negoci de CAMBRIDGE SCHOOL.<\/p>\n\n\n\n<p class=\"eplus-OADDj4\">Per exercitar els drets d\u2019acc\u00e9s, rectificaci\u00f3, cancel\u00b7laci\u00f3 i oposici\u00f3 de les seves dades personals que puguin obrar en el nostre fitxer, podr\u00e0 adre\u00e7ar-se mitjan\u00e7ant carta a&nbsp; Pla\u00e7a Porxada 39 de Granollers o b\u00e9 enviar un correu electr\u00f2nic a l\u2019adre\u00e7a:  <a href=\"mailto:protecciodades@cambridgeschool.com\" class=\"ek-link\">protecciodades@cambridgeschool.com<\/a> . En el sup\u00f2sit que no obtingui una resposta satisfact\u00f2ria o desitgi m\u00e9s informaci\u00f3 al respecte de qualsevol d\u2019aquests drets, pot adre\u00e7ar-se a l\u2019Agencia Espa\u00f1ola de Protecci\u00f3n de Datos (www.aepd.es &#8211; C\/ Jorge Juan, 6 de Madrid).<\/p>\n\n\n\n<p class=\"eplus-42IWFU\">Per tal de poder tractar la seva sol\u00b7licitud, requerim que consenti que CAMBRIDGE SCHOOL pugui tractar i cedir aquestes dades en els termes d\u2019aquesta cl\u00e0usula de confidencialitat.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal25074_bd8a9a-ea\"><span class=\"kt-blocks-modal-link-inner\">Informaci\u00f3 legal<\/span><\/button><\/div>\n\n\n<style>#kt-modal25074_9da59b-58 .kt-blocks-modal-link{color:#FFFFFF;background:transparent;border-color:#212327;border-radius:0px;font-size:14px;line-height:20px;border-width:0px 0px 0px 0px;padding:4px 8px 4px 8px;margin:0px 0px 0px 0px;}#kt-modal25074_9da59b-58 .kt-blocks-modal-link:hover, #kt-modal25074_9da59b-58 .kt-blocks-modal-link:focus{border-color:#FFFFFF;}#kt-modal25074_9da59b-58 .kt-modal-overlay, #kt-target-modal25074_9da59b-58 .kt-modal-overlay, .kb-modal-content25074_9da59b-58 .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal25074_9da59b-58 .kt-modal-overlay, #kt-target-modal25074_9da59b-58 .kt-modal-overlay, .kb-modal-content25074_9da59b-58 .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal25074_9da59b-58 .kt-modal-container, #kt-target-modal25074_9da59b-58 .kt-modal-container, .kb-modal-content25074_9da59b-58 .kt-modal-container{width:80%;max-width:800px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal25074_9da59b-58 .kt-modal-container, #kt-target-modal25074_9da59b-58 .kt-modal-container, .kb-modal-content25074_9da59b-58 .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal25074_9da59b-58 .kt-modal-container, #kt-target-modal25074_9da59b-58 .kt-modal-container, .kb-modal-content25074_9da59b-58 .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal25074_9da59b-58 .kt-modal-close svg, #kt-target-modal25074_9da59b-58 .kt-modal-close svg, .kb-modal-content25074_9da59b-58 .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal25074_9da59b-58 .kt-modal-container, #kt-target-modal25074_9da59b-58 .kt-modal-container, .kb-modal-content25074_9da59b-58 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal25074_9da59b-58 .kt-modal-close svg, #kt-target-modal25074_9da59b-58 .kt-modal-close svg, .kb-modal-content25074_9da59b-58 .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal25074_9da59b-58 .kt-modal-container, #kt-target-modal25074_9da59b-58 .kt-modal-container, .kb-modal-content25074_9da59b-58 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal25074_9da59b-58 .kt-modal-close svg, #kt-target-modal25074_9da59b-58 .kt-modal-close svg, .kb-modal-content25074_9da59b-58 .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center peu-line\" id=\"kt-modal25074_9da59b-58\"><div id=\"kt-target-modal25074_9da59b-58\" class=\"kb-modal-content25074_9da59b-58 kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal25074_9da59b-58-content\" class=\"kt-modal-content\">\n<h2 class=\"wp-block-heading eplus-sNdj9i\">Pol\u00edtica de cookies<\/h2>\n\n\n\n<p class=\"eplus-uexzYR\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-fnefwl\">Qu\u00e8 s\u00f3n les cookies?<\/h4>\n\n\n\n<p class=\"eplus-boQ043\">Una cookie \u00e9s un fitxer que es descarrega al vostre ordinador en accedir a determinades p\u00e0gines web. Les cookies permeten a una p\u00e0gina web, entre altres coses, emmagatzemar i recuperar informaci\u00f3 sobre els h\u00e0bits de navegaci\u00f3 d\u2019un usuari o del seu equip i, depenent de la informaci\u00f3 que continguin i de la forma en qu\u00e8 utilitzi el seu equip, es poden utilitzar per recon\u00e8ixer l\u2019usuari.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-CBCvWB\">Quins tipus de cookies utilitza aquesta p\u00e0gina web?<\/h4>\n\n\n\n<p class=\"eplus-LJY25h\">Aix\u00ed mateix, depenent de la finalitat per a la qual s\u2019utilitzen, les cookies poden ser:<\/p>\n\n\n\n<p class=\"eplus-gSXhaX\">Cookies d\u2019Anal\u00edtica: Recopilen informaci\u00f3 per avaluar l\u2019 \u00fas de la web i l\u2019activitat general dels mateixos. L\u2019anal\u00edtica web \u00e9s la mesura, recopilaci\u00f3, an\u00e0lisi i informe de dades d\u2019Internet als efectes de la comprensi\u00f3 i l\u2019optimitzaci\u00f3 de l\u2019\u00fas del lloc web.<\/p>\n\n\n\n<p class=\"eplus-Rrqz47\">La llista de les cookies utilitzades pot ser modificada en funci\u00f3 de la inclusi\u00f3 o exclusi\u00f3 dels serveis web i aplicacions.<\/p>\n\n\n\n<p class=\"eplus-m59MOg\">Per gestionar les activitats de les cookies del seu ordinador, pot acceptar expl\u00edcitament, bloquejar o esborrar. Si no fa aix\u00f2 i continuar navegant a la web, s\u2019entendr\u00e0 que les accepta.<\/p>\n\n\n\n<p class=\"eplus-GivzpY\">Si vost\u00e8 desitja en qualsevol moment de retirar el seu consentiment per a l\u2019\u00fas de cookies, ha d\u2019eliminar les cookies emmagatzemades al seu ordinador o dispositiu m\u00f2bil a trav\u00e9s dels ajustos i configuracions del seu navegador d\u2019Internet.<\/p>\n\n\n\n<p class=\"eplus-sJydMu\">Seguiu <a href=\"http:\/\/www.google.com\/intl\/es_ALL\/policies\/privacy\/\" class=\"ek-link\">aquest enlla\u00e7<\/a> on podeu consultar la pol\u00edtica de privacitat d\u2019aquests serveis de Google.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-NcQom1\">Revocaci\u00f3 i eliminaci\u00f3 de cookies<\/h4>\n\n\n\n<p class=\"eplus-OPS5lQ\">Podeu permetre, bloquejar o eliminar les cookies instal\u00b7lades en el vostre dispositiu mitjan\u00e7ant la configuraci\u00f3 de les opcions del navegador instal\u00b7lat al vostre dispositiu.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Per a m\u00e9s informaci\u00f3 sobre el navegador Firefox premeu <a href=\"http:\/\/support.mozilla.org\/es\/kb\/cookies-informacion-que-los-sitios-web-guardan-en-\" class=\"ek-link\">aqu\u00ed<\/a>.<\/li>\n\n\n\n<li>Per a m\u00e9s informaci\u00f3 sobre el navegador Chrome premeu <a href=\"https:\/\/support.google.com\/chrome\/answer\/95647?hl=es\" class=\"ek-link\">aqu\u00ed<\/a>.<\/li>\n\n\n\n<li>Per a m\u00e9s informaci\u00f3 sobre el navegador Explorer premeu<a href=\"http:\/\/windows.microsoft.com\/es-es\/internet-explorer\/delete-manage-cookies#ie=ie-11\" class=\"ek-link\"> aqu\u00ed<\/a>.<\/li>\n\n\n\n<li>Per a m\u00e9s informaci\u00f3 sobre el navegador Safari premeu <a href=\"http:\/\/support.apple.com\/kb\/HT1677?viewlocale=es_ES&amp;locale=es_ES\">aqu\u00ed<\/a>.<\/li>\n\n\n\n<li>Per a m\u00e9s informaci\u00f3 sobre el navegador Opera premeu <a href=\"http:\/\/help.opera.com\/Mac\/12.10\/es-LA\/cookies.html\">aqu\u00ed.<\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal25074_9da59b-58\"><span class=\"kt-blocks-modal-link-inner\">Pol\u00edtica de cookies<\/span><\/button><\/div>\n\n\n<style>#kt-modal25074_8e2389-74 .kt-blocks-modal-link{color:#FFFFFF;background:transparent;border-color:#212327;border-radius:0px;font-size:14px;line-height:20px;border-width:0px 0px 0px 0px;padding:4px 8px 4px 8px;margin:0px 0px 0px 0px;}#kt-modal25074_8e2389-74 .kt-blocks-modal-link:hover, #kt-modal25074_8e2389-74 .kt-blocks-modal-link:focus{border-color:#FFFFFF;}#kt-modal25074_8e2389-74 .kt-modal-overlay, #kt-target-modal25074_8e2389-74 .kt-modal-overlay, .kb-modal-content25074_8e2389-74 .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal25074_8e2389-74 .kt-modal-overlay, #kt-target-modal25074_8e2389-74 .kt-modal-overlay, .kb-modal-content25074_8e2389-74 .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal25074_8e2389-74 .kt-modal-container, #kt-target-modal25074_8e2389-74 .kt-modal-container, .kb-modal-content25074_8e2389-74 .kt-modal-container{width:80%;max-width:800px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal25074_8e2389-74 .kt-modal-container, #kt-target-modal25074_8e2389-74 .kt-modal-container, .kb-modal-content25074_8e2389-74 .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal25074_8e2389-74 .kt-modal-container, #kt-target-modal25074_8e2389-74 .kt-modal-container, .kb-modal-content25074_8e2389-74 .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal25074_8e2389-74 .kt-modal-close svg, #kt-target-modal25074_8e2389-74 .kt-modal-close svg, .kb-modal-content25074_8e2389-74 .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal25074_8e2389-74 .kt-modal-container, #kt-target-modal25074_8e2389-74 .kt-modal-container, .kb-modal-content25074_8e2389-74 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal25074_8e2389-74 .kt-modal-close svg, #kt-target-modal25074_8e2389-74 .kt-modal-close svg, .kb-modal-content25074_8e2389-74 .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal25074_8e2389-74 .kt-modal-container, #kt-target-modal25074_8e2389-74 .kt-modal-container, .kb-modal-content25074_8e2389-74 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal25074_8e2389-74 .kt-modal-close svg, #kt-target-modal25074_8e2389-74 .kt-modal-close svg, .kb-modal-content25074_8e2389-74 .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center peu-line\" id=\"kt-modal25074_8e2389-74\"><div id=\"kt-target-modal25074_8e2389-74\" class=\"kb-modal-content25074_8e2389-74 kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal25074_8e2389-74-content\" class=\"kt-modal-content\">\n<h2 class=\"wp-block-heading eplus-selAla\">POL\u00cdTICA DE PROTECCI\u00d3 DE DADES DE CAR\u00c0CTER PERSONAL<\/h2>\n\n\n\n<p class=\"eplus-bYIpn9\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-1dSj6Y\">Qui&nbsp;\u00e9s el Responsable del Tractament&nbsp;de les seves&nbsp;dades personals?<\/h4>\n\n\n\n<p class=\"eplus-6RV54I\">Identitat: Cambridge Language School, S.L. (&#8220;Cambridge School&#8221;;)<br>C.I.F.: B-61104576<br>Domicili social: Pla\u00e7a Porxada 39, 08401, Granollers (Barcelona)<br>E-mail:&nbsp;<a href=\"mailto:info@cambridgeschool.com\">info@cambridgeschool.com<br><\/a>Tel\u00e8fon: (+34) 93.870.20.01<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-fvsq8r\">Normativa d\u2019Aplicaci\u00f3<\/h4>\n\n\n\n<p class=\"eplus-eJtofj\">El Reglament General de Protecci\u00f3n de Dades RGPD (UE) 2016\/679 de 27 d\u2019abril de 2.016&nbsp; i la Ley Org\u00e1nica 3\/2018 de 5 de desembre de Protecci\u00f3 de Dades Personals i Garantia dels Drets Digitals.<\/p>\n\n\n\n<p class=\"eplus-obWY84\">Mitjan\u00e7ant l\u2019acceptaci\u00f3 de la nostra pol\u00edtica de privacitat l\u2019usuari presta el seu consentiment informat, expr\u00e9s, lliure i inequ\u00edvoc perqu\u00e8 les seves dades personals obtingudes a trav\u00e9s de la web&nbsp;<a href=\"http:\/\/www.dsgeoprojectes.com\/\">www.cambridgeschool.com<\/a>&nbsp;siguin incloses en un fitxer del qual n\u2019\u00e9s responsable Cambridge Language School S.L. i sobre el qual s\u2019apliquen les mesures t\u00e8cniques, legals i organitzatives establertes en la normativa sobre protecci\u00f3 de dades de car\u00e0cter personal per evitar qualsevol acc\u00e9s, alteraci\u00f3, p\u00e8rdua o tractament no autoritzats.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-3aPl44\">Amb quina finalitat tractem les teves dades personals?<\/h4>\n\n\n\n<p class=\"eplus-LkoZ1P\">A Cambridge School tractem la informaci\u00f3 que ens facilita l\u2019usuari amb la finalitat de gestionar les seves sol\u00b7licituds d\u2019informaci\u00f3, enviar-li comunicacions sobre novetats o ofertes comercials que puguin ser del seu inter\u00e8s.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-msqg3Y\">Quina \u00e9s la legitimaci\u00f3 pel tractament de les seves dades?<\/h4>\n\n\n\n<p class=\"eplus-KAN50H\">La base legal per al tractament de dades \u00e9s el consentiment de l\u2019usuari que el presta mitjan\u00e7ant l\u2019acceptaci\u00f3 de la \u201cPrimera Capa\u201d de la cl\u00e0usula de tractament de dades. Si no es faciliten totes les dades de car\u00e0cter personal requerides per Cambridge School, podria implicar una incompleta atenci\u00f3 de la sol\u00b7licitud requerida. L\u2019usuari t\u00e9 dret a revocar el seu consentiment en qualsevol moment sense que aix\u00f2 afecti de forma retroactiva al tractament de dades personals realitzat fins a aquest moment.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-0L1kP4\">&nbsp;A quins destinataris es comunicaran les seves dades?<\/h4>\n\n\n\n<p class=\"eplus-6UWETY\">Les dades dels usuaris s\u2019allotgen en servidors de Montaweb S.L. contractats a l\u2019efecte mitjan\u00e7ant contracte d\u2019encarregat de tractament per Cambridge School.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-7Vea3s\">Quins s\u00f3n els seus drets quan ens faciliten les seves dades personals?<\/h4>\n\n\n\n<p class=\"eplus-u1ucDQ\">Qualsevol usuari t\u00e9 dret a obtenir confirmaci\u00f3 sobre si a Cambridge School estem tractant amb dades personals que et concerneixin o no.<\/p>\n\n\n\n<p class=\"eplus-Gx7WpD\">L\u2019usuari pot exercir el seu dret d\u2019acc\u00e9s a les dades personals, aix\u00ed com sol\u00b7licitar la rectificaci\u00f3 de les dades inexactes o, en el seu cas, sol\u00b7licitar la seva cancel\u00b7laci\u00f3 o supressi\u00f3 quan les dades ja no siguin necess\u00e0ries per a la finalitat amb qu\u00e8 van ser recollides.<\/p>\n\n\n\n<p class=\"eplus-n6w3ck\">L\u2019usuari podr\u00e0 sol\u00b7licitar la limitaci\u00f3 i oposici\u00f3 del tractament de les seves dades, en determinades circumst\u00e0ncies i per motius relacionats amb la seva situaci\u00f3 particular.<\/p>\n\n\n\n<p class=\"eplus-O7cg65\">L\u2019usuari podr\u00e0 exercitar els drets referits anteriorment, en els termes i condicions previstos a la legislaci\u00f3 vigent, al domicili social de Cambridge School o sol\u00b7icitar-lo per correu electr\u00f2nic a&nbsp;<a href=\"mailto:info@cambridgeschool.com\">info@cambridgeschool.com<\/a>. En el sup\u00f2sit que no obtingui una resposta satisfact\u00f2ria o desitgi m\u00e9s informaci\u00f3 al respecte de qualsevol d\u2019aquests drets, pot acudir a l\u2019\u201dAgencia Espa\u00f1ola de Protecci\u00f3n de Datos\u201d (<a href=\"http:\/\/www.aepd.es\/\">www.aepd.es<\/a>&nbsp;&#8211; C\/ Jorge Juan, 6 de Madrid).<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-W8R72O\">Durant quant temps conservarem les seves dades?<\/h4>\n\n\n\n<p class=\"eplus-wWP2Y2\">Les dades personals proporcionades es conservaran mentre no se sol\u00b7liciti la seva supressi\u00f3 per part de l\u2019interessat.<\/p>\n\n\n\n<h4 class=\"wp-block-heading eplus-xOUXJi\">Enlla\u00e7os a altres plataformes o xarxes socials<\/h4>\n\n\n\n<p class=\"eplus-r8ize8\">La web&nbsp;<a href=\"http:\/\/www.cambridgeschool.com\/\">www.cambridgeschool.com<\/a>&nbsp;posa a disposici\u00f3 dels Usuari\/es mitjans d\u2019enlla\u00e7 que permeten accedir als canals i p\u00e0gines que la p\u00e0gina web Cambridge Language School S.L. mant\u00e9 a les plataformes i xarxes socials de Facebook, Twitter, Instagram i YouTube propietat de tercers i gestionades per aquests&nbsp; tercers.<\/p>\n\n\n\n<p class=\"eplus-WG3wFK\">L\u2019establiment d\u2019aquestes aplicacions no implica l\u2019exist\u00e8ncia de cap relaci\u00f3n entre Cambridge Language School S.L. i les xarxes socials enlla\u00e7ades, com tampoc l\u2019acceptaci\u00f3 dels continguts i serveis essent-ne els seus titulars els seus responsables.<\/p>\n\n\n\n<p class=\"eplus-Dtg32y\">Tenint en compte que Cambridge Language School S.L. no t\u00e9 cap control sobre els continguts allotjats en aquestes xarxes socials, l\u2019usuari reconeix i accepta que Cambridge Language School S.L. no assumeix cap responsabilitat pels continguts ni pels serveis als quals l\u2019usuari pugui accedir en aquestes p\u00e0gines, ni per la publicitat, ni per qualsevol altre material disponible en aquests.<\/p>\n\n\n\n<p class=\"eplus-74bhwA\">En cap cas Cambridge Language School S.L. comparteix amb Facebook, Twitter, Instagram ni YouTube cap tipus d\u2019informaci\u00f3 privada sobre els usuaris i tota la informaci\u00f3 que l\u2019usuari vulgui proporcionar a aquestes xarxes socials estar\u00e0 sota la seva pr\u00f2pia responsabilitat.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal25074_8e2389-74\"><span class=\"kt-blocks-modal-link-inner\">Pol\u00edtica de privacitat<\/span><\/button><\/div>\n\n\n<style>.wp-block-kadence-icon.kt-svg-icons25074_d9bd8e-a4{justify-content:flex-end;}@media all and (max-width: 767px){.wp-block-kadence-icon.kt-svg-icons25074_d9bd8e-a4{justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons25074_d9bd8e-a4 alignnone aligncenter\"><style>.kt-svg-item-25074_1a0800-a8 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-25074_1a0800-a8 .kb-svg-icon-wrap{color:#FFFFFF;font-size:26px;margin-right:7px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-25074_1a0800-a8\"><a href=\"https:\/\/www.facebook.com\/CambridgeSchoolPage \" class=\"kt-svg-icon-link\" target=\"_blank\" rel=\"noopener noreferrer\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_facebook-square\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M400 32H48A48 48 0 0 0 0 80v352a48 48 0 0 0 48 48h137.25V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.27c-30.81 0-40.42 19.12-40.42 38.73V256h68.78l-11 71.69h-57.78V480H400a48 48 0 0 0 48-48V80a48 48 0 0 0-48-48z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-25074_f15af8-23 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-25074_f15af8-23 .kb-svg-icon-wrap{color:#FFFFFF;font-size:26px;margin-right:3px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-25074_f15af8-23\"><a href=\"https:\/\/twitter.com\/CambridgeSchool \" class=\"kt-svg-icon-link\" target=\"_blank\" rel=\"noopener noreferrer\"><span class=\"kb-svg-icon-wrap kb-svg-icon-kb-custom-28791\"><svg viewBox=\"0 0 24 24\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21.9,22c-0.1,0-0.1,0-0.1,0c-1.9,0-3.8,0-5.7,0c-0.1,0-0.2,0-0.2-0.1c-1.7-2.5-3.4-5-5.1-7.5c-0.1-0.1-0.2-0.2-0.2-0.4  c-0.2,0.3-0.5,0.5-0.7,0.8c-1.5,1.8-3,3.5-4.5,5.3c-0.5,0.6-1,1.2-1.6,1.8c0,0-0.1,0.1-0.1,0.1c-0.5,0-1.1,0-1.6,0c0,0,0,0-0.1,0  c2.6-3,5.2-6.1,7.8-9.1C7,9.2,4.5,5.4,1.8,1.6c0,0,0.1,0,0.1,0c1.9,0,3.8,0,5.7,0c0.1,0,0.1,0,0.2,0.1c0.6,0.9,1.2,1.8,1.8,2.7  c0.8,1.1,1.5,2.2,2.3,3.3c0.3,0.5,0.6,0.9,0.9,1.4c0,0,0,0,0,0.1c0.1-0.1,0.2-0.2,0.3-0.3c1.2-1.4,2.5-2.9,3.7-4.3  c0.8-0.9,1.6-1.9,2.4-2.8c0,0,0.1-0.1,0.1-0.1c0.6,0,1.1,0,1.7,0c-0.1,0.1-0.2,0.2-0.3,0.3c-1.4,1.7-2.9,3.4-4.3,5  c-0.9,1.1-1.9,2.2-2.8,3.3c-0.1,0.1,0,0.1,0,0.2c0.8,1.1,1.5,2.2,2.3,3.3c0.9,1.3,1.7,2.5,2.6,3.8c1,1.4,1.9,2.8,2.9,4.2  C21.7,21.8,21.8,21.9,21.9,22z M19.4,20.8c0,0,0-0.1-0.1-0.1c-0.8-1.2-1.7-2.4-2.5-3.6c-1.5-2.1-2.9-4.2-4.4-6.3  c-1-1.4-1.9-2.7-2.9-4.1C8.7,5.4,7.9,4.2,7,3C7,2.9,6.9,2.9,6.8,2.9c-0.8,0-1.6,0-2.5,0c0,0-0.1,0-0.1,0C4.5,3.3,4.8,3.6,5,4  c1.5,2.1,2.9,4.2,4.4,6.3c1,1.5,2.1,3,3.1,4.5c1.4,2,2.8,4,4.1,5.9c0,0.1,0.1,0.1,0.2,0.1c0.8,0,1.7,0,2.5,0  C19.3,20.8,19.4,20.8,19.4,20.8z\"\/><g \/><g \/><g \/><g \/><g \/><g \/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-25074_be1523-62 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-25074_be1523-62 .kb-svg-icon-wrap{color:#FFFFFF;font-size:26px;margin-right:6px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-25074_be1523-62\"><a href=\"https:\/\/www.instagram.com\/cambridge.school\/ \" class=\"kt-svg-icon-link\" target=\"_blank\" rel=\"noopener noreferrer\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_instagram\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><rect x=\"2\" y=\"2\" width=\"20\" height=\"20\" rx=\"5\" ry=\"5\"\/><path d=\"M16 11.37A4 4 0 1 1 12.63 8 4 4 0 0 1 16 11.37z\"\/><line x1=\"17.5\" y1=\"6.5\" x2=\"17.5\" y2=\"6.5\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-25074_e3d5da-cb .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-25074_e3d5da-cb .kb-svg-icon-wrap{color:#FFFFFF;font-size:26px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-25074_e3d5da-cb\"><a href=\"https:\/\/www.youtube.com\/cambridgeschoolvo \" class=\"kt-svg-icon-link\" target=\"_blank\" rel=\"noopener noreferrer\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_youtube\"><svg viewBox=\"0 0 576 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n\n\n\n<p class=\"eplus-Su6JQR\"><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p class=\"eplus-jv1967\"><\/p>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>CURSOS D&#8217;ANGL\u00c8S ONLINE PER A EMPRESES Amb bonificacions p\u00fabliques FUNDAE Sol\u00b7licita m\u00e9s informaci\u00f3 Sol\u00b7licita m\u00e9s informaci\u00f3 Plans d&#8217;angl\u00e8s per videoconfer\u00e8ncia a mida de la teva empresa Via ZOOM o TEAMS, des de casa o des de l&#8217;oficina. Planifica la formaci\u00f3 d&#8217;idiomes online de la teva empresa amb Cambridge&nbsp;School&nbsp;In-company. Per a tota la plantilla o per &#8230; <a title=\"Cursos empreses\" class=\"read-more\" href=\"https:\/\/zoom.cambridgeschool.com\/ca\/cursos-empreses\/\" aria-label=\"M\u00e9s informaci\u00f3 sobre Cursos empreses\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":6,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","slim_seo":{"title":"CURSOS DE INGL\u00c9S ONLINE PARA EMPRESAS - Cambridge School","description":"Planifica la formaci\u00f3n de idiomas online de tu empresa con Cambridge School In-company. Para toda la plantilla o para perfiles concretos, con planes adaptados para todos los niveles y un plan de seguimiento de los progresos que facilita un alto retorno de tu inversi\u00f3n"},"_joinchat":[],"footnotes":""},"class_list":["post-26636","page","type-page","status-publish"],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"admin","author_link":"https:\/\/zoom.cambridgeschool.com\/ca\/author\/admin\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/pages\/26636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/comments?post=26636"}],"version-history":[{"count":8,"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/pages\/26636\/revisions"}],"predecessor-version":[{"id":29239,"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/pages\/26636\/revisions\/29239"}],"wp:attachment":[{"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/media?parent=26636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}