{"id":23993,"date":"2021-02-11T10:58:26","date_gmt":"2021-02-11T10:58:26","guid":{"rendered":"https:\/\/zoom.cambridgeschool.com\/?page_id=23993"},"modified":"2026-04-21T11:50:21","modified_gmt":"2026-04-21T09:50:21","slug":"curs-angles-online-joves","status":"publish","type":"page","link":"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/","title":{"rendered":"Curs angl\u00e8s online joves"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_78848b-ac{margin-bottom:0px;}.kb-row-layout-id23993_78848b-ac > .kt-row-column-wrap{align-content:end;}:where(.kb-row-layout-id23993_78848b-ac > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:end;}.kb-row-layout-id23993_78848b-ac > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1200px;padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;min-height:485px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_78848b-ac{background-image:url('https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/shutterstock_1701863359.jpg');background-size:cover;background-position:49% 46%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id23993_78848b-ac > .kt-row-layout-overlay{opacity:0.50;}@media all and (max-width: 1024px){.kb-row-layout-id23993_78848b-ac > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_78848b-ac > .kt-row-column-wrap{min-height:400px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_78848b-ac alignfull kt-row-has-bg wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-kadence-rowlayout\" id=\"informacio\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-bottom kb-theme-content-width\">\n<style>.kadence-column23993_342d31-c1 > .kt-inside-inner-col{display:flex;}.kadence-column23993_342d31-c1 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);}.kadence-column23993_342d31-c1 > .kt-inside-inner-col,.kadence-column23993_342d31-c1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_342d31-c1 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-none, 0rem );column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_342d31-c1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_342d31-c1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_342d31-c1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_342d31-c1{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_342d31-c1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_342d31-c1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_342d31-c1 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_8644ae-72{margin-bottom:0px;}.kb-row-layout-id23993_8644ae-72 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id23993_8644ae-72 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id23993_8644ae-72 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );max-width:1200px;min-height:67px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id23993_8644ae-72 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_8644ae-72 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id23993_8644ae-72 > .kt-row-column-wrap{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_8644ae-72 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column23993_1803df-db > .kt-inside-inner-col{display:flex;}.kadence-column23993_1803df-db > .kt-inside-inner-col,.kadence-column23993_1803df-db > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_1803df-db > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_1803df-db > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column23993_1803df-db > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column23993_1803df-db{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_1803df-db{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_1803df-db > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column23993_1803df-db > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_1803df-db{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column23993_1803df-db{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_1803df-db{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_1803df-db > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column23993_1803df-db > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column23993_1803df-db{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_1803df-db{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_1803df-db > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column23993_1803df-db > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_1803df-db inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col{display:flex;}.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col,.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column23993_d7a7b4-91{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_d7a7b4-91{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col{background-color:rgba(0, 60, 90, 0.73);}.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_d7a7b4-91{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column23993_d7a7b4-91{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_d7a7b4-91{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column23993_d7a7b4-91{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_d7a7b4-91{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column23993_d7a7b4-91 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column23993_d7a7b4-91, .kt-inside-inner-col > .kadence-column23993_d7a7b4-91:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_d7a7b4-91 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading23993_a69b29-e6, .wp-block-kadence-advancedheading.kt-adv-heading23993_a69b29-e6[data-kb-block=\"kb-adv-heading23993_a69b29-e6\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;text-align:left;font-size:40px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_a69b29-e6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_a69b29-e6[data-kb-block=\"kb-adv-heading23993_a69b29-e6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_a69b29-e6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_a69b29-e6[data-kb-block=\"kb-adv-heading23993_a69b29-e6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading23993_a69b29-e6, .wp-block-kadence-advancedheading.kt-adv-heading23993_a69b29-e6[data-kb-block=\"kb-adv-heading23993_a69b29-e6\"]{font-size:26px;}}<\/style>\n<h1 class=\"kt-adv-heading23993_a69b29-e6 wp-block-kadence-advancedheading has-central-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading23993_a69b29-e6\"><span class=\"ugb-highlight\" style=\"color: #FFFFFF;\">CURSOS D&#8217;ANGL\u00c8S ONLINE PER A JOVES<\/span><\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_a49229-46, .wp-block-kadence-advancedheading.kt-adv-heading23993_a49229-46[data-kb-block=\"kb-adv-heading23993_a49229-46\"]{margin-bottom:0px;text-align:left;font-size:var(--global-kb-font-size-lg, 2rem);font-weight:600;font-style:normal;font-family:'Open Sans';}.wp-block-kadence-advancedheading.kt-adv-heading23993_a49229-46 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_a49229-46[data-kb-block=\"kb-adv-heading23993_a49229-46\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_a49229-46 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_a49229-46[data-kb-block=\"kb-adv-heading23993_a49229-46\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading23993_a49229-46, .wp-block-kadence-advancedheading.kt-adv-heading23993_a49229-46[data-kb-block=\"kb-adv-heading23993_a49229-46\"]{font-size:var(--global-kb-font-size-md, 1.25rem);}}<\/style>\n<h3 class=\"kt-adv-heading23993_a49229-46 wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading23993_a49229-46\">Per videoconfer\u00e8ncia \u2013 via ZOOM<\/h3>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column23993_7bd4c2-4e > .kt-inside-inner-col{display:flex;}.kadence-column23993_7bd4c2-4e > .kt-inside-inner-col,.kadence-column23993_7bd4c2-4e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_7bd4c2-4e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_7bd4c2-4e > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column23993_7bd4c2-4e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column23993_7bd4c2-4e{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_7bd4c2-4e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_7bd4c2-4e > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column23993_7bd4c2-4e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_7bd4c2-4e{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column23993_7bd4c2-4e{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_7bd4c2-4e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_7bd4c2-4e > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column23993_7bd4c2-4e > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column23993_7bd4c2-4e{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_7bd4c2-4e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column23993_7bd4c2-4e > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column23993_7bd4c2-4e > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_7bd4c2-4e\"><div class=\"kt-inside-inner-col\"><style>.kadence-column23993_e2352d-43 > .kt-inside-inner-col{display:flex;}.kadence-column23993_e2352d-43 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column23993_e2352d-43 > .kt-inside-inner-col{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}.kadence-column23993_e2352d-43 > .kt-inside-inner-col,.kadence-column23993_e2352d-43 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_e2352d-43 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_e2352d-43 > .kt-inside-inner-col{flex-direction:column;align-items:center;}.kadence-column23993_e2352d-43 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column23993_e2352d-43 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column23993_e2352d-43 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_e2352d-43 > .kt-inside-inner-col{background-color:rgba(0, 60, 90, 0.72);}.kadence-column23993_e2352d-43 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_e2352d-43{text-align:left;}.kadence-column23993_e2352d-43{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_e2352d-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kadence-column23993_e2352d-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_e2352d-43 kvs-sm-false\" data-aos=\"fade-up\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading23993_6e74c5-83, .wp-block-kadence-advancedheading.kt-adv-heading23993_6e74c5-83[data-kb-block=\"kb-adv-heading23993_6e74c5-83\"]{font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_6e74c5-83 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_6e74c5-83[data-kb-block=\"kb-adv-heading23993_6e74c5-83\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_6e74c5-83 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_6e74c5-83[data-kb-block=\"kb-adv-heading23993_6e74c5-83\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading23993_6e74c5-83 wp-block-kadence-advancedheading has-central-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading23993_6e74c5-83\">Sol\u00b7licita m\u00e9s informaci\u00f3<\/div>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f28457-o1\" lang=\"ca\" dir=\"ltr\" data-wpcf7-id=\"28457\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ca\/wp-json\/wp\/v2\/pages\/23993#wpcf7-f28457-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulari de contacte\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"28457\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"ca\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f28457-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:28457,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;repeater_remove_button&quot;:&quot;bottom&quot;,&quot;notice_dismissed_rollback-cf7-5.8.5&quot;:true,&quot;notice_dismissed_rollback-cf7-5.8.6&quot;:true,&quot;notice_dismissed_rollback-cf7-5.8.7&quot;:true}}\" \/>\n<\/fieldset>\n<div class=\"formulari header\">\n\t<div class=\"\">\n\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_source\" \/>\n\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_medium\" \/>\n\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_campaign\" \/>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Nom\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nom i cognoms\" value=\"\" type=\"text\" name=\"Nom\" \/><\/span>\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correu electr\u00f2nic\" value=\"\" type=\"email\" name=\"Email\" \/><\/span>\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e8fon\" value=\"\" type=\"tel\" name=\"Telefon\" \/><\/span>\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Curs\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"Curs\"><option value=\"\">-- Tria una opci\u00f3 --<\/option><option value=\"Adults\">Adults<\/option><option value=\"Joves\">Joves<\/option><option value=\"Empreses\">Empreses<\/option><option value=\"Certificats\">Certificats<\/option><\/select><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Accepta-privacitat\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"Accepta-privacitat\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Accepto la <a class=\"sg-popup-id-24535\" style=\"text-decoration:underline;\">Pol\u00edtica de Privacitat<\/a> de Cambridge School<\/span><\/label><\/span><\/span><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Accepta-comunicacions\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"Accepta-comunicacions\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Accepto rebre comunicacions de Cambridge School<\/span><\/label><\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"sense-marge\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner enviar\" type=\"submit\" value=\"ENVIAR\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"58\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_e94dc7-70{margin-bottom:0px;margin-top:-60px;margin-bottom:40px;}.kb-row-layout-id23993_e94dc7-70 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_e94dc7-70 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_e94dc7-70 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_e94dc7-70 > .kt-row-layout-overlay{opacity:0.30;}@media all and (min-width: 1025px){.kb-row-layout-id23993_e94dc7-70{display:none !important;}}@media all and (max-width: 1024px){.kb-row-layout-id23993_e94dc7-70 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (min-width: 768px) and (max-width: 1024px){.kb-row-layout-id23993_e94dc7-70{display:none !important;}}@media all and (max-width: 767px){.kb-row-layout-id23993_e94dc7-70 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_e94dc7-70 alignnone kb-v-lg-hidden kb-v-md-hidden wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_86dbce-49 > .kt-inside-inner-col{display:flex;}.kadence-column23993_86dbce-49 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column23993_86dbce-49 > .kt-inside-inner-col{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}.kadence-column23993_86dbce-49 > .kt-inside-inner-col,.kadence-column23993_86dbce-49 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_86dbce-49 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_86dbce-49 > .kt-inside-inner-col{flex-direction:column;align-items:center;}.kadence-column23993_86dbce-49 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column23993_86dbce-49 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column23993_86dbce-49 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_86dbce-49 > .kt-inside-inner-col{background-color:#003c5a;}.kadence-column23993_86dbce-49 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_86dbce-49{text-align:left;}.kadence-column23993_86dbce-49{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_86dbce-49 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kadence-column23993_86dbce-49 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_86dbce-49 kvs-lg-false kvs-md-false\" data-aos=\"fade-up\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading23993_7e5fe9-2a, .wp-block-kadence-advancedheading.kt-adv-heading23993_7e5fe9-2a[data-kb-block=\"kb-adv-heading23993_7e5fe9-2a\"]{text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_7e5fe9-2a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_7e5fe9-2a[data-kb-block=\"kb-adv-heading23993_7e5fe9-2a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_7e5fe9-2a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_7e5fe9-2a[data-kb-block=\"kb-adv-heading23993_7e5fe9-2a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading23993_7e5fe9-2a, .wp-block-kadence-advancedheading.kt-adv-heading23993_7e5fe9-2a[data-kb-block=\"kb-adv-heading23993_7e5fe9-2a\"]{padding-bottom:var(--global-kb-spacing-xs, 1rem);font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<div class=\"kt-adv-heading23993_7e5fe9-2a wp-block-kadence-advancedheading has-central-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading23993_7e5fe9-2a\">Sol\u00b7licita m\u00e9s informaci\u00f3<\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns23993_9ce2a0-0b{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns23993_9ce2a0-0b .kt-button{font-weight:normal;font-style:normal;}.kt-btns23993_9ce2a0-0b .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns23993_9ce2a0-0b .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns23993_9ce2a0-0b .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns23993_9ce2a0-0b .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns23993_9ce2a0-0b .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns23993_9ce2a0-0b .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns23993_9ce2a0-0b .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns23993_9ce2a0-0b\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn23993_d936f1-a1.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn23993_d936f1-a1.kb-button{background:#4BAE50;}<\/style><span class=\"kb-button kt-button button kb-btn23993_d936f1-a1 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  joinchat_open wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">WhatsApp<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_ee5eaa-90{margin-bottom:0px;}.kb-row-layout-id23993_ee5eaa-90 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_ee5eaa-90 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_ee5eaa-90 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:900px;margin-left:auto;margin-right:auto;padding-top:30px;padding-bottom:40px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_ee5eaa-90 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_ee5eaa-90 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_ee5eaa-90 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_ee5eaa-90 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_5265fb-5c > .kt-inside-inner-col,.kadence-column23993_5265fb-5c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_5265fb-5c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_5265fb-5c > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_5265fb-5c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_5265fb-5c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_5265fb-5c{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_5265fb-5c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_5265fb-5c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_5265fb-5c inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading23993_f8e39f-0c, .wp-block-kadence-advancedheading.kt-adv-heading23993_f8e39f-0c[data-kb-block=\"kb-adv-heading23993_f8e39f-0c\"]{margin-bottom:0px;text-align:center;font-size:42px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_f8e39f-0c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_f8e39f-0c[data-kb-block=\"kb-adv-heading23993_f8e39f-0c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_f8e39f-0c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_f8e39f-0c[data-kb-block=\"kb-adv-heading23993_f8e39f-0c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading23993_f8e39f-0c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_f8e39f-0c\">El seu angl\u00e8s creix amb ells<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_d066da-60, .wp-block-kadence-advancedheading.kt-adv-heading23993_d066da-60[data-kb-block=\"kb-adv-heading23993_d066da-60\"]{margin-bottom:20px;text-align:center;font-size:40px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_d066da-60 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_d066da-60[data-kb-block=\"kb-adv-heading23993_d066da-60\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_d066da-60 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_d066da-60[data-kb-block=\"kb-adv-heading23993_d066da-60\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading23993_d066da-60 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_d066da-60\">Tamb\u00e9 online!<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_7dfa78-31, .wp-block-kadence-advancedheading.kt-adv-heading23993_7dfa78-31[data-kb-block=\"kb-adv-heading23993_7dfa78-31\"]{margin-bottom:5px;text-align:center;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_7dfa78-31 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_7dfa78-31[data-kb-block=\"kb-adv-heading23993_7dfa78-31\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_7dfa78-31 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_7dfa78-31[data-kb-block=\"kb-adv-heading23993_7dfa78-31\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading23993_7dfa78-31 wp-block-kadence-advancedheading has-central-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading23993_7dfa78-31\"><strong><strong>Dels 10 als 17 anys \u00e9s una fase de creixement acad\u00e8mic.<\/strong><\/strong><\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_db49a2-25, .wp-block-kadence-advancedheading.kt-adv-heading23993_db49a2-25[data-kb-block=\"kb-adv-heading23993_db49a2-25\"]{margin-top:0px;margin-bottom:40px;text-align:center;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_db49a2-25 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_db49a2-25[data-kb-block=\"kb-adv-heading23993_db49a2-25\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_db49a2-25 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_db49a2-25[data-kb-block=\"kb-adv-heading23993_db49a2-25\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading23993_db49a2-25 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_db49a2-25\">Els joves treballen la <strong>gram\u00e0tica<\/strong> i amplien el seu <strong>vocabulari <\/strong>amb cursos <strong>adequats a les seves prefer\u00e8ncies i necessitats<\/strong> que els permeten treure el millor de si mateixos.<\/h4>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_d0eb95-5e{margin-bottom:0px;margin-bottom:30px;}.kb-row-layout-id23993_d0eb95-5e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_d0eb95-5e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_d0eb95-5e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:30px;padding-bottom:25px;}.kb-row-layout-id23993_d0eb95-5e > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id23993_d0eb95-5e > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id23993_d0eb95-5e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_d0eb95-5e > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id23993_d0eb95-5e > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id23993_d0eb95-5e > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id23993_d0eb95-5e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_d0eb95-5e alignfull has-central-palette-6-background-color kt-row-has-bg editorskit-no-mobile wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_9f6907-8e > .kt-inside-inner-col,.kadence-column23993_9f6907-8e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_9f6907-8e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_9f6907-8e > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_9f6907-8e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_9f6907-8e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_9f6907-8e{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_9f6907-8e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_9f6907-8e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_9f6907-8e inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_dcec11-69 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_dcec11-69 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:30px;}.kt-info-box23993_dcec11-69 .kt-blocks-info-box-link-wrap:hover{background:#F2F2F2;}.kt-info-box23993_dcec11-69.wp-block-kadence-infobox{max-width:100%;}.kt-info-box23993_dcec11-69 .kadence-info-box-image-inner-intrisic-container{max-width:105px;}.kt-info-box23993_dcec11-69 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:400px;height:0px;max-width:100%;}.kt-info-box23993_dcec11-69 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_dcec11-69 .kt-info-svg-icon-flip, .kt-info-box23993_dcec11-69 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_dcec11-69 .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:0px;}.kt-info-box23993_dcec11-69 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box23993_dcec11-69 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box23993_dcec11-69 .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:22px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:20px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box23993_dcec11-69 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box23993_dcec11-69 .kt-blocks-info-box-text{font-size:15px;}.kt-info-box23993_dcec11-69 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_dcec11-69 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_dcec11-69 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_dcec11-69 .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box23993_dcec11-69 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_dcec11-69\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona5.png\" alt=\"Cursos-ingles-online- Cambridge-school-icona5\" width=\"400\" height=\"400\" class=\"kt-info-box-image wp-image-23838\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona5.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona5-300x300.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona5-150x150.png 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\"><strong>Classes<\/strong> <strong>molt<\/strong><br><strong>interactives<\/strong><\/h4><p class=\"kt-blocks-info-box-text\">Dissenyades especialment per a joves <strong>de 10 a 17 anys<\/strong>, que oferim en grups d&#8217;edats similars i del mateix nivell.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column23993_c595d5-aa > .kt-inside-inner-col,.kadence-column23993_c595d5-aa > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_c595d5-aa > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_c595d5-aa > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_c595d5-aa > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_c595d5-aa > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_c595d5-aa{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_c595d5-aa > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_c595d5-aa > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_c595d5-aa inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_2a73b0-67 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_2a73b0-67 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:20px;}.kt-info-box23993_2a73b0-67 .kt-blocks-info-box-link-wrap:hover{background:#f2f2f2;}.kt-info-box23993_2a73b0-67.wp-block-kadence-infobox{max-width:100%;}.kt-info-box23993_2a73b0-67 .kadence-info-box-image-inner-intrisic-container{max-width:105px;}.kt-info-box23993_2a73b0-67 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:150px;height:0px;max-width:100%;}.kt-info-box23993_2a73b0-67 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_2a73b0-67 .kt-info-svg-icon-flip, .kt-info-box23993_2a73b0-67 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_2a73b0-67 .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:0px;}.kt-info-box23993_2a73b0-67 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box23993_2a73b0-67 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box23993_2a73b0-67 .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:22px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:20px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box23993_2a73b0-67 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box23993_2a73b0-67 .kt-blocks-info-box-text{font-size:15px;}.kt-info-box23993_2a73b0-67 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_2a73b0-67 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_2a73b0-67 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_2a73b0-67 .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box23993_2a73b0-67 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_2a73b0-67\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Logos-cambridges.png\" alt=\"Logos-cambridges\" width=\"150\" height=\"150\" class=\"kt-info-box-image wp-image-23898\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\"><strong>Cursos acad\u00e8mics estructurats<\/strong><\/h4><p class=\"kt-blocks-info-box-text\">Per cobrir les <strong>necessitats comunicatives en angl\u00e8s<\/strong> i preparar-se per als futurs <strong>ex\u00e0mens oficials<\/strong>.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column23993_f0ef6c-cb > .kt-inside-inner-col,.kadence-column23993_f0ef6c-cb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_f0ef6c-cb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_f0ef6c-cb > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_f0ef6c-cb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_f0ef6c-cb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_f0ef6c-cb{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_f0ef6c-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_f0ef6c-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_f0ef6c-cb inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_ed24c1-77 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_ed24c1-77 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:30px;}.kt-info-box23993_ed24c1-77 .kt-blocks-info-box-link-wrap:hover{background:#f2f2f2;}.kt-info-box23993_ed24c1-77.wp-block-kadence-infobox{max-width:100%;}.kt-info-box23993_ed24c1-77 .kadence-info-box-image-inner-intrisic-container{max-width:105px;}.kt-info-box23993_ed24c1-77 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:400px;height:0px;max-width:100%;}.kt-info-box23993_ed24c1-77 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_ed24c1-77 .kt-info-svg-icon-flip, .kt-info-box23993_ed24c1-77 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_ed24c1-77 .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:0px;}.kt-info-box23993_ed24c1-77 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box23993_ed24c1-77 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box23993_ed24c1-77 .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:22px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:20px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box23993_ed24c1-77 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box23993_ed24c1-77 .kt-blocks-info-box-text{font-size:15px;}.kt-info-box23993_ed24c1-77 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_ed24c1-77 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_ed24c1-77 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_ed24c1-77 .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box23993_ed24c1-77 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_ed24c1-77\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12.png\" alt=\"Cursos-ingles-online- Cambridge-school-icona12\" width=\"400\" height=\"400\" class=\"kt-info-box-image wp-image-23823\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12-300x300.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12-150x150.png 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\"><strong>Amb seguiment personalitzat<\/strong><\/h4><p class=\"kt-blocks-info-box-text\"><strong><strong>Tests peri\u00f2dics<\/strong> i <strong>informes personalitzats<\/strong> <\/strong>de cada alumne.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column23993_938965-15 > .kt-inside-inner-col,.kadence-column23993_938965-15 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_938965-15 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_938965-15 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_938965-15 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_938965-15 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_938965-15{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_938965-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_938965-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_938965-15 inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_22feaa-dd .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_22feaa-dd .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:0px;}.kt-info-box23993_22feaa-dd .kt-blocks-info-box-link-wrap:hover{background:#f2f2f2;}.kt-info-box23993_22feaa-dd.wp-block-kadence-infobox{max-width:100%;}.kt-info-box23993_22feaa-dd .kadence-info-box-image-inner-intrisic-container{max-width:105px;}.kt-info-box23993_22feaa-dd .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:400px;height:0px;max-width:100%;}.kt-info-box23993_22feaa-dd .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_22feaa-dd .kt-info-svg-icon-flip, .kt-info-box23993_22feaa-dd .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_22feaa-dd .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:0px;}.kt-info-box23993_22feaa-dd .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box23993_22feaa-dd .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box23993_22feaa-dd .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:22px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:20px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box23993_22feaa-dd .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box23993_22feaa-dd .kt-blocks-info-box-text{font-size:15px;}.kt-info-box23993_22feaa-dd .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_22feaa-dd .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_22feaa-dd .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_22feaa-dd .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box23993_22feaa-dd .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_22feaa-dd\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icono5.png\" alt=\"Cursos-ingles-online- Cambridge-school-icono5\" width=\"400\" height=\"400\" class=\"kt-info-box-image wp-image-23850\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icono5.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icono5-300x300.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icono5-150x150.png 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\"><strong>Estret contacte fam\u00edlies-professor<\/strong><\/h4><p class=\"kt-blocks-info-box-text\">Amb <strong>reunions informatives<\/strong> i de <strong>seguiment online<\/strong> per videoconfer\u00e8ncia via ZOOM amb els pares.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_2b57ae-70{margin-bottom:0px;margin-bottom:0px;}.kb-row-layout-id23993_2b57ae-70 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_2b57ae-70 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_2b57ae-70 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1200px;margin-left:auto;margin-right:auto;padding-top:50px;padding-bottom:50px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_2b57ae-70 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_2b57ae-70 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_2b57ae-70{margin-bottom:0px;}.kb-row-layout-id23993_2b57ae-70 > .kt-row-column-wrap{padding-right:15px;padding-left:15px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_2b57ae-70 alignnone has-central-palette-6-background-color kt-row-has-bg editorskit-no-desktop editorskit-no-tablet wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_04c1b5-14 > .kt-inside-inner-col,.kadence-column23993_04c1b5-14 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_04c1b5-14 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_04c1b5-14 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_04c1b5-14 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_04c1b5-14 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_04c1b5-14{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_04c1b5-14 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_04c1b5-14 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_04c1b5-14 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_f52d0f-9f .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_f52d0f-9f .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:30px;}.kt-info-box23993_f52d0f-9f .kt-blocks-info-box-link-wrap:hover{background:#F2F2F2;}.kt-info-box23993_f52d0f-9f.wp-block-kadence-infobox{max-width:100%;}.kt-info-box23993_f52d0f-9f .kadence-info-box-image-inner-intrisic-container{max-width:70px;}.kt-info-box23993_f52d0f-9f .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:400px;height:0px;max-width:100%;}.kt-info-box23993_f52d0f-9f .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_f52d0f-9f .kt-info-svg-icon-flip, .kt-info-box23993_f52d0f-9f .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_f52d0f-9f .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box23993_f52d0f-9f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box23993_f52d0f-9f .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:23px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box23993_f52d0f-9f .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box23993_f52d0f-9f .kt-blocks-info-box-text{font-size:16px;}.kt-info-box23993_f52d0f-9f .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_f52d0f-9f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_f52d0f-9f .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_f52d0f-9f .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box23993_f52d0f-9f .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_f52d0f-9f\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona5.png\" alt=\"Cursos-ingles-online- Cambridge-school-icona5\" width=\"400\" height=\"400\" class=\"kt-info-box-image wp-image-23838\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona5.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona5-300x300.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona5-150x150.png 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\"><strong>Classes&nbsp;din\u00e0miques&nbsp;i interactives<\/strong><\/h4><p class=\"kt-blocks-info-box-text\">Dissenyades especialment per a joves <strong>de 10 a 17 anys<\/strong>, que oferim en grups d&#8217;edats similars i del mateix nivell.<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_a1b281-ba .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_a1b281-ba .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:30px;}.kt-info-box23993_a1b281-ba .kt-blocks-info-box-link-wrap:hover{background:#f2f2f2;}.kt-info-box23993_a1b281-ba.wp-block-kadence-infobox{max-width:100%;}.kt-info-box23993_a1b281-ba .kadence-info-box-image-inner-intrisic-container{max-width:70px;}.kt-info-box23993_a1b281-ba .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:150px;height:0px;max-width:100%;}.kt-info-box23993_a1b281-ba .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_a1b281-ba .kt-info-svg-icon-flip, .kt-info-box23993_a1b281-ba .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_a1b281-ba .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box23993_a1b281-ba .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box23993_a1b281-ba .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:23px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box23993_a1b281-ba .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box23993_a1b281-ba .kt-blocks-info-box-text{font-size:16px;}.kt-info-box23993_a1b281-ba .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_a1b281-ba .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_a1b281-ba .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_a1b281-ba .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box23993_a1b281-ba .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_a1b281-ba\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Logos-cambridges.png\" alt=\"Logos-cambridges\" width=\"150\" height=\"150\" class=\"kt-info-box-image wp-image-23898\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\"><strong>Cursos acad\u00e8mics estructurats<\/strong><\/h4><p class=\"kt-blocks-info-box-text\">Per cobrir les <strong>necessitats comunicatives en angl\u00e8s<\/strong> i preparar-se per als futurs <strong>ex\u00e0mens oficials<\/strong>.<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_22a31d-e5 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_22a31d-e5 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:30px;}.kt-info-box23993_22a31d-e5 .kt-blocks-info-box-link-wrap:hover{background:#f2f2f2;}.kt-info-box23993_22a31d-e5.wp-block-kadence-infobox{max-width:100%;}.kt-info-box23993_22a31d-e5 .kadence-info-box-image-inner-intrisic-container{max-width:70px;}.kt-info-box23993_22a31d-e5 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:400px;height:0px;max-width:100%;}.kt-info-box23993_22a31d-e5 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_22a31d-e5 .kt-info-svg-icon-flip, .kt-info-box23993_22a31d-e5 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_22a31d-e5 .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box23993_22a31d-e5 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box23993_22a31d-e5 .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:23px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box23993_22a31d-e5 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box23993_22a31d-e5 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box23993_22a31d-e5 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_22a31d-e5 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_22a31d-e5 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_22a31d-e5 .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box23993_22a31d-e5 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_22a31d-e5\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12.png\" alt=\"Cursos-ingles-online- Cambridge-school-icona12\" width=\"400\" height=\"400\" class=\"kt-info-box-image wp-image-23823\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12-300x300.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona12-150x150.png 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\"><strong>Amb seguiment personalitzat<\/strong><\/h4><p class=\"kt-blocks-info-box-text\"><strong><strong><strong>Tests peri\u00f2dics<\/strong> i <strong>informes personalitzats<\/strong> <\/strong><\/strong>de cada alumne.<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_eb5df0-c2 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_eb5df0-c2 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:0px;}.kt-info-box23993_eb5df0-c2 .kt-blocks-info-box-link-wrap:hover{background:#f2f2f2;}.kt-info-box23993_eb5df0-c2.wp-block-kadence-infobox{max-width:100%;}.kt-info-box23993_eb5df0-c2 .kadence-info-box-image-inner-intrisic-container{max-width:70px;}.kt-info-box23993_eb5df0-c2 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:400px;height:0px;max-width:100%;}.kt-info-box23993_eb5df0-c2 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_eb5df0-c2 .kt-info-svg-icon-flip, .kt-info-box23993_eb5df0-c2 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_eb5df0-c2 .kt-blocks-info-box-media{color:#89CA4A;background:transparent;border-color:#eeeeee;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box23993_eb5df0-c2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#eeeeee;}.kt-info-box23993_eb5df0-c2 .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:#212327;font-size:23px;line-height:28px;font-style:normal;font-weight:bold;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:15px;margin-left:0px;}.kt-info-box23993_eb5df0-c2 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#212327;}.wp-block-kadence-infobox.kt-info-box23993_eb5df0-c2 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box23993_eb5df0-c2 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_eb5df0-c2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_eb5df0-c2 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_eb5df0-c2 .kt-blocks-info-box-link-wrap{text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box23993_eb5df0-c2 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_eb5df0-c2\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icono5.png\" alt=\"Cursos-ingles-online- Cambridge-school-icono5\" width=\"400\" height=\"400\" class=\"kt-info-box-image wp-image-23850\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icono5.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icono5-300x300.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icono5-150x150.png 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\"><strong>Estret contacte fam\u00edlies-professor<\/strong><\/h4><p class=\"kt-blocks-info-box-text\">Amb <strong>reunions informatives<\/strong> i de <strong>seguiment online<\/strong> per videoconfer\u00e8ncia via ZOOM amb els pares.<br><\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_95cc31-eb{margin-bottom:0px;}.kb-row-layout-id23993_95cc31-eb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_95cc31-eb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_95cc31-eb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_95cc31-eb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_95cc31-eb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_95cc31-eb{margin-top:0px;}.kb-row-layout-id23993_95cc31-eb > .kt-row-column-wrap{padding-top:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_95cc31-eb alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_88a353-78 > .kt-inside-inner-col,.kadence-column23993_88a353-78 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_88a353-78 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_88a353-78 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_88a353-78 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_88a353-78 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_88a353-78{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_88a353-78 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_88a353-78 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_88a353-78 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_fe2878-a8{margin-bottom:0px;}.kb-row-layout-id23993_fe2878-a8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_fe2878-a8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_fe2878-a8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);padding-top:25px;padding-bottom:0px;padding-left:30px;grid-template-columns:minmax(0, calc(10% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(90% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id23993_fe2878-a8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_fe2878-a8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_fe2878-a8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_fe2878-a8 alignnone has-central-palette-4-background-color kt-row-has-bg editorskit-no-mobile wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_bc02e6-77 > .kt-inside-inner-col,.kadence-column23993_bc02e6-77 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_bc02e6-77 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_bc02e6-77 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_bc02e6-77 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_bc02e6-77 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_bc02e6-77{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_bc02e6-77 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_bc02e6-77 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_bc02e6-77 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-large eplus-WXLKBl\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona11.png\" alt=\"Cursos-ingles-online- Cambridge-school-icona11\" class=\"wp-image-23843\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona11.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona11-300x300.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona11-150x150.png 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p class=\"eplus-B3xrsQ\"><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column23993_001ea5-b4 > .kt-inside-inner-col,.kadence-column23993_001ea5-b4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_001ea5-b4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_001ea5-b4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_001ea5-b4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_001ea5-b4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_001ea5-b4{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_001ea5-b4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_001ea5-b4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_001ea5-b4 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading23993_db51a0-19, .wp-block-kadence-advancedheading.kt-adv-heading23993_db51a0-19[data-kb-block=\"kb-adv-heading23993_db51a0-19\"]{margin-bottom:0px;font-size:31px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_db51a0-19 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_db51a0-19[data-kb-block=\"kb-adv-heading23993_db51a0-19\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_db51a0-19 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_db51a0-19[data-kb-block=\"kb-adv-heading23993_db51a0-19\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading23993_db51a0-19 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading23993_db51a0-19\"><strong><strong><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">NOTA D\u2019INTER\u00c8S ACAD\u00c8MIC<\/span><\/strong><\/strong><\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_66673e-ac, .wp-block-kadence-advancedheading.kt-adv-heading23993_66673e-ac[data-kb-block=\"kb-adv-heading23993_66673e-ac\"]{padding-bottom:0px;margin-top:0px;margin-bottom:0px;font-size:28px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_66673e-ac mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_66673e-ac[data-kb-block=\"kb-adv-heading23993_66673e-ac\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_66673e-ac img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_66673e-ac[data-kb-block=\"kb-adv-heading23993_66673e-ac\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading23993_66673e-ac wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading23993_66673e-ac\"><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">Cada curs de nivell&nbsp;<strong><span style=\"text-decoration: underline;\" class=\"ek-underline\">equival a 1 any escolar sencer<\/span>.<\/strong><\/span><\/h2>\n\n\n\n<p class=\"eplus-bCaQL9\"><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_4dd490-55{margin-bottom:0px;}.kb-row-layout-id23993_4dd490-55 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_4dd490-55 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_4dd490-55 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(10% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(90% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id23993_4dd490-55 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_4dd490-55 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_4dd490-55 > .kt-row-column-wrap{padding-right:30px;padding-left:30px;grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_4dd490-55 alignnone has-central-palette-4-background-color kt-row-has-bg editorskit-no-desktop editorskit-no-tablet wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-right-golden kt-row-valign-top\">\n<style>.kadence-column23993_fcecbe-64 > .kt-inside-inner-col,.kadence-column23993_fcecbe-64 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_fcecbe-64 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_fcecbe-64 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_fcecbe-64 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_fcecbe-64 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_fcecbe-64{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_fcecbe-64 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_fcecbe-64 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_fcecbe-64 inner-column-1\"><div class=\"kt-inside-inner-col\"><div class=\"wp-block-image eplus-jSxt2P\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona11.png\" alt=\"Cursos-ingles-online- Cambridge-school-icona11\" class=\"wp-image-23843\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona11.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona11-300x300.png 300w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Cursos-ingles-online-Cambridge-school-icona11-150x150.png 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n<style>.kadence-column23993_77231c-03 > .kt-inside-inner-col,.kadence-column23993_77231c-03 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_77231c-03 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_77231c-03 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_77231c-03 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_77231c-03 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_77231c-03{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_77231c-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_77231c-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_77231c-03 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading23993_e0101c-48, .wp-block-kadence-advancedheading.kt-adv-heading23993_e0101c-48[data-kb-block=\"kb-adv-heading23993_e0101c-48\"]{margin-bottom:0px;font-size:31px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_e0101c-48 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_e0101c-48[data-kb-block=\"kb-adv-heading23993_e0101c-48\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_e0101c-48 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_e0101c-48[data-kb-block=\"kb-adv-heading23993_e0101c-48\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading23993_e0101c-48, .wp-block-kadence-advancedheading.kt-adv-heading23993_e0101c-48[data-kb-block=\"kb-adv-heading23993_e0101c-48\"]{font-size:20px;}}<\/style>\n<h2 class=\"kt-adv-heading23993_e0101c-48 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading23993_e0101c-48\"><strong><strong><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">NOTA D\u2019INTER\u00c8S ACAD\u00c8MIC<\/span><\/strong><\/strong><\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_1550f8-b5, .wp-block-kadence-advancedheading.kt-adv-heading23993_1550f8-b5[data-kb-block=\"kb-adv-heading23993_1550f8-b5\"]{margin-top:0px;font-size:20px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_1550f8-b5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_1550f8-b5[data-kb-block=\"kb-adv-heading23993_1550f8-b5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_1550f8-b5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_1550f8-b5[data-kb-block=\"kb-adv-heading23993_1550f8-b5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading23993_1550f8-b5 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading23993_1550f8-b5\"><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">Cada curs de nivell&nbsp;<strong>equ<span style=\"text-decoration: underline;\" class=\"ek-underline\">ival a 1 any escolar sencer<\/span>.<\/strong><\/span><\/h2>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_0deab6-86{margin-bottom:0px;}.kb-row-layout-id23993_0deab6-86 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_0deab6-86 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_0deab6-86 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:85px;padding-bottom:10px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_0deab6-86 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_0deab6-86 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_0deab6-86 > .kt-row-column-wrap{padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_0deab6-86 alignnone wp-block-kadence-rowlayout\" id=\"jovenes-verano\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_98cecd-44 > .kt-inside-inner-col,.kadence-column23993_98cecd-44 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_98cecd-44 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_98cecd-44 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_98cecd-44 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_98cecd-44 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_98cecd-44{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_98cecd-44 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_98cecd-44 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_98cecd-44\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading23993_b90a48-1a, .wp-block-kadence-advancedheading.kt-adv-heading23993_b90a48-1a[data-kb-block=\"kb-adv-heading23993_b90a48-1a\"]{margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-xl, 3rem);font-weight:600;font-style:normal;font-family:'Open Sans';}.wp-block-kadence-advancedheading.kt-adv-heading23993_b90a48-1a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_b90a48-1a[data-kb-block=\"kb-adv-heading23993_b90a48-1a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_b90a48-1a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_b90a48-1a[data-kb-block=\"kb-adv-heading23993_b90a48-1a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading23993_b90a48-1a wp-block-kadence-advancedheading has-central-palette-4-color has-text-color\" data-kb-block=\"kb-adv-heading23993_b90a48-1a\"><strong>Tria el teu curs d&#8217;estiu:<\/strong><\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_80dd3a-05{margin-bottom:0px;margin-top:0px;}.kb-row-layout-id23993_80dd3a-05 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_80dd3a-05 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_80dd3a-05 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_80dd3a-05 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_80dd3a-05 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_80dd3a-05 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_80dd3a-05 alignnone wp-block-kadence-rowlayout\" id=\"intensivos-verano\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_64a7b4-c9 > .kt-inside-inner-col,.kadence-column23993_64a7b4-c9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_64a7b4-c9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_64a7b4-c9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_64a7b4-c9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_64a7b4-c9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_64a7b4-c9{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_64a7b4-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_64a7b4-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_64a7b4-c9\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_b6c560-d3 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_b6c560-d3 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#4BAE50;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}.kt-info-box23993_b6c560-d3 .kt-blocks-info-box-link-wrap:hover{background:#4BAE50;}.kt-info-box23993_b6c560-d3 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_b6c560-d3 .kt-info-svg-icon-flip, .kt-info-box23993_b6c560-d3 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_b6c560-d3 .kt-blocks-info-box-media{color:#FFFFFF;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box23993_b6c560-d3 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#FFFFFF;background:transparent;border-color:#444444;}.kt-info-box23993_b6c560-d3 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:#FFFFFF;font-size:32px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_b6c560-d3 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:#FFFFFF;}.kt-info-box23993_b6c560-d3 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box23993_b6c560-d3 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_b6c560-d3 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_b6c560-d3 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_b6c560-d3 .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_b6c560-d3\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_sun kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"5\"\/><line x1=\"12\" y1=\"1\" x2=\"12\" y2=\"3\"\/><line x1=\"12\" y1=\"21\" x2=\"12\" y2=\"23\"\/><line x1=\"4.22\" y1=\"4.22\" x2=\"5.64\" y2=\"5.64\"\/><line x1=\"18.36\" y1=\"18.36\" x2=\"19.78\" y2=\"19.78\"\/><line x1=\"1\" y1=\"12\" x2=\"3\" y2=\"12\"\/><line x1=\"21\" y1=\"12\" x2=\"23\" y2=\"12\"\/><line x1=\"4.22\" y1=\"19.78\" x2=\"5.64\" y2=\"18.36\"\/><line x1=\"18.36\" y1=\"5.64\" x2=\"19.78\" y2=\"4.22\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">CURSOS INTENSIUS D\u2019UN NIVELL \u2013 Estiu 2026<\/h2><\/div><\/span><\/div>\n\n\n<style>.kt-accordion-id23993_61fd0d-e4 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id23993_61fd0d-e4 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#F2F2F2;padding-top:0px;padding-right:30px;padding-bottom:30px;padding-left:50px;}.kt-accordion-id23993_61fd0d-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;font-size:18px;line-height:24px;color:#555555;padding-top:30px;padding-right:30px;padding-bottom:50px;padding-left:70px;}.kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id23993_61fd0d-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_61fd0d-e4 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id23993_61fd0d-e4 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_61fd0d-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#212327;background:#F2F2F2;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#212327;}.kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#212327;}.kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_61fd0d-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#F2F2F2;}@media all and (max-width: 1024px){.kt-accordion-id23993_61fd0d-e4 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id23993_61fd0d-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_61fd0d-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_61fd0d-e4 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_61fd0d-e4 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_61fd0d-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id23993_61fd0d-e4 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id23993_61fd0d-e4 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id23993_61fd0d-e4 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_61fd0d-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_61fd0d-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_61fd0d-e4 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_61fd0d-e4 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_61fd0d-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone acordio\"><div class=\"kt-accordion-wrap kt-accordion-id23993_61fd0d-e4 kt-accordion-has-4-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrowcircle kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane23993_8ee8f1-03\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong><span class=\"ugb-highlight\" style=\"color: #00B8D6;\"><br><strong><span class=\"ugb-highlight\" style=\"color: #00B8D6;\">PER AVAN\u00c7AR<\/span> <span class=\"ugb-highlight\" style=\"color: #00B8D6;\"><strong><span class=\"ugb-highlight\" style=\"color: #00B8D6;\">1 CURS ACAD\u00c8MIC ANUAL<\/span><\/strong> EN NOM\u00c9S 5 SETMANES<\/span><\/strong>!<br><\/span><\/strong><br><strong>Nivells: <\/strong>Per a edats d&#8217;11 a 18 anys, tots els nivells fins a C2 Proficiency.<br><strong>Durada:<\/strong> 5 setmanes &#8211; del 25 juny al 29 juliol.<br><br><span class=\"ek-underline\" style=\"text-decoration: underline;\">M\u00e9s informaci\u00f3?<\/span><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"eplus-OgiBp0\"><strong>CURSOS ESTRUCTURATS <\/strong>seguint els nivells homologats del Marc Europeu Com\u00fa de Refer\u00e8ncia per a les lleng\u00fces (MECR).<\/p>\n\n\n\n<p class=\"eplus-lfv3vK\"><strong>INCLOUEN:<\/strong> Classes di\u00e0ries + <em>Friday<\/em> <em>Fun Hour!<\/em> (Teens A2 i B1) + 2 ex\u00e0menes + <em>Homework<\/em>&nbsp;i&nbsp;<em>writing&nbsp;tasks<\/em>&nbsp;+ Seguiment personalitzat amb informes i entrevista personal amb fam\u00edlies via Zoom + Assessorament sobre l&#8217;examen oficial de Cambridge English corresponent.<br><br><strong>HORARIS:<\/strong> De dilluns a divendres en horari de mat\u00ed o tarda, segons nivell.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_940124-0a, .wp-block-kadence-advancedheading.kt-adv-heading23993_940124-0a[data-kb-block=\"kb-adv-heading23993_940124-0a\"]{padding-top:40px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_940124-0a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_940124-0a[data-kb-block=\"kb-adv-heading23993_940124-0a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_940124-0a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_940124-0a[data-kb-block=\"kb-adv-heading23993_940124-0a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading23993_940124-0a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_940124-0a\">T&#8217;interessa aquest curs?<\/h4>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns23993_c1cdff-ff, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns23993_c1cdff-ff, .wp-block-kadence-advancedbtn.kb-btns23993_c1cdff-ff, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns23993_c1cdff-ff{margin-top:0px;margin-right:0px;margin-bottom:30px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns23993_c1cdff-ff{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns23993_c1cdff-ff .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns23993_c1cdff-ff\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn23993_98f3ae-7a.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn23993_98f3ae-7a.kb-button{color:#FFFFFF;background:#003C5A;border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_98f3ae-7a.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_98f3ae-7a.kb-button:focus{color:#ffffff;background:#00B8D6;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_98f3ae-7a.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_98f3ae-7a.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_98f3ae-7a.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn23993_98f3ae-7a.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_98f3ae-7a.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_98f3ae-7a.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn23993_98f3ae-7a kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/\/#ancora2\"><span class=\"kt-btn-inner-text\">Informa-te\u2019n ara!<\/span><\/a><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_7fa291-00{margin-bottom:0px;margin-top:0px;}.kb-row-layout-id23993_7fa291-00 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_7fa291-00 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_7fa291-00 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_7fa291-00 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_7fa291-00 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_7fa291-00 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_7fa291-00 alignnone wp-block-kadence-rowlayout\" id=\"consolidacion-verano\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_5465b2-1b > .kt-inside-inner-col,.kadence-column23993_5465b2-1b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_5465b2-1b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_5465b2-1b > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_5465b2-1b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_5465b2-1b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_5465b2-1b{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_5465b2-1b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_5465b2-1b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_5465b2-1b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_4cb1c7-54 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_4cb1c7-54 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#4BAE50;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}.kt-info-box23993_4cb1c7-54 .kt-blocks-info-box-link-wrap:hover{background:#4BAE50;}.kt-info-box23993_4cb1c7-54 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_4cb1c7-54 .kt-info-svg-icon-flip, .kt-info-box23993_4cb1c7-54 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_4cb1c7-54 .kt-blocks-info-box-media{color:#FFFFFF;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box23993_4cb1c7-54 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#FFFFFF;background:transparent;border-color:#444444;}.kt-info-box23993_4cb1c7-54 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:#FFFFFF;font-size:32px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_4cb1c7-54 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:#FFFFFF;}.kt-info-box23993_4cb1c7-54 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box23993_4cb1c7-54 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_4cb1c7-54 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_4cb1c7-54 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_4cb1c7-54 .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_4cb1c7-54\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_sun kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"5\"\/><line x1=\"12\" y1=\"1\" x2=\"12\" y2=\"3\"\/><line x1=\"12\" y1=\"21\" x2=\"12\" y2=\"23\"\/><line x1=\"4.22\" y1=\"4.22\" x2=\"5.64\" y2=\"5.64\"\/><line x1=\"18.36\" y1=\"18.36\" x2=\"19.78\" y2=\"19.78\"\/><line x1=\"1\" y1=\"12\" x2=\"3\" y2=\"12\"\/><line x1=\"21\" y1=\"12\" x2=\"23\" y2=\"12\"\/><line x1=\"4.22\" y1=\"19.78\" x2=\"5.64\" y2=\"18.36\"\/><line x1=\"18.36\" y1=\"5.64\" x2=\"19.78\" y2=\"4.22\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">MIG INTENSIU \u2013 Estiu 2026<\/h2><\/div><\/span><\/div>\n\n\n<style>.kt-accordion-id23993_ec6605-d0 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id23993_ec6605-d0 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#F2F2F2;padding-top:0px;padding-right:30px;padding-bottom:30px;padding-left:50px;}.kt-accordion-id23993_ec6605-d0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;font-size:18px;line-height:24px;color:#555555;padding-top:30px;padding-right:30px;padding-bottom:50px;padding-left:70px;}.kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id23993_ec6605-d0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_ec6605-d0 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id23993_ec6605-d0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_ec6605-d0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#212327;background:#F2F2F2;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#212327;}.kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#212327;}.kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_ec6605-d0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#F2F2F2;}@media all and (max-width: 1024px){.kt-accordion-id23993_ec6605-d0 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id23993_ec6605-d0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_ec6605-d0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_ec6605-d0 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_ec6605-d0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_ec6605-d0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id23993_ec6605-d0 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id23993_ec6605-d0 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id23993_ec6605-d0 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_ec6605-d0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_ec6605-d0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_ec6605-d0 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_ec6605-d0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_ec6605-d0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone acordio\"><div class=\"kt-accordion-wrap kt-accordion-id23993_ec6605-d0 kt-accordion-has-4-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrowcircle kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane23993_821cd1-a3\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong><span class=\"ugb-highlight\" style=\"color: #00B8D6;\"><br>PER CONSOLIDAR ALL\u00d2 APR\u00c8S EN EL TEU NIVELL.<br><\/span><\/strong><br><strong>Nivells:<\/strong> Per a edats d&#8217;11 a 18 anys, tots els nivells fins a C2&nbsp;Proficiency.<br><strong>Durada: <\/strong>2 setmanes i mitja &#8211; del 25 juny a l&#8217;10 juliol o del 13 juliol al 29 juliol.<br><br><span class=\"ek-underline\" style=\"text-decoration: underline;\">M\u00e9s informaci\u00f3?<\/span><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"eplus-aIyjvr\"><strong>CURSOS ideals per a alumnes que volen refor\u00e7ar<\/strong> al llarg de l&#8217;estiu el seu nivell d&#8217;angl\u00e8s i els coneixements adquirits, per\u00f2 no necessiten avan\u00e7ar tot un curs.<\/p>\n\n\n\n<p class=\"eplus-mV1mWL\"><strong>INCLOUEN: <\/strong>Classes di\u00e0ries + <em>Friday<\/em> <em>Fun Hour!<\/em> (Teens A2 i B1) + Examen final +&nbsp;<em>Homework&nbsp;<\/em>i&nbsp;<em>writing&nbsp;tasks<\/em>&nbsp;+ Seguiment personalitzat amb informe i entrevista personal amb la fam\u00edlia via Zoom a final de curs.<\/p>\n\n\n\n<p class=\"eplus-Nw3ccY\"><strong>HORARIS:<\/strong> De dilluns a divendres en horari de mat\u00ed o tarda, segons nivell.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_a75d9c-7a, .wp-block-kadence-advancedheading.kt-adv-heading23993_a75d9c-7a[data-kb-block=\"kb-adv-heading23993_a75d9c-7a\"]{padding-top:40px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_a75d9c-7a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_a75d9c-7a[data-kb-block=\"kb-adv-heading23993_a75d9c-7a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_a75d9c-7a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_a75d9c-7a[data-kb-block=\"kb-adv-heading23993_a75d9c-7a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading23993_a75d9c-7a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_a75d9c-7a\">T&#8217;interessa aquest curs?<\/h4>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns23993_c33ae7-9b, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns23993_c33ae7-9b, .wp-block-kadence-advancedbtn.kb-btns23993_c33ae7-9b, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns23993_c33ae7-9b{margin-top:0px;margin-right:0px;margin-bottom:30px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns23993_c33ae7-9b{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns23993_c33ae7-9b .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns23993_c33ae7-9b\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn23993_b310c2-b0.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn23993_b310c2-b0.kb-button{color:#FFFFFF;background:#003C5A;border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_b310c2-b0.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_b310c2-b0.kb-button:focus{color:#ffffff;background:#00B8D6;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_b310c2-b0.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_b310c2-b0.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_b310c2-b0.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn23993_b310c2-b0.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_b310c2-b0.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_b310c2-b0.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn23993_b310c2-b0 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/\/#ancora2\"><span class=\"kt-btn-inner-text\">Informa-te\u2019n ara!<\/span><\/a><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_bce249-e0{margin-bottom:0px;margin-top:0px;}.kb-row-layout-id23993_bce249-e0 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_bce249-e0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_bce249-e0 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_bce249-e0 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_bce249-e0 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_bce249-e0 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_bce249-e0 alignnone wp-block-kadence-rowlayout\" id=\"examenes-verano\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_90ff6c-bc > .kt-inside-inner-col,.kadence-column23993_90ff6c-bc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_90ff6c-bc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_90ff6c-bc > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_90ff6c-bc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_90ff6c-bc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_90ff6c-bc{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_90ff6c-bc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_90ff6c-bc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_90ff6c-bc\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_652079-7c .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_652079-7c .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#4BAE50;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}.kt-info-box23993_652079-7c .kt-blocks-info-box-link-wrap:hover{background:#4BAE50;}.kt-info-box23993_652079-7c .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_652079-7c .kt-info-svg-icon-flip, .kt-info-box23993_652079-7c .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_652079-7c .kt-blocks-info-box-media{color:#FFFFFF;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box23993_652079-7c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#FFFFFF;background:transparent;border-color:#444444;}.kt-info-box23993_652079-7c .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:#FFFFFF;font-size:32px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_652079-7c .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:#FFFFFF;}.kt-info-box23993_652079-7c .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box23993_652079-7c .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_652079-7c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_652079-7c .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_652079-7c .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_652079-7c\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_sun kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"5\"\/><line x1=\"12\" y1=\"1\" x2=\"12\" y2=\"3\"\/><line x1=\"12\" y1=\"21\" x2=\"12\" y2=\"23\"\/><line x1=\"4.22\" y1=\"4.22\" x2=\"5.64\" y2=\"5.64\"\/><line x1=\"18.36\" y1=\"18.36\" x2=\"19.78\" y2=\"19.78\"\/><line x1=\"1\" y1=\"12\" x2=\"3\" y2=\"12\"\/><line x1=\"21\" y1=\"12\" x2=\"23\" y2=\"12\"\/><line x1=\"4.22\" y1=\"19.78\" x2=\"5.64\" y2=\"18.36\"\/><line x1=\"18.36\" y1=\"5.64\" x2=\"19.78\" y2=\"4.22\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">CURSOS T\u00c8CNIQUES D&#8217;EXAMEN \u2013 Estiu 2026<\/h2><\/div><\/span><\/div>\n\n\n<style>.kt-accordion-id23993_471d78-3d .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id23993_471d78-3d .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#F2F2F2;padding-top:0px;padding-right:30px;padding-bottom:30px;padding-left:50px;}.kt-accordion-id23993_471d78-3d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;font-size:18px;line-height:24px;color:#555555;padding-top:30px;padding-right:30px;padding-bottom:50px;padding-left:70px;}.kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id23993_471d78-3d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_471d78-3d .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id23993_471d78-3d .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_471d78-3d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#212327;background:#F2F2F2;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#212327;}.kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#212327;}.kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_471d78-3d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#F2F2F2;}@media all and (max-width: 1024px){.kt-accordion-id23993_471d78-3d .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id23993_471d78-3d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_471d78-3d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_471d78-3d .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_471d78-3d .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_471d78-3d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id23993_471d78-3d .kt-accordion-inner-wrap{display:block;}.kt-accordion-id23993_471d78-3d .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id23993_471d78-3d .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_471d78-3d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_471d78-3d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_471d78-3d .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_471d78-3d .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_471d78-3d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone acordio\"><div class=\"kt-accordion-wrap kt-accordion-id23993_471d78-3d kt-accordion-has-4-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrowcircle kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane23993_9e8dcb-ed\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong><span class=\"ugb-highlight\" style=\"color: #00B8D6;\"><br><\/span><\/strong><span class=\"ugb-highlight\" style=\"color: #00B8D6;\"><strong>AUGMENTA LES TEVES OPCIONS PER A L\u2019EXAMEN OFICIAL DEL JULIOL!<br><\/strong><\/span><br><strong>Nivells: <\/strong>B2&nbsp;First,&nbsp;C1&nbsp;Advanced i C2 Proficiency.<br><strong>Durada:<\/strong> 30 hores en total &#8211; 5 setmanes.<br><br><span class=\"ek-underline\" style=\"text-decoration: underline;\">M\u00e9s informaci\u00f3?<\/span><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"eplus-qXlyRh\"><strong>CURSOS DE T\u00c8CNIQUES ESPEC\u00cdFIQUES<\/strong> d&#8217;examen i <strong>ERRORS COMUNS<\/strong> que cal evitar en els ex\u00e0mens oficials, aix\u00ed com per aprendre a gestionar el temps i saber qu\u00e8 s&#8217;espera de l&#8217;alumne examinat.<\/p>\n\n\n\n<p class=\"eplus-mUTfN8\"><strong>INCLOU:<\/strong>&nbsp;6h&nbsp;de classes setmanals + 4 ex\u00e0mens complets + 1 examen simulacre + Pr\u00e0ctica i correcci\u00f3 de les <em>writing&nbsp;tasks<\/em>&nbsp;+ Avaluaci\u00f3 i seguiment personalitzat per identificar quins punts us cal millorar de cara a l\u2019examen.<\/p>\n\n\n\n<p><strong>HORARIS:<\/strong> Dos dies a la setmana en horari de mat\u00ed o tarda, segons nivell.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_b2eeb3-84, .wp-block-kadence-advancedheading.kt-adv-heading23993_b2eeb3-84[data-kb-block=\"kb-adv-heading23993_b2eeb3-84\"]{padding-top:40px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_b2eeb3-84 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_b2eeb3-84[data-kb-block=\"kb-adv-heading23993_b2eeb3-84\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_b2eeb3-84 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_b2eeb3-84[data-kb-block=\"kb-adv-heading23993_b2eeb3-84\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading23993_b2eeb3-84 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_b2eeb3-84\">T&#8217;interessa aquest curs?<\/h4>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns23993_1aaaf5-a9, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns23993_1aaaf5-a9, .wp-block-kadence-advancedbtn.kb-btns23993_1aaaf5-a9, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns23993_1aaaf5-a9{margin-top:0px;margin-right:0px;margin-bottom:30px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns23993_1aaaf5-a9{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns23993_1aaaf5-a9 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns23993_1aaaf5-a9\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn23993_d4deb4-87.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn23993_d4deb4-87.kb-button{color:#FFFFFF;background:#003C5A;border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_d4deb4-87.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_d4deb4-87.kb-button:focus{color:#ffffff;background:#00B8D6;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_d4deb4-87.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_d4deb4-87.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_d4deb4-87.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn23993_d4deb4-87.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_d4deb4-87.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_d4deb4-87.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn23993_d4deb4-87 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/\/#ancora2\"><span class=\"kt-btn-inner-text\">Informa-te\u2019n ara!<\/span><\/a><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_57d4fb-d5{margin-bottom:0px;margin-top:0px;}.kb-row-layout-id23993_57d4fb-d5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_57d4fb-d5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_57d4fb-d5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_57d4fb-d5 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_57d4fb-d5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_57d4fb-d5 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_57d4fb-d5 alignnone wp-block-kadence-rowlayout\" id=\"particulares-verano\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_7e62f0-79 > .kt-inside-inner-col,.kadence-column23993_7e62f0-79 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_7e62f0-79 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_7e62f0-79 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_7e62f0-79 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_7e62f0-79 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_7e62f0-79{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_7e62f0-79 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_7e62f0-79 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_7e62f0-79 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_db8615-62 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_db8615-62 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#4BAE50;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}.kt-info-box23993_db8615-62 .kt-blocks-info-box-link-wrap:hover{background:#4BAE50;}.kt-info-box23993_db8615-62 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_db8615-62 .kt-info-svg-icon-flip, .kt-info-box23993_db8615-62 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_db8615-62 .kt-blocks-info-box-media{color:#FFFFFF;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box23993_db8615-62 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#FFFFFF;background:transparent;border-color:#444444;}.kt-info-box23993_db8615-62 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:#FFFFFF;font-size:32px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_db8615-62 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:#FFFFFF;}.kt-info-box23993_db8615-62 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box23993_db8615-62 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_db8615-62 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_db8615-62 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_db8615-62 .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_db8615-62\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_sun kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"5\"\/><line x1=\"12\" y1=\"1\" x2=\"12\" y2=\"3\"\/><line x1=\"12\" y1=\"21\" x2=\"12\" y2=\"23\"\/><line x1=\"4.22\" y1=\"4.22\" x2=\"5.64\" y2=\"5.64\"\/><line x1=\"18.36\" y1=\"18.36\" x2=\"19.78\" y2=\"19.78\"\/><line x1=\"1\" y1=\"12\" x2=\"3\" y2=\"12\"\/><line x1=\"21\" y1=\"12\" x2=\"23\" y2=\"12\"\/><line x1=\"4.22\" y1=\"19.78\" x2=\"5.64\" y2=\"18.36\"\/><line x1=\"18.36\" y1=\"5.64\" x2=\"19.78\" y2=\"4.22\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">CLASSES PARTICULARS \u2013 Estiu 2026<\/h2><\/div><\/span><\/div>\n\n\n<style>.kt-accordion-id23993_093ea4-e4 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id23993_093ea4-e4 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#F2F2F2;padding-top:0px;padding-right:30px;padding-bottom:30px;padding-left:50px;}.kt-accordion-id23993_093ea4-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;font-size:18px;line-height:24px;color:#555555;padding-top:30px;padding-right:30px;padding-bottom:50px;padding-left:70px;}.kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id23993_093ea4-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_093ea4-e4 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id23993_093ea4-e4 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_093ea4-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#212327;background:#F2F2F2;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#212327;}.kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#212327;}.kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_093ea4-e4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#F2F2F2;}@media all and (max-width: 1024px){.kt-accordion-id23993_093ea4-e4 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id23993_093ea4-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_093ea4-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_093ea4-e4 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_093ea4-e4 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_093ea4-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id23993_093ea4-e4 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id23993_093ea4-e4 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id23993_093ea4-e4 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_093ea4-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_093ea4-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_093ea4-e4 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_093ea4-e4 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_093ea4-e4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone acordio\"><div class=\"kt-accordion-wrap kt-accordion-id23993_093ea4-e4 kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrowcircle kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane23993_f33ffc-be\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong><span class=\"ugb-highlight\" style=\"color: #00B8D6;\"><br><\/span><\/strong><span class=\"ugb-highlight\" style=\"color: #00B8D6;\"><strong>INDIVIDUALS O EN GRUP REDU\u00cfT (FINS A 4 PERSONES)<\/strong><\/span><br><br><strong>Nivells: <\/strong>Per a tots els nivells.<br><strong>Durada: <\/strong>A partir d&#8217;1 h\/setmana.<br><br><span class=\"ek-underline\" style=\"text-decoration: underline;\">M\u00e9s informaci\u00f3<\/span><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"eplus-qizyd0\"><strong>LES CLASSES PARTICULARS<\/strong> permeten <strong>ajustar el contingut i l\u2019enfocament a mida, segons les necessitats de l&#8217;alumne<\/strong> i adaptant-les al seu <strong>ritme individual<\/strong>. Per tant, s\u00f3n ideals per als alumnes que desitgin aprendre de manera accelerada, tinguin un rendiment inferior en les classes de grup (per exemple, per timidesa o d\u00e8ficit d&#8217;atenci\u00f3) o tinguin disponibilitat d&#8217;horaris redu\u00efda. Tamb\u00e9 s\u00f3n ideals per als joves que necessiten un refor\u00e7 de l&#8217;idioma.<\/p>\n\n\n\n<p class=\"eplus-HCiFSh\"><strong>HORARIS<\/strong> i durada de les classes a convenir, segons les necessitats de l&#8217;alumne.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_f6deb3-15, .wp-block-kadence-advancedheading.kt-adv-heading23993_f6deb3-15[data-kb-block=\"kb-adv-heading23993_f6deb3-15\"]{padding-top:40px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_f6deb3-15 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_f6deb3-15[data-kb-block=\"kb-adv-heading23993_f6deb3-15\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_f6deb3-15 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_f6deb3-15[data-kb-block=\"kb-adv-heading23993_f6deb3-15\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading23993_f6deb3-15 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_f6deb3-15\">T&#8217;interessa aquest curs?<\/h4>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns23993_9b7ad3-05, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns23993_9b7ad3-05, .wp-block-kadence-advancedbtn.kb-btns23993_9b7ad3-05, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns23993_9b7ad3-05{margin-top:0px;margin-right:0px;margin-bottom:30px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns23993_9b7ad3-05{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns23993_9b7ad3-05 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns23993_9b7ad3-05\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn23993_4156c6-2f.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn23993_4156c6-2f.kb-button{color:#FFFFFF;background:#003C5A;border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_4156c6-2f.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_4156c6-2f.kb-button:focus{color:#ffffff;background:#00B8D6;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_4156c6-2f.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_4156c6-2f.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_4156c6-2f.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn23993_4156c6-2f.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_4156c6-2f.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_4156c6-2f.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn23993_4156c6-2f kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/\/#ancora2\"><span class=\"kt-btn-inner-text\">Informa-te\u2019n ara!<\/span><\/a><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_a4b6cc-72{margin-bottom:0px;}.kb-row-layout-id23993_a4b6cc-72 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_a4b6cc-72 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_a4b6cc-72 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:85px;padding-bottom:10px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_a4b6cc-72 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_a4b6cc-72 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_a4b6cc-72 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_a4b6cc-72 alignnone wp-block-kadence-rowlayout\" id=\"jovenes-inviero\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_0f6111-e4 > .kt-inside-inner-col,.kadence-column23993_0f6111-e4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_0f6111-e4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_0f6111-e4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_0f6111-e4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_0f6111-e4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_0f6111-e4{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_0f6111-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_0f6111-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_0f6111-e4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading23993_9d6014-f9, .wp-block-kadence-advancedheading.kt-adv-heading23993_9d6014-f9[data-kb-block=\"kb-adv-heading23993_9d6014-f9\"]{margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-xl, 3rem);font-weight:600;font-style:normal;font-family:'Open Sans';}.wp-block-kadence-advancedheading.kt-adv-heading23993_9d6014-f9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_9d6014-f9[data-kb-block=\"kb-adv-heading23993_9d6014-f9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_9d6014-f9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_9d6014-f9[data-kb-block=\"kb-adv-heading23993_9d6014-f9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading23993_9d6014-f9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_9d6014-f9\"><strong>I de setembre a juny:<\/strong><\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_38aaef-cd{margin-bottom:0px;margin-top:0px;}.kb-row-layout-id23993_38aaef-cd > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_38aaef-cd > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_38aaef-cd > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_38aaef-cd > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_38aaef-cd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_38aaef-cd > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_38aaef-cd alignnone wp-block-kadence-rowlayout\" id=\"jovenes-anual\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_8440b1-55 > .kt-inside-inner-col,.kadence-column23993_8440b1-55 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_8440b1-55 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_8440b1-55 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_8440b1-55 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_8440b1-55 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_8440b1-55{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_8440b1-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_8440b1-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_8440b1-55 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_dca2e4-34 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_dca2e4-34 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#003C5A;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}.kt-info-box23993_dca2e4-34 .kt-blocks-info-box-link-wrap:hover{background:#003C5A;}.kt-info-box23993_dca2e4-34.wp-block-kadence-infobox{max-width:100%;}.kt-info-box23993_dca2e4-34 .kadence-info-box-image-inner-intrisic-container{max-width:75px;}.kt-info-box23993_dca2e4-34 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:68%;width:400px;height:0px;max-width:100%;}.kt-info-box23993_dca2e4-34 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_dca2e4-34 .kt-info-svg-icon-flip, .kt-info-box23993_dca2e4-34 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_dca2e4-34 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box23993_dca2e4-34 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box23993_dca2e4-34 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:#FFFFFF;font-size:32px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_dca2e4-34 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:#FFFFFF;}.kt-info-box23993_dca2e4-34 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box23993_dca2e4-34 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_dca2e4-34 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_dca2e4-34 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_dca2e4-34 .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);}.kt-info-box23993_dca2e4-34 .kt-blocks-info-box-link-wrap{display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box23993_dca2e4-34 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_dca2e4-34\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png\" alt=\"vimet-blanc\" width=\"400\" height=\"272\" class=\"kt-info-box-image wp-image-23865\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc-300x204.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">CURS ANUAL d\u2019un nivell 2026-27<\/h2><\/div><\/span><\/div>\n\n\n<style>.kt-accordion-id23993_aa6057-fb .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:1px;}.kt-accordion-id23993_aa6057-fb .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#F2F2F2;padding-top:0px;padding-right:30px;padding-bottom:30px;padding-left:50px;}.kt-accordion-id23993_aa6057-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;font-size:18px;line-height:24px;color:#555555;padding-top:30px;padding-right:30px;padding-bottom:50px;padding-left:70px;}.kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id23993_aa6057-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_aa6057-fb .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id23993_aa6057-fb .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_aa6057-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#212327;background:#F2F2F2;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#212327;}.kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#212327;}.kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_aa6057-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#F2F2F2;}@media all and (max-width: 1024px){.kt-accordion-id23993_aa6057-fb .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id23993_aa6057-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_aa6057-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_aa6057-fb .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_aa6057-fb .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_aa6057-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id23993_aa6057-fb .kt-accordion-inner-wrap{display:block;}.kt-accordion-id23993_aa6057-fb .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:1px;}.kt-accordion-id23993_aa6057-fb .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_aa6057-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_aa6057-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_aa6057-fb .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_aa6057-fb .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_aa6057-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone acordio\"><div class=\"kt-accordion-wrap kt-accordion-id23993_aa6057-fb kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrowcircle kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"0\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane23993_2f648a-68 obrir\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong><span class=\"ugb-highlight\" style=\"color: #00B8D6;\">AMB MATR\u00cdCULA OBERTA TOT L&#8217;ANY!<br><\/span><\/strong><br><strong>Nivells:<\/strong> A2&nbsp;Key&nbsp;\u00b7 B1&nbsp;Preliminary&nbsp;\u00b7 B2&nbsp;First&nbsp;\u00b7 C1&nbsp;Advanced&nbsp;\u00b7 C2&nbsp;Proficiency.<br><strong>Durada:<\/strong> 100 hores en total &#8211; 3h\/setmana de setembre a juny.<br><br><span class=\"ek-underline\" style=\"text-decoration: underline;\">M\u00e9s informaci\u00f3?<\/span><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"eplus-dhNnfA\"><strong>CURSOS ESTRUCTURATS<\/strong> seguint els nivells homologats del Marc Europeu Com\u00fa de Refer\u00e8ncia per a les lleng\u00fces (MECR).<br><br><strong>INCLOU:<\/strong><br>Classes setmanals + Tests peri\u00f2dics + 2 ex\u00e0mens +&nbsp;<em>Homework&nbsp;<\/em>i&nbsp;<em>writing&nbsp;tasks<\/em>&nbsp;+ Seguiment personalitzat amb informes i entrevistes amb les fam\u00edlies via Zoom a mig curs i a final de curs + Assessorament sobre l&#8217;examen oficial de Cambridge English corresponent.<\/p>\n\n\n\n<p><strong>HORARI<\/strong>: Pots triar fer les 3 hores semanals en 1 o 2 dies, en horari de mat\u00ed o tarda, segons nivell.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_8168f9-6c, .wp-block-kadence-advancedheading.kt-adv-heading23993_8168f9-6c[data-kb-block=\"kb-adv-heading23993_8168f9-6c\"]{padding-top:40px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_8168f9-6c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_8168f9-6c[data-kb-block=\"kb-adv-heading23993_8168f9-6c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_8168f9-6c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_8168f9-6c[data-kb-block=\"kb-adv-heading23993_8168f9-6c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading23993_8168f9-6c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_8168f9-6c\">T&#8217;interessa aquest curs?<\/h4>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns23993_22f38e-f5, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns23993_22f38e-f5, .wp-block-kadence-advancedbtn.kb-btns23993_22f38e-f5, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns23993_22f38e-f5{margin-top:0px;margin-right:0px;margin-bottom:30px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns23993_22f38e-f5{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns23993_22f38e-f5 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns23993_22f38e-f5\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn23993_547475-13.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn23993_547475-13.kb-button{color:#FFFFFF;background:#003C5A;border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_547475-13.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_547475-13.kb-button:focus{color:#ffffff;background:#00B8D6;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_547475-13.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_547475-13.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_547475-13.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn23993_547475-13.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_547475-13.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_547475-13.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn23993_547475-13 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/\/#ancora2\"><span class=\"kt-btn-inner-text\">Informa-te\u2019n ara!<\/span><\/a><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_ef1700-34{margin-bottom:0px;margin-top:0px;}.kb-row-layout-id23993_ef1700-34 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_ef1700-34 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_ef1700-34 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_ef1700-34 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_ef1700-34 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_ef1700-34 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_ef1700-34 alignnone wp-block-kadence-rowlayout\" id=\"jovenes-semintensivo\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_9a955f-4b > .kt-inside-inner-col,.kadence-column23993_9a955f-4b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_9a955f-4b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_9a955f-4b > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_9a955f-4b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_9a955f-4b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_9a955f-4b{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_9a955f-4b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_9a955f-4b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_9a955f-4b inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_303b74-96 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_303b74-96 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#003C5A;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}.kt-info-box23993_303b74-96 .kt-blocks-info-box-link-wrap:hover{background:#003C5A;}.kt-info-box23993_303b74-96.wp-block-kadence-infobox{max-width:100%;}.kt-info-box23993_303b74-96 .kadence-info-box-image-inner-intrisic-container{max-width:75px;}.kt-info-box23993_303b74-96 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:68%;width:400px;height:0px;max-width:100%;}.kt-info-box23993_303b74-96 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_303b74-96 .kt-info-svg-icon-flip, .kt-info-box23993_303b74-96 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_303b74-96 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box23993_303b74-96 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box23993_303b74-96 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:#FFFFFF;font-size:32px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_303b74-96 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:#FFFFFF;}.kt-info-box23993_303b74-96 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box23993_303b74-96 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_303b74-96 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_303b74-96 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_303b74-96 .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);}.kt-info-box23993_303b74-96 .kt-blocks-info-box-link-wrap{display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box23993_303b74-96 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_303b74-96\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png\" alt=\"vimet-blanc\" width=\"400\" height=\"272\" class=\"kt-info-box-image wp-image-23865\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc-300x204.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">CURS SEMIINTENSIU 2026-27<\/h2><\/div><\/span><\/div>\n\n\n<style>.kt-accordion-id23993_d02856-6d .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:1px;}.kt-accordion-id23993_d02856-6d .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#F2F2F2;padding-top:0px;padding-right:30px;padding-bottom:30px;padding-left:50px;}.kt-accordion-id23993_d02856-6d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;font-size:18px;line-height:24px;color:#555555;padding-top:30px;padding-right:30px;padding-bottom:50px;padding-left:70px;}.kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id23993_d02856-6d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_d02856-6d .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id23993_d02856-6d .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_d02856-6d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#212327;background:#F2F2F2;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#212327;}.kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#212327;}.kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_d02856-6d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#F2F2F2;}@media all and (max-width: 1024px){.kt-accordion-id23993_d02856-6d .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id23993_d02856-6d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_d02856-6d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_d02856-6d .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_d02856-6d .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_d02856-6d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id23993_d02856-6d .kt-accordion-inner-wrap{display:block;}.kt-accordion-id23993_d02856-6d .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:1px;}.kt-accordion-id23993_d02856-6d .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_d02856-6d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_d02856-6d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_d02856-6d .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_d02856-6d .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_d02856-6d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone acordio\"><div class=\"kt-accordion-wrap kt-accordion-id23993_d02856-6d kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrowcircle kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"0\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane23993_423b0f-4a obrir\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><span class=\"ugb-highlight\" style=\"font-weight: bold; color: rgb(0, 184, 214);\">UN CURS ACAD\u00c8MIC ANUAL EN NOM\u00c9S 4 MESOS!<br><\/span><br><strong>Nivells:<\/strong> B2&nbsp;First&nbsp;\u00b7 C1&nbsp;Advanced.<br><strong>Durada:<\/strong> 6h\/setmana durant 15 setmanes.<br><br><span class=\"ek-underline\" style=\"text-decoration: underline;\">M\u00e9s informaci\u00f3?<\/span><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"eplus-dhNnfA\"><strong>CURSOS ESTRUCTURATS<\/strong> seguint els nivells homologats del Marc Europeu Com\u00fa de Refer\u00e8ncia per a les lleng\u00fces (MECR).<br><br><strong>INCLOU:<\/strong><br>Classes setmanals + Tests peri\u00f2dics + 2 ex\u00e0mens +&nbsp;<em>Homework&nbsp;<\/em>i&nbsp;<em>writing&nbsp;tasks<\/em>&nbsp;+ Seguiment personalitzat amb informes i entrevistes amb les fam\u00edlies via Zoom a mig curs i a final de curs + Assessorament sobre l&#8217;examen oficial de Cambridge English corresponent.<\/p>\n\n\n\n<p><strong>HORARI<\/strong>: Dues classes de 3 hores en horari de tarda.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_134413-66, .wp-block-kadence-advancedheading.kt-adv-heading23993_134413-66[data-kb-block=\"kb-adv-heading23993_134413-66\"]{padding-top:40px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_134413-66 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_134413-66[data-kb-block=\"kb-adv-heading23993_134413-66\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_134413-66 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_134413-66[data-kb-block=\"kb-adv-heading23993_134413-66\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading23993_134413-66 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_134413-66\">T&#8217;interessa aquest curs?<\/h4>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns23993_c728d5-ce, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns23993_c728d5-ce, .wp-block-kadence-advancedbtn.kb-btns23993_c728d5-ce, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns23993_c728d5-ce{margin-top:0px;margin-right:0px;margin-bottom:30px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns23993_c728d5-ce{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns23993_c728d5-ce .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns23993_c728d5-ce\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn23993_674b5a-39.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn23993_674b5a-39.kb-button{color:#FFFFFF;background:#003C5A;border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_674b5a-39.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_674b5a-39.kb-button:focus{color:#ffffff;background:#00B8D6;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_674b5a-39.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_674b5a-39.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_674b5a-39.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn23993_674b5a-39.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_674b5a-39.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_674b5a-39.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn23993_674b5a-39 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/\/#ancora2\"><span class=\"kt-btn-inner-text\">Informa-te\u2019n ara!<\/span><\/a><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_aa68e3-2d{margin-bottom:0px;margin-top:0px;}.kb-row-layout-id23993_aa68e3-2d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_aa68e3-2d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_aa68e3-2d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_aa68e3-2d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_aa68e3-2d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_aa68e3-2d > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_aa68e3-2d alignnone wp-block-kadence-rowlayout\" id=\"jovenes-examenes\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_d15201-ef > .kt-inside-inner-col,.kadence-column23993_d15201-ef > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_d15201-ef > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_d15201-ef > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_d15201-ef > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_d15201-ef > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_d15201-ef{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_d15201-ef > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_d15201-ef > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_d15201-ef inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_fa2466-cb .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_fa2466-cb .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#003C5A;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}.kt-info-box23993_fa2466-cb .kt-blocks-info-box-link-wrap:hover{background:#003C5A;}.kt-info-box23993_fa2466-cb.wp-block-kadence-infobox{max-width:100%;}.kt-info-box23993_fa2466-cb .kadence-info-box-image-inner-intrisic-container{max-width:55px;}.kt-info-box23993_fa2466-cb .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:68%;width:400px;height:0px;max-width:100%;}.kt-info-box23993_fa2466-cb .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_fa2466-cb .kt-info-svg-icon-flip, .kt-info-box23993_fa2466-cb .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_fa2466-cb .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box23993_fa2466-cb .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box23993_fa2466-cb .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:#FFFFFF;font-size:32px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_fa2466-cb .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:#FFFFFF;}.kt-info-box23993_fa2466-cb .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box23993_fa2466-cb .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_fa2466-cb .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_fa2466-cb .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_fa2466-cb .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_fa2466-cb\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png\" alt=\"vimet-blanc\" width=\"400\" height=\"272\" class=\"kt-info-box-image wp-image-23865\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc-300x204.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">CURSOS DE T\u00c8CNIQUES D&#8217;EXAMEN&nbsp;<\/h2><\/div><\/span><\/div>\n\n\n<style>.kt-accordion-id23993_e418b5-06 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id23993_e418b5-06 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#F2F2F2;padding-top:0px;padding-right:30px;padding-bottom:30px;padding-left:50px;}.kt-accordion-id23993_e418b5-06 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;font-size:18px;line-height:24px;color:#555555;padding-top:30px;padding-right:30px;padding-bottom:50px;padding-left:70px;}.kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id23993_e418b5-06 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_e418b5-06 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id23993_e418b5-06 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_e418b5-06 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#212327;background:#F2F2F2;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#212327;}.kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#212327;}.kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_e418b5-06:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#F2F2F2;}@media all and (max-width: 1024px){.kt-accordion-id23993_e418b5-06 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id23993_e418b5-06 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_e418b5-06 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_e418b5-06 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_e418b5-06 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_e418b5-06 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id23993_e418b5-06 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id23993_e418b5-06 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id23993_e418b5-06 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_e418b5-06 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_e418b5-06 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_e418b5-06 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_e418b5-06 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_e418b5-06 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone acordio\"><div class=\"kt-accordion-wrap kt-accordion-id23993_e418b5-06 kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrowcircle kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane23993_cdc46d-55\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><span class=\"ugb-highlight\" style=\"color: #00B8D6;\"><strong>AUGMENTA LES TEVES OPCIONS <strong><span class=\"ugb-highlight\" style=\"color: #00B8D6;\"><span class=\"uppercase\">a l&#8217;examen del DESEMBRE<\/span><\/span><\/strong>!<\/strong><br><\/span><br><strong>Nivells: <\/strong>B2\u00a0First i C1 Advanced.<br><strong>Durada:<\/strong> 30 hores en total &#8211; 3h\/setmana del setembre al novembre.<br><br><span class=\"ek-underline\" style=\"text-decoration: underline;\">M\u00e9s informaci\u00f3?<\/span><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"eplus-8l6d14\"><strong>CURSOS DE T\u00c8CNIQUES ESPEC\u00cdFIQUES<\/strong> d&#8217;examen i <strong>ERRORS COMUNS<\/strong> que cal evitar en els ex\u00e0mens oficials, aix\u00ed com per aprendre a gestionar el temps i saber qu\u00e8 s&#8217;espera de l&#8217;alumne examinat.<\/p>\n\n\n\n<p class=\"eplus-ISdT2n\"><strong>INCLOU<\/strong>: Classes setmanals amb realitzaci\u00f3 de tota la tipologia d&#8217;\u00e0rees de l&#8217;examen + Correcci\u00f3 de les&nbsp;<em>writing&nbsp;tasks<\/em>&nbsp;+ Examen simulacre + Avaluaci\u00f3 i seguiment personalitzat per identificar els punts que cal millorar de cara a l&#8217;examen.<\/p>\n\n\n\n<p><strong><strong>DATES I HORARIS<\/strong><\/strong> segons nivell.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_e52601-a6, .wp-block-kadence-advancedheading.kt-adv-heading23993_e52601-a6[data-kb-block=\"kb-adv-heading23993_e52601-a6\"]{padding-top:40px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_e52601-a6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_e52601-a6[data-kb-block=\"kb-adv-heading23993_e52601-a6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_e52601-a6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_e52601-a6[data-kb-block=\"kb-adv-heading23993_e52601-a6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading23993_e52601-a6 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_e52601-a6\">T&#8217;interessa aquest curs?<\/h4>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns23993_3249bc-f8, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns23993_3249bc-f8, .wp-block-kadence-advancedbtn.kb-btns23993_3249bc-f8, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns23993_3249bc-f8{margin-top:0px;margin-right:0px;margin-bottom:30px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns23993_3249bc-f8{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns23993_3249bc-f8 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns23993_3249bc-f8\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn23993_44fa31-a2.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn23993_44fa31-a2.kb-button{color:#FFFFFF;background:#003C5A;border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_44fa31-a2.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_44fa31-a2.kb-button:focus{color:#ffffff;background:#00B8D6;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_44fa31-a2.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_44fa31-a2.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_44fa31-a2.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn23993_44fa31-a2.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_44fa31-a2.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_44fa31-a2.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn23993_44fa31-a2 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/\/#ancora2\"><span class=\"kt-btn-inner-text\">Informa-te\u2019n ara!<\/span><\/a><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_96609c-60{margin-bottom:0px;margin-top:0px;}.kb-row-layout-id23993_96609c-60 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_96609c-60 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_96609c-60 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_96609c-60 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_96609c-60 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_96609c-60 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_96609c-60 alignnone wp-block-kadence-rowlayout\" id=\"jovenes-particulares\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_b04b65-9f > .kt-inside-inner-col,.kadence-column23993_b04b65-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_b04b65-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_b04b65-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_b04b65-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_b04b65-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_b04b65-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_b04b65-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_b04b65-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_b04b65-9f inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box23993_e3e14b-2f .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box23993_e3e14b-2f .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#003C5A;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}.kt-info-box23993_e3e14b-2f .kt-blocks-info-box-link-wrap:hover{background:#003C5A;}.kt-info-box23993_e3e14b-2f.wp-block-kadence-infobox{max-width:100%;}.kt-info-box23993_e3e14b-2f .kadence-info-box-image-inner-intrisic-container{max-width:55px;}.kt-info-box23993_e3e14b-2f .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:68%;width:400px;height:0px;max-width:100%;}.kt-info-box23993_e3e14b-2f .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box23993_e3e14b-2f .kt-info-svg-icon-flip, .kt-info-box23993_e3e14b-2f .kt-blocks-info-box-number{font-size:50px;}.kt-info-box23993_e3e14b-2f .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box23993_e3e14b-2f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box23993_e3e14b-2f .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:#FFFFFF;font-size:32px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_e3e14b-2f .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:#FFFFFF;}.kt-info-box23993_e3e14b-2f .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box23993_e3e14b-2f .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box23993_e3e14b-2f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box23993_e3e14b-2f .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 767px){.kt-info-box23993_e3e14b-2f .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box23993_e3e14b-2f\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png\" alt=\"vimet-blanc\" width=\"400\" height=\"272\" class=\"kt-info-box-image wp-image-23865\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc.png 400w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/vimet-blanc-300x204.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">CLASSES PARTICULARS 2026-27<\/h2><\/div><\/span><\/div>\n\n\n<style>.kt-accordion-id23993_3c2c27-48 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id23993_3c2c27-48 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#F2F2F2;padding-top:0px;padding-right:30px;padding-bottom:30px;padding-left:50px;}.kt-accordion-id23993_3c2c27-48 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;font-size:18px;line-height:24px;color:#555555;padding-top:30px;padding-right:30px;padding-bottom:50px;padding-left:70px;}.kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id23993_3c2c27-48 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_3c2c27-48 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id23993_3c2c27-48 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_3c2c27-48 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#212327;background:#F2F2F2;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#212327;}.kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#212327;}.kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id23993_3c2c27-48:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#F2F2F2;}@media all and (max-width: 1024px){.kt-accordion-id23993_3c2c27-48 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id23993_3c2c27-48 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_3c2c27-48 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_3c2c27-48 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id23993_3c2c27-48 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_3c2c27-48 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id23993_3c2c27-48 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id23993_3c2c27-48 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id23993_3c2c27-48 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_3c2c27-48 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#555555;border-top-style:solid;border-right-color:#555555;border-right-style:solid;border-bottom-color:#555555;border-bottom-style:solid;border-left-color:#555555;border-left-style:solid;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id23993_3c2c27-48 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id23993_3c2c27-48 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id23993_3c2c27-48 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id23993_3c2c27-48 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone acordio\"><div class=\"kt-accordion-wrap kt-accordion-id23993_3c2c27-48 kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrowcircle kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane23993_c6fd20-d3\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong><span class=\"ugb-highlight\" style=\"color: #00B8D6;\"><br><\/span><\/strong><span class=\"ugb-highlight\" style=\"color: #00B8D6;\"><strong>INDIVIDUALS O EN GRUP REDU\u00cfT (FINS A 4 PERSONES)<br><\/strong><\/span><br><strong>Nivells: <\/strong>Per a tots els nivells.<br><strong>Durada: <\/strong>A partir d&#8217;1 h\/setmana.<br><br><span class=\"ek-underline\" style=\"text-decoration: underline;\">M\u00e9s informaci\u00f3<\/span><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"eplus-qizyd0\"><strong>LES CLASSES PARTICULARS<\/strong> permeten <strong>ajustar el contingut i l\u2019enfocament a mida, segons les necessitats de l&#8217;alumne<\/strong> i adaptant-les al seu <strong>ritme individual<\/strong>. Per tant, s\u00f3n ideals per als alumnes que desitgin aprendre de manera accelerada, tinguin un rendiment inferior en les classes de grup (per exemple, per timidesa o d\u00e8ficit d&#8217;atenci\u00f3) o tinguin disponibilitat d&#8217;horaris redu\u00efda. Tamb\u00e9 s\u00f3n ideals per als joves que necessiten un refor\u00e7 de l&#8217;idioma.<\/p>\n\n\n\n<p class=\"eplus-HCiFSh\"><strong>HORARIS<\/strong> i durada de les classes a convenir, segons les necessitats de l&#8217;alumne.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_d6de4d-d9, .wp-block-kadence-advancedheading.kt-adv-heading23993_d6de4d-d9[data-kb-block=\"kb-adv-heading23993_d6de4d-d9\"]{padding-top:40px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_d6de4d-d9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_d6de4d-d9[data-kb-block=\"kb-adv-heading23993_d6de4d-d9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_d6de4d-d9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_d6de4d-d9[data-kb-block=\"kb-adv-heading23993_d6de4d-d9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading23993_d6de4d-d9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_d6de4d-d9\">T&#8217;interessa aquest curs?<\/h4>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns23993_c0877e-63, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns23993_c0877e-63, .wp-block-kadence-advancedbtn.kb-btns23993_c0877e-63, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns23993_c0877e-63{margin-top:0px;margin-right:0px;margin-bottom:30px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns23993_c0877e-63{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns23993_c0877e-63 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns23993_c0877e-63\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn23993_e180aa-22.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn23993_e180aa-22.kb-button{color:#FFFFFF;background:#003C5A;border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_e180aa-22.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_e180aa-22.kb-button:focus{color:#ffffff;background:#00B8D6;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_e180aa-22.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn23993_e180aa-22.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_e180aa-22.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn23993_e180aa-22.kb-button{border-top:0px solid #555555;border-right:0px solid #555555;border-bottom:0px solid #555555;border-left:0px solid #555555;}.wp-block-kadence-advancedbtn .kb-btn23993_e180aa-22.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn23993_e180aa-22.kb-button:focus{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn23993_e180aa-22 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/\/#ancora2\"><span class=\"kt-btn-inner-text\">Informa-te\u2019n ara!<\/span><\/a><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_9e04fa-d2{margin-bottom:0px;margin-top:0px;}.kb-row-layout-id23993_9e04fa-d2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_9e04fa-d2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_9e04fa-d2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:970px;margin-left:auto;margin-right:auto;padding-top:25px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_9e04fa-d2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_9e04fa-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_9e04fa-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_9e04fa-d2 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_4df971-eb > .kt-inside-inner-col,.kadence-column23993_4df971-eb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_4df971-eb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_4df971-eb > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_4df971-eb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_4df971-eb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_4df971-eb{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_4df971-eb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_4df971-eb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_4df971-eb\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_7546e4-32{margin-bottom:0px;margin-top:10px;}.kb-row-layout-id23993_7546e4-32 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_7546e4-32 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_7546e4-32 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:50px;padding-bottom:50px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_7546e4-32 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_7546e4-32 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_7546e4-32 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_7546e4-32 alignfull has-central-palette-2-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"pla-personal\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_fa9190-f9 > .kt-inside-inner-col,.kadence-column23993_fa9190-f9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_fa9190-f9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_fa9190-f9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_fa9190-f9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_fa9190-f9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_fa9190-f9{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_fa9190-f9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_fa9190-f9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_fa9190-f9 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading23993_b10f68-19, .wp-block-kadence-advancedheading.kt-adv-heading23993_b10f68-19[data-kb-block=\"kb-adv-heading23993_b10f68-19\"]{margin-bottom:10px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_b10f68-19 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_b10f68-19[data-kb-block=\"kb-adv-heading23993_b10f68-19\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_b10f68-19 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_b10f68-19[data-kb-block=\"kb-adv-heading23993_b10f68-19\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading23993_b10f68-19 wp-block-kadence-advancedheading has-central-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading23993_b10f68-19\"><strong><span class=\"ugb-highlight\" style=\"color: #FFFFFF;\">Pla d\u2019acompanyament Objectius Cambridge.<\/span><\/strong><\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_923292-3f, .wp-block-kadence-advancedheading.kt-adv-heading23993_923292-3f[data-kb-block=\"kb-adv-heading23993_923292-3f\"]{text-align:center;font-size:34px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_923292-3f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_923292-3f[data-kb-block=\"kb-adv-heading23993_923292-3f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_923292-3f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_923292-3f[data-kb-block=\"kb-adv-heading23993_923292-3f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading23993_923292-3f, .wp-block-kadence-advancedheading.kt-adv-heading23993_923292-3f[data-kb-block=\"kb-adv-heading23993_923292-3f\"]{font-size:18px;}}<\/style>\n<h3 class=\"kt-adv-heading23993_923292-3f wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_923292-3f\">M\u00e9s que un curs online, <strong>un complet pla de formaci\u00f3<\/strong>.<\/h3>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_782453-b3{margin-bottom:0px;}.kb-row-layout-id23993_782453-b3 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id23993_782453-b3 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id23993_782453-b3 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(40% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(60% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id23993_782453-b3 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_782453-b3 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id23993_782453-b3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_782453-b3 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column23993_014089-0e > .kt-inside-inner-col,.kadence-column23993_014089-0e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_014089-0e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_014089-0e > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_014089-0e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_014089-0e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_014089-0e{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_014089-0e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_014089-0e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_014089-0e inner-column-1\"><div class=\"kt-inside-inner-col\"><div class=\"wp-block-image eplus-1g2sJf\">\n<figure class=\"alignright size-full\"><a href=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Pla-Objectius-Cambridge-YL-CAT-25-26-joves.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"841\" src=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Pla-Objectius-Cambridge-YL-CAT-25-26-joves.jpg\" alt=\"Pla objectius cambridge yl cat 25 26 joves\" class=\"wp-image-29208\" srcset=\"https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Pla-Objectius-Cambridge-YL-CAT-25-26-joves.jpg 595w, https:\/\/zoom.cambridgeschool.com\/wp-content\/uploads\/Pla-Objectius-Cambridge-YL-CAT-25-26-joves-212x300.jpg 212w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/><\/a><\/figure>\n<\/div><\/div><\/div>\n\n\n<style>.kadence-column23993_8ced5e-fd > .kt-inside-inner-col,.kadence-column23993_8ced5e-fd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_8ced5e-fd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_8ced5e-fd > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_8ced5e-fd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_8ced5e-fd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_8ced5e-fd{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_8ced5e-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_8ced5e-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_8ced5e-fd inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading23993_ebbe0b-13, .wp-block-kadence-advancedheading.kt-adv-heading23993_ebbe0b-13[data-kb-block=\"kb-adv-heading23993_ebbe0b-13\"]{font-size:30px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_ebbe0b-13 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_ebbe0b-13[data-kb-block=\"kb-adv-heading23993_ebbe0b-13\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_ebbe0b-13 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_ebbe0b-13[data-kb-block=\"kb-adv-heading23993_ebbe0b-13\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading23993_ebbe0b-13, .wp-block-kadence-advancedheading.kt-adv-heading23993_ebbe0b-13[data-kb-block=\"kb-adv-heading23993_ebbe0b-13\"]{font-size:24px;}}<\/style>\n<h4 class=\"kt-adv-heading23993_ebbe0b-13 wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading23993_ebbe0b-13\"><strong><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">Perqu\u00e8 cada pas \u00e9s important.<\/span><\/strong><\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_fa6a4e-ac, .wp-block-kadence-advancedheading.kt-adv-heading23993_fa6a4e-ac[data-kb-block=\"kb-adv-heading23993_fa6a4e-ac\"]{font-size:21px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_fa6a4e-ac mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_fa6a4e-ac[data-kb-block=\"kb-adv-heading23993_fa6a4e-ac\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_fa6a4e-ac img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_fa6a4e-ac[data-kb-block=\"kb-adv-heading23993_fa6a4e-ac\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading23993_fa6a4e-ac, .wp-block-kadence-advancedheading.kt-adv-heading23993_fa6a4e-ac[data-kb-block=\"kb-adv-heading23993_fa6a4e-ac\"]{font-size:17px;}}<\/style>\n<h5 class=\"kt-adv-heading23993_fa6a4e-ac wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_fa6a4e-ac\">A Cambridge&nbsp;School&nbsp;us oferim m\u00e9s que un curs d&#8217;angl\u00e8s: tamb\u00e9 facilitem als vostres fills <strong>plans d&#8217;acompanyament <\/strong>personalitzats.<br><br>Amb el <em><strong>Pla: Objectius Cambridge<\/strong><\/em>, fixem metes personals en el temps i els guiem pas a pas per ajudar-los a assolir:<br><strong><br>&#8211; <span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">Nivell B2&nbsp;First<\/span><\/strong>&nbsp;a 3r &#8211; 4t d&#8217;ESO<strong><br>&#8211; <\/strong><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\"><strong>Nivell C1&nbsp;Advanced<\/strong>&nbsp;<\/span>a 1r &#8211; 2n de Batxillerat<\/h5>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_1303f7-ef, .wp-block-kadence-advancedheading.kt-adv-heading23993_1303f7-ef[data-kb-block=\"kb-adv-heading23993_1303f7-ef\"]{font-size:21px;font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_1303f7-ef mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_1303f7-ef[data-kb-block=\"kb-adv-heading23993_1303f7-ef\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_1303f7-ef img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_1303f7-ef[data-kb-block=\"kb-adv-heading23993_1303f7-ef\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading23993_1303f7-ef wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_1303f7-ef\"><strong><span style=\"color: #FFFFFF;\" class=\"ugb-highlight\">Com en l&#8217;exemple de la taula:<br><\/span><\/strong>Digueu-nos quina <strong>edat<\/strong> tenen els vostres fills, quin <strong>curs<\/strong> estan fent i feu una <strong>prova de nivell<\/strong> amb nosaltres. Com m\u00e9s aviat comencin, m\u00e9s f\u00e0cil ser\u00e0 el seu cam\u00ed.<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading23993_a2a19a-78, .wp-block-kadence-advancedheading.kt-adv-heading23993_a2a19a-78[data-kb-block=\"kb-adv-heading23993_a2a19a-78\"]{font-size:23px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading23993_a2a19a-78 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_a2a19a-78[data-kb-block=\"kb-adv-heading23993_a2a19a-78\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_a2a19a-78 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_a2a19a-78[data-kb-block=\"kb-adv-heading23993_a2a19a-78\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading23993_a2a19a-78, .wp-block-kadence-advancedheading.kt-adv-heading23993_a2a19a-78[data-kb-block=\"kb-adv-heading23993_a2a19a-78\"]{font-size:17px;}}<\/style>\n<h5 class=\"kt-adv-heading23993_a2a19a-78 blanc wp-block-kadence-advancedheading has-central-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading23993_a2a19a-78\"><strong><span style=\"text-decoration: underline;\" class=\"ek-underline\"><a href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/#ancora2\" class=\"ek-link\">Sol\u00b7licita el teu pla sense comprom\u00eds!<\/a><\/span><\/strong><\/h5>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id23993_6edeb0-d4{margin-bottom:0px;margin-top:0px;margin-bottom:0px;}.kb-row-layout-id23993_6edeb0-d4 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id23993_6edeb0-d4 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id23993_6edeb0-d4 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:10px;padding-bottom:10px;min-height:120px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id23993_6edeb0-d4 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id23993_6edeb0-d4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id23993_6edeb0-d4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id23993_6edeb0-d4 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column23993_2f472e-1e > .kt-inside-inner-col,.kadence-column23993_2f472e-1e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column23993_2f472e-1e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column23993_2f472e-1e > .kt-inside-inner-col{flex-direction:column;}.kadence-column23993_2f472e-1e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column23993_2f472e-1e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column23993_2f472e-1e{position:relative;}@media all and (max-width: 1024px){.kadence-column23993_2f472e-1e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column23993_2f472e-1e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column23993_2f472e-1e inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading23993_906c15-d3, .wp-block-kadence-advancedheading.kt-adv-heading23993_906c15-d3[data-kb-block=\"kb-adv-heading23993_906c15-d3\"]{margin-top:0px;margin-bottom:0px;text-align:center;font-size:42px;font-weight:600;font-style:normal;font-family:'Open Sans';}.wp-block-kadence-advancedheading.kt-adv-heading23993_906c15-d3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading23993_906c15-d3[data-kb-block=\"kb-adv-heading23993_906c15-d3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading23993_906c15-d3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading23993_906c15-d3[data-kb-block=\"kb-adv-heading23993_906c15-d3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading23993_906c15-d3, .wp-block-kadence-advancedheading.kt-adv-heading23993_906c15-d3[data-kb-block=\"kb-adv-heading23993_906c15-d3\"]{font-size:36px;}}<\/style>\n<h2 class=\"kt-adv-heading23993_906c15-d3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading23993_906c15-d3\">Comencem?<\/h2>\n\n\n\n<p class=\"eplus-txeeJ2\"><\/p>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>CURSOS D&#8217;ANGL\u00c8S ONLINE PER A JOVES Per videoconfer\u00e8ncia \u2013 via ZOOM Sol\u00b7licita m\u00e9s informaci\u00f3 Sol\u00b7licita m\u00e9s informaci\u00f3 El seu angl\u00e8s creix amb ells Tamb\u00e9 online! Dels 10 als 17 anys \u00e9s una fase de creixement acad\u00e8mic. Els joves treballen la gram\u00e0tica i amplien el seu vocabulari amb cursos adequats a les seves prefer\u00e8ncies i necessitats &#8230; <a title=\"Curs angl\u00e8s online joves\" class=\"read-more\" href=\"https:\/\/zoom.cambridgeschool.com\/ca\/curs-angles-online-joves\/\" aria-label=\"M\u00e9s informaci\u00f3 sobre Curs angl\u00e8s online joves\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":14,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","slim_seo":{"title":"Cursos angl\u00e8s online joves - Cambrdige School","description":"Cursos d\u2019angl\u00e8s per videoconfer\u00e8ncia per a joves de 12 a 17 anys: cursos anuals, preparaci\u00f3 d\u2019ex\u00e0mens oficials Cambridge, intensius estiu, classes particulars\u2026"},"_joinchat":[],"footnotes":""},"class_list":["post-23993","page","type-page","status-publish"],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"admin","author_link":"https:\/\/zoom.cambridgeschool.com\/ca\/author\/admin\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/pages\/23993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/comments?post=23993"}],"version-history":[{"count":29,"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/pages\/23993\/revisions"}],"predecessor-version":[{"id":29301,"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/pages\/23993\/revisions\/29301"}],"wp:attachment":[{"href":"https:\/\/zoom.cambridgeschool.com\/ca\/wp-json\/wp\/v2\/media?parent=23993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}